{"text_format":"1","workbook":"xlsx","n_sheets":10,"sheets":["INTRO","COUNTRY_INFO","DEC","ALB_MBD","PZQ","IVM","IVM+","SUMMARY","SHIPMENT","DATA_POLICY"],"not_rendered":{"charts":0,"images":3,"macros":1,"external_links":0,"defined_names":4,"comments":9,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"INTRO","index":0,"n_rows":50,"n_cols":5,"rows_kept":50,"cut":false,"hidden":false,"merged":[[7,2,7,4],[11,1,11,4],[4,1,4,4],[10,2,10,4],[20,2,20,4],[17,1,17,4],[13,1,13,4],[18,2,18,4],[8,2,8,4],[9,2,9,4],[19,1,19,4],[12,1,12,4],[16,1,16,4],[14,1,14,4],[15,1,15,4],[0,1,0,4],[2,1,2,4],[1,1,1,4],[5,1,5,4],[3,1,3,4],[21,1,21,4],[46,1,46,4],[38,1,38,2],[40,1,40,2],[42,1,42,2],[44,1,44,2],[36,1,36,2],[22,2,23,4],[25,2,26,4],[27,1,27,4],[32,1,32,2],[29,1,29,4],[30,1,30,4],[28,2,28,4],[24,1,24,4],[34,1,34,2]]}
[]
[null,"Joint request for selected PC medicines v.3.1"]
[]
[null,"As part of global efforts to accelerate expansion of preventive chemotherapy (PC) for control and elimination of lymphatic filariasis, schistosomiasis and soil-transmitted helminthiases, the World Health Organization (WHO) facilitates the supply of albendazole 400 mg tablets (GSK) to national lymphatic filariasis elimination programmes and national soil-transmitted helminth control programmes; diethylcarbamazine citrate 100 mg tablets (Eisai) to national lymphatic filariasis elimination programmes; mebendazole 500 mg tablets (J&J) for national soil-transmitted helminth control programmes; and praziquantel 600 mg tablets (Merck KGaA)  for school-age children to national schistosomiasis control programmes. WHO also collaborates to supply ivermectin 3 mg tablets (Merck) for onchocerciasis and lymphatic filariasis donation programmes.  \nThis Excel-based tool is designed to assist countries in quantifying the number of tablets of relevant PC medicines required to reach the planned target population and districts for the year of request. Output of the tool is a joint request for PC medicines, which can be printed, signed and submitted to WHO to request these medicines."]
[]
[null,"Structure of the application (worksheets):"]
[]
[null,"INTRO","This worksheet includes guides on how to complete the joint request for selected PC medicines and information about the status of PC for endemic diseases in the country."]
[null,"COUNTRY_INFO","This worksheet includes information about administrative structure of the country, population by age group, status of endemicity for each disease, population requiring PC and planned interventions."]
[null,"DEC, ALB_MBD, PZQ and IVM","These worksheets include information about endemic districts targeted for treatment with specified PC medicines, treatment plan, and number of tablets required and requested. "]
[null,"SUMMARY","This worksheet includes summary of number of tablets requested, information about stock, and date for submission of requested medicines. Before generating the report (run macros) please select the medicine for which the report is needed. Follow the same rule to see the number of people to be treated for the specific disease. \nThis worksheet should be printed and submitted as a joint request for selected PC medicines (see the instruction for submission in the SUMMARY worksheet)."]
[]
[null,"Instruction for data entry"]
[]
[null,"Most of the cells in the above-mentioned worksheets include formula that are calculated automatically according to the treatment policy recommended by WHO for each disease.\nSee the link http://www.who.int/neglected_diseases/preventive_chemotherapy/pct_manual/en/index.html"]
[]
[null,"Please enter your data into the cells according to their colour code:"]
[]
[null,null,"White - cell is not protected. Please enter the value of the requested indicator."]
[]
[null,null,"Yellow - cell is protected and includes name of indicator. No data entry required."]
[]
[null,null,"Orange - cell is not protected and includes a drop-down menu. Please select the value from the drop-down list."]
[]
[]
[null,null,"Green - cell is not protected and includes formula. Please change the value only if your data are different from those that are calculated automatically."]
[]
[]
[null,null,"Blue - cell is protected and includes formula. No data entry required."]
[]
[null,"Country data"]
[]
[null,"COUNTRY",null,null,"Zimbabwe"]
[]
[null,"Year for request of the medicine",null,null,2020]
[]
[null,"Is country endemic for lymphatic filariasis (LF)?",null,null,"Endemic"]
[]
[null,"Is country endemic for onchocerciasis (ONCHO)?",null,null,"Non-endemic"]
[]
[null,"Is country endemic for soil-transmitted helminthiases (STH)?",null,null,"Endemic"]
[]
[null,"Is country endemic for schistosomiasis (SCH)?",null,null,"Endemic"]
[]
[null,"How many administrative units in the country?",null,null,63]
[]
[null,"If demographical data at the second administrative level are not available by age group, please enter the proportion (%) of population by age group in the country. If data are available, please leave these cells blank."]
[null,"1-4 years age","Preschool-age children (PreSAC)",null,0.11]
[null,"5-14 years age","School-age children (SAC)",null,0.31]
[null,"15 years +","Adults",null,0.56000000000000005]

{"sheet":"COUNTRY_INFO","index":1,"n_rows":71,"n_cols":26,"rows_kept":71,"cut":false,"hidden":false,"merged":[[3,0,3,2],[3,7,3,10],[3,15,3,18],[5,0,5,2],[3,20,3,23],[5,20,5,23],[7,0,7,18],[5,3,5,6],[5,7,5,10],[5,11,5,14],[5,15,5,18]]}
["COUNTRY INFORMATION"]
["Administrative structure, population by age group, status of endemicity and planned interventions"]
[]
["TOTAL",null,null,{"$f":"SUM(D$9:D$1000)","v":14270045},{"$f":"SUM(E$9:E$1000)","v":1569703},{"$f":"SUM(F$9:F$1000)","v":4423713},{"$f":"SUM(G$9:G$1000)","v":7991227},null,null,null,null,{"$f":"SUM(L$9:L$1000)","v":8029929},{"$f":"SUM(M$9:M$1000)","v":0},{"$f":"SUM(N$9:N$1000)","v":423232},{"$f":"SUM(O$9:O$1000)","v":3413153.68}]
[]
["Country administrative structure",null,null,"Population",null,null,null,"Endemicity",null,null,null,"Population requiring PC",null,null,null,"Number of treatment rounds planned for the year",null,null,null,"Criteria to apply for \nIVM+DEC+ALB therapy","Epidemiological surveys planned for the year"]
["Country","Province/State","District","Total","PreSAC","SAC","Adults","LF","Oncho","STH","SCH","LF","Oncho","STH","SCH","LF","Oncho","STH","SCH","LF","LF","Oncho","STH","SCH","IU_ID","IU_NAME"]
[]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Manicaland","Buhera",268633,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D9*INTRO!$E$48,0))","v":29550},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D9*INTRO!$E$49,0))","v":83276},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D9*INTRO!$E$50,0))","v":150434},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H9>0,IF($H9=4,\"Unknown\",IF($H9=99,\"Stopped\",$D9)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I9>0, IF($I9=4,\"Unknown\",IF($I9=99,\"Stopped\",$D9)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J9>1,$J9<5), IF($J9=4, \"Unknown\", E9+F9), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K9>0,$K9<5), IF($K9=4,\"Unknown\", IF($K9=1, $F9*0.33, IF($K9=2, $F9*0.5+$G9*0.2, SUM(F9:G9)))), 0),\"Not required\")","v":71724.800000000003},0,null,0,1,null,null,null,null,null,52904,"Buhera"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Manicaland","Chimanimani",147429,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D10*INTRO!$E$48,0))","v":16217},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D10*INTRO!$E$49,0))","v":45703},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D10*INTRO!$E$50,0))","v":82560},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H10>0,IF($H10=4,\"Unknown\",IF($H10=99,\"Stopped\",$D10)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I10>0, IF($I10=4,\"Unknown\",IF($I10=99,\"Stopped\",$D10)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J10>1,$J10<5), IF($J10=4, \"Unknown\", E10+F10), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K10>0,$K10<5), IF($K10=4,\"Unknown\", IF($K10=1, $F10*0.33, IF($K10=2, $F10*0.5+$G10*0.2, SUM(F10:G10)))), 0),\"Not required\")","v":39363.5},0,null,0,1,null,null,null,null,null,52905,"Chimanimani"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Manicaland","Chipinge",354132,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D11*INTRO!$E$48,0))","v":38955},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D11*INTRO!$E$49,0))","v":109781},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D11*INTRO!$E$50,0))","v":198314},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H11>0,IF($H11=4,\"Unknown\",IF($H11=99,\"Stopped\",$D11)),0),\"Not required\")","v":354132},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I11>0, IF($I11=4,\"Unknown\",IF($I11=99,\"Stopped\",$D11)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J11>1,$J11<5), IF($J11=4, \"Unknown\", E11+F11), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K11>0,$K11<5), IF($K11=4,\"Unknown\", IF($K11=1, $F11*0.33, IF($K11=2, $F11*0.5+$G11*0.2, SUM(F11:G11)))), 0),\"Not required\")","v":94553.3},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52906,"Chipinge"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Manicaland","Makoni",330667,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D12*INTRO!$E$48,0))","v":36373},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D12*INTRO!$E$49,0))","v":102507},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D12*INTRO!$E$50,0))","v":185174},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H12>0,IF($H12=4,\"Unknown\",IF($H12=99,\"Stopped\",$D12)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I12>0, IF($I12=4,\"Unknown\",IF($I12=99,\"Stopped\",$D12)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J12>1,$J12<5), IF($J12=4, \"Unknown\", E12+F12), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K12>0,$K12<5), IF($K12=4,\"Unknown\", IF($K12=1, $F12*0.33, IF($K12=2, $F12*0.5+$G12*0.2, SUM(F12:G12)))), 0),\"Not required\")","v":88288.3},0,null,0,1,null,null,null,null,null,52907,"Makoni"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Manicaland","Mutare",286384,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D13*INTRO!$E$48,0))","v":31502},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D13*INTRO!$E$49,0))","v":88779},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D13*INTRO!$E$50,0))","v":160375},0,null,0,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H13>0,IF($H13=4,\"Unknown\",IF($H13=99,\"Stopped\",$D13)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I13>0, IF($I13=4,\"Unknown\",IF($I13=99,\"Stopped\",$D13)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J13>1,$J13<5), IF($J13=4, \"Unknown\", E13+F13), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K13>0,$K13<5), IF($K13=4,\"Unknown\", IF($K13=1, $F13*0.33, IF($K13=2, $F13*0.5+$G13*0.2, SUM(F13:G13)))), 0),\"Not required\")","v":76464.5},0,null,0,1,null,null,null,null,null,52908,"Mutare"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Manicaland","Mutasa",184364,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D14*INTRO!$E$48,0))","v":20280},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D14*INTRO!$E$49,0))","v":57153},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D14*INTRO!$E$50,0))","v":103244},0,null,1,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H14>0,IF($H14=4,\"Unknown\",IF($H14=99,\"Stopped\",$D14)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I14>0, IF($I14=4,\"Unknown\",IF($I14=99,\"Stopped\",$D14)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J14>1,$J14<5), IF($J14=4, \"Unknown\", E14+F14), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K14>0,$K14<5), IF($K14=4,\"Unknown\", IF($K14=1, $F14*0.33, IF($K14=2, $F14*0.5+$G14*0.2, SUM(F14:G14)))), 0),\"Not required\")","v":18860.490000000002},0,null,0,0,null,null,null,null,null,52909,"Mutasa"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Manicaland","Nyanga",343301,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D15*INTRO!$E$48,0))","v":37763},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D15*INTRO!$E$49,0))","v":106423},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D15*INTRO!$E$50,0))","v":192249},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H15>0,IF($H15=4,\"Unknown\",IF($H15=99,\"Stopped\",$D15)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I15>0, IF($I15=4,\"Unknown\",IF($I15=99,\"Stopped\",$D15)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J15>1,$J15<5), IF($J15=4, \"Unknown\", E15+F15), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K15>0,$K15<5), IF($K15=4,\"Unknown\", IF($K15=1, $F15*0.33, IF($K15=2, $F15*0.5+$G15*0.2, SUM(F15:G15)))), 0),\"Not required\")","v":91661.3},0,null,0,1,null,null,null,null,null,52910,"Nyanga"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Harare","Chitungwiza",389866,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D16*INTRO!$E$48,0))","v":42885},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D16*INTRO!$E$49,0))","v":120858},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D16*INTRO!$E$50,0))","v":218325},0,null,1,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H16>0,IF($H16=4,\"Unknown\",IF($H16=99,\"Stopped\",$D16)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I16>0, IF($I16=4,\"Unknown\",IF($I16=99,\"Stopped\",$D16)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J16>1,$J16<5), IF($J16=4, \"Unknown\", E16+F16), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K16>0,$K16<5), IF($K16=4,\"Unknown\", IF($K16=1, $F16*0.33, IF($K16=2, $F16*0.5+$G16*0.2, SUM(F16:G16)))), 0),\"Not required\")","v":39883.14},0,null,0,0,null,null,null,null,null,52965,"Chitungwiza"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Harare","Harare",1746801,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D17*INTRO!$E$48,0))","v":192148},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D17*INTRO!$E$49,0))","v":541508},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D17*INTRO!$E$50,0))","v":978209},0,null,1,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H17>0,IF($H17=4,\"Unknown\",IF($H17=99,\"Stopped\",$D17)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I17>0, IF($I17=4,\"Unknown\",IF($I17=99,\"Stopped\",$D17)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J17>1,$J17<5), IF($J17=4, \"Unknown\", E17+F17), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K17>0,$K17<5), IF($K17=4,\"Unknown\", IF($K17=1, $F17*0.33, IF($K17=2, $F17*0.5+$G17*0.2, SUM(F17:G17)))), 0),\"Not required\")","v":178697.64},0,null,0,0,null,null,null,null,null,52903,"Harare"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashnaland Central","Bindura",184525,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D18*INTRO!$E$48,0))","v":20298},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D18*INTRO!$E$49,0))","v":57203},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D18*INTRO!$E$50,0))","v":103334},0,null,5,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H18>0,IF($H18=4,\"Unknown\",IF($H18=99,\"Stopped\",$D18)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I18>0, IF($I18=4,\"Unknown\",IF($I18=99,\"Stopped\",$D18)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J18>1,$J18<5), IF($J18=4, \"Unknown\", E18+F18), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K18>0,$K18<5), IF($K18=4,\"Unknown\", IF($K18=1, $F18*0.33, IF($K18=2, $F18*0.5+$G18*0.2, SUM(F18:G18)))), 0),\"Not required\")","v":49268.3},0,null,0,1,null,null,null,null,null,52911,"Bindura"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashnaland Central","Centenary",134155,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D19*INTRO!$E$48,0))","v":14757},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D19*INTRO!$E$49,0))","v":41588},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D19*INTRO!$E$50,0))","v":75127},1,null,0,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H19>0,IF($H19=4,\"Unknown\",IF($H19=99,\"Stopped\",$D19)),0),\"Not required\")","v":134155},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I19>0, IF($I19=4,\"Unknown\",IF($I19=99,\"Stopped\",$D19)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J19>1,$J19<5), IF($J19=4, \"Unknown\", E19+F19), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K19>0,$K19<5), IF($K19=4,\"Unknown\", IF($K19=1, $F19*0.33, IF($K19=2, $F19*0.5+$G19*0.2, SUM(F19:G19)))), 0),\"Not required\")","v":35819.4},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52912,"Centenary"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashnaland Central","Guruve",135520,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D20*INTRO!$E$48,0))","v":14907},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D20*INTRO!$E$49,0))","v":42011},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D20*INTRO!$E$50,0))","v":75891},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H20>0,IF($H20=4,\"Unknown\",IF($H20=99,\"Stopped\",$D20)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I20>0, IF($I20=4,\"Unknown\",IF($I20=99,\"Stopped\",$D20)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J20>1,$J20<5), IF($J20=4, \"Unknown\", E20+F20), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K20>0,$K20<5), IF($K20=4,\"Unknown\", IF($K20=1, $F20*0.33, IF($K20=2, $F20*0.5+$G20*0.2, SUM(F20:G20)))), 0),\"Not required\")","v":36183.699999999997},0,null,0,1,null,null,null,null,null,52913,"Guruve"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashnaland Central","Mazowe",266581,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D21*INTRO!$E$48,0))","v":29324},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D21*INTRO!$E$49,0))","v":82640},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D21*INTRO!$E$50,0))","v":149285},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H21>0,IF($H21=4,\"Unknown\",IF($H21=99,\"Stopped\",$D21)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I21>0, IF($I21=4,\"Unknown\",IF($I21=99,\"Stopped\",$D21)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J21>1,$J21<5), IF($J21=4, \"Unknown\", E21+F21), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K21>0,$K21<5), IF($K21=4,\"Unknown\", IF($K21=1, $F21*0.33, IF($K21=2, $F21*0.5+$G21*0.2, SUM(F21:G21)))), 0),\"Not required\")","v":71177},0,null,0,1,null,null,null,null,null,52914,"Mazowe"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashnaland Central","Mt Darwin",232412,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D22*INTRO!$E$48,0))","v":25565},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D22*INTRO!$E$49,0))","v":72048},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D22*INTRO!$E$50,0))","v":130151},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H22>0,IF($H22=4,\"Unknown\",IF($H22=99,\"Stopped\",$D22)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I22>0, IF($I22=4,\"Unknown\",IF($I22=99,\"Stopped\",$D22)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J22>1,$J22<5), IF($J22=4, \"Unknown\", E22+F22), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K22>0,$K22<5), IF($K22=4,\"Unknown\", IF($K22=1, $F22*0.33, IF($K22=2, $F22*0.5+$G22*0.2, SUM(F22:G22)))), 0),\"Not required\")","v":62054.2},0,null,0,1,null,null,null,null,null,52916,"Mt Darwin"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashnaland Central","Rushinga",80893,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D23*INTRO!$E$48,0))","v":8898},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D23*INTRO!$E$49,0))","v":25077},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D23*INTRO!$E$50,0))","v":45300},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H23>0,IF($H23=4,\"Unknown\",IF($H23=99,\"Stopped\",$D23)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I23>0, IF($I23=4,\"Unknown\",IF($I23=99,\"Stopped\",$D23)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J23>1,$J23<5), IF($J23=4, \"Unknown\", E23+F23), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K23>0,$K23<5), IF($K23=4,\"Unknown\", IF($K23=1, $F23*0.33, IF($K23=2, $F23*0.5+$G23*0.2, SUM(F23:G23)))), 0),\"Not required\")","v":21598.5},0,null,0,1,null,null,null,null,null,52917,"Rushinga"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashnaland Central","Shamva",135094,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D24*INTRO!$E$48,0))","v":14860},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D24*INTRO!$E$49,0))","v":41879},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D24*INTRO!$E$50,0))","v":75653},1,null,1,3,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H24>0,IF($H24=4,\"Unknown\",IF($H24=99,\"Stopped\",$D24)),0),\"Not required\")","v":135094},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I24>0, IF($I24=4,\"Unknown\",IF($I24=99,\"Stopped\",$D24)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J24>1,$J24<5), IF($J24=4, \"Unknown\", E24+F24), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K24>0,$K24<5), IF($K24=4,\"Unknown\", IF($K24=1, $F24*0.33, IF($K24=2, $F24*0.5+$G24*0.2, SUM(F24:G24)))), 0),\"Not required\")","v":117532},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52918,"Shamva"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashnaland Central","Mbire",90004,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D25*INTRO!$E$48,0))","v":9900},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D25*INTRO!$E$49,0))","v":27901},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D25*INTRO!$E$50,0))","v":50402},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H25>0,IF($H25=4,\"Unknown\",IF($H25=99,\"Stopped\",$D25)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I25>0, IF($I25=4,\"Unknown\",IF($I25=99,\"Stopped\",$D25)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J25>1,$J25<5), IF($J25=4, \"Unknown\", E25+F25), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K25>0,$K25<5), IF($K25=4,\"Unknown\", IF($K25=1, $F25*0.33, IF($K25=2, $F25*0.5+$G25*0.2, SUM(F25:G25)))), 0),\"Not required\")","v":24030.9},0,null,0,1,null,null,null,null,null,52915,"Mbire"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland East","Chikomba",132183,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D26*INTRO!$E$48,0))","v":14540},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D26*INTRO!$E$49,0))","v":40977},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D26*INTRO!$E$50,0))","v":74022},1,null,1,3,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H26>0,IF($H26=4,\"Unknown\",IF($H26=99,\"Stopped\",$D26)),0),\"Not required\")","v":132183},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I26>0, IF($I26=4,\"Unknown\",IF($I26=99,\"Stopped\",$D26)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J26>1,$J26<5), IF($J26=4, \"Unknown\", E26+F26), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K26>0,$K26<5), IF($K26=4,\"Unknown\", IF($K26=1, $F26*0.33, IF($K26=2, $F26*0.5+$G26*0.2, SUM(F26:G26)))), 0),\"Not required\")","v":114999},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52919,"Chikomba"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland East","Goromonzi",245809,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D27*INTRO!$E$48,0))","v":27039},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D27*INTRO!$E$49,0))","v":76201},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D27*INTRO!$E$50,0))","v":137653},1,null,0,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H27>0,IF($H27=4,\"Unknown\",IF($H27=99,\"Stopped\",$D27)),0),\"Not required\")","v":245809},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I27>0, IF($I27=4,\"Unknown\",IF($I27=99,\"Stopped\",$D27)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J27>1,$J27<5), IF($J27=4, \"Unknown\", E27+F27), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K27>0,$K27<5), IF($K27=4,\"Unknown\", IF($K27=1, $F27*0.33, IF($K27=2, $F27*0.5+$G27*0.2, SUM(F27:G27)))), 0),\"Not required\")","v":25146.33},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52920,"Goromonzi"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland East","UMP",123032,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D28*INTRO!$E$48,0))","v":13534},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D28*INTRO!$E$49,0))","v":38140},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D28*INTRO!$E$50,0))","v":68898},1,null,2,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H28>0,IF($H28=4,\"Unknown\",IF($H28=99,\"Stopped\",$D28)),0),\"Not required\")","v":123032},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I28>0, IF($I28=4,\"Unknown\",IF($I28=99,\"Stopped\",$D28)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J28>1,$J28<5), IF($J28=4, \"Unknown\", E28+F28), 0),\"Not required\")","v":51674},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K28>0,$K28<5), IF($K28=4,\"Unknown\", IF($K28=1, $F28*0.33, IF($K28=2, $F28*0.5+$G28*0.2, SUM(F28:G28)))), 0),\"Not required\")","v":32849.599999999999},1,null,1,1,"Starting late: <4 MDA rounds",null,null,null,null,52927,"UMP"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland East","Hwedza",77537,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D29*INTRO!$E$48,0))","v":8529},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D29*INTRO!$E$49,0))","v":24036},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D29*INTRO!$E$50,0))","v":43421},1,null,1,3,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H29>0,IF($H29=4,\"Unknown\",IF($H29=99,\"Stopped\",$D29)),0),\"Not required\")","v":77537},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I29>0, IF($I29=4,\"Unknown\",IF($I29=99,\"Stopped\",$D29)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J29>1,$J29<5), IF($J29=4, \"Unknown\", E29+F29), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K29>0,$K29<5), IF($K29=4,\"Unknown\", IF($K29=1, $F29*0.33, IF($K29=2, $F29*0.5+$G29*0.2, SUM(F29:G29)))), 0),\"Not required\")","v":67457},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52921,"Hwedza"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland East","Marondera",195548,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D30*INTRO!$E$48,0))","v":21510},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D30*INTRO!$E$49,0))","v":60620},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D30*INTRO!$E$50,0))","v":109507},1,null,0,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H30>0,IF($H30=4,\"Unknown\",IF($H30=99,\"Stopped\",$D30)),0),\"Not required\")","v":195548},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I30>0, IF($I30=4,\"Unknown\",IF($I30=99,\"Stopped\",$D30)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J30>1,$J30<5), IF($J30=4, \"Unknown\", E30+F30), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K30>0,$K30<5), IF($K30=4,\"Unknown\", IF($K30=1, $F30*0.33, IF($K30=2, $F30*0.5+$G30*0.2, SUM(F30:G30)))), 0),\"Not required\")","v":20004.600000000002},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52922,"Marondera"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland East","Mudzi",145585,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D31*INTRO!$E$48,0))","v":16014},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D31*INTRO!$E$49,0))","v":45131},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D31*INTRO!$E$50,0))","v":81528},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H31>0,IF($H31=4,\"Unknown\",IF($H31=99,\"Stopped\",$D31)),0),\"Not required\")","v":145585},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I31>0, IF($I31=4,\"Unknown\",IF($I31=99,\"Stopped\",$D31)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J31>1,$J31<5), IF($J31=4, \"Unknown\", E31+F31), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K31>0,$K31<5), IF($K31=4,\"Unknown\", IF($K31=1, $F31*0.33, IF($K31=2, $F31*0.5+$G31*0.2, SUM(F31:G31)))), 0),\"Not required\")","v":38871.1},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52923,"Mudzi"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland East","Murewa",218080,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D32*INTRO!$E$48,0))","v":23989},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D32*INTRO!$E$49,0))","v":67605},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D32*INTRO!$E$50,0))","v":122125},1,null,2,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H32>0,IF($H32=4,\"Unknown\",IF($H32=99,\"Stopped\",$D32)),0),\"Not required\")","v":218080},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I32>0, IF($I32=4,\"Unknown\",IF($I32=99,\"Stopped\",$D32)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J32>1,$J32<5), IF($J32=4, \"Unknown\", E32+F32), 0),\"Not required\")","v":91594},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K32>0,$K32<5), IF($K32=4,\"Unknown\", IF($K32=1, $F32*0.33, IF($K32=2, $F32*0.5+$G32*0.2, SUM(F32:G32)))), 0),\"Not required\")","v":58227.5},1,null,1,1,"Starting late: <4 MDA rounds",null,null,null,null,52924,"Murewa"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland East","Mutoko",159651,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D33*INTRO!$E$48,0))","v":17562},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D33*INTRO!$E$49,0))","v":49492},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D33*INTRO!$E$50,0))","v":89405},1,null,2,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H33>0,IF($H33=4,\"Unknown\",IF($H33=99,\"Stopped\",$D33)),0),\"Not required\")","v":159651},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I33>0, IF($I33=4,\"Unknown\",IF($I33=99,\"Stopped\",$D33)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J33>1,$J33<5), IF($J33=4, \"Unknown\", E33+F33), 0),\"Not required\")","v":67054},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K33>0,$K33<5), IF($K33=4,\"Unknown\", IF($K33=1, $F33*0.33, IF($K33=2, $F33*0.5+$G33*0.2, SUM(F33:G33)))), 0),\"Not required\")","v":42627},1,null,1,1,"Starting late: <4 MDA rounds",null,null,null,null,52925,"Mutoko"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland East","Seke",354965,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D34*INTRO!$E$48,0))","v":39046},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D34*INTRO!$E$49,0))","v":110039},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D34*INTRO!$E$50,0))","v":198780},1,null,2,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H34>0,IF($H34=4,\"Unknown\",IF($H34=99,\"Stopped\",$D34)),0),\"Not required\")","v":354965},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I34>0, IF($I34=4,\"Unknown\",IF($I34=99,\"Stopped\",$D34)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J34>1,$J34<5), IF($J34=4, \"Unknown\", E34+F34), 0),\"Not required\")","v":149085},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K34>0,$K34<5), IF($K34=4,\"Unknown\", IF($K34=1, $F34*0.33, IF($K34=2, $F34*0.5+$G34*0.2, SUM(F34:G34)))), 0),\"Not required\")","v":94775.5},1,null,1,1,"Starting late: <4 MDA rounds",null,null,null,null,52926,"Seke"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland West","Chegutu",296994,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D35*INTRO!$E$48,0))","v":32669},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D35*INTRO!$E$49,0))","v":92068},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D35*INTRO!$E$50,0))","v":166317},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H35>0,IF($H35=4,\"Unknown\",IF($H35=99,\"Stopped\",$D35)),0),\"Not required\")","v":296994},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I35>0, IF($I35=4,\"Unknown\",IF($I35=99,\"Stopped\",$D35)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J35>1,$J35<5), IF($J35=4, \"Unknown\", E35+F35), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K35>0,$K35<5), IF($K35=4,\"Unknown\", IF($K35=1, $F35*0.33, IF($K35=2, $F35*0.5+$G35*0.2, SUM(F35:G35)))), 0),\"Not required\")","v":79297.399999999994},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52928,"Chegutu"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland West","Hurungwe",390917,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D36*INTRO!$E$48,0))","v":43001},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D36*INTRO!$E$49,0))","v":121184},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D36*INTRO!$E$50,0))","v":218914},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H36>0,IF($H36=4,\"Unknown\",IF($H36=99,\"Stopped\",$D36)),0),\"Not required\")","v":390917},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I36>0, IF($I36=4,\"Unknown\",IF($I36=99,\"Stopped\",$D36)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J36>1,$J36<5), IF($J36=4, \"Unknown\", E36+F36), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K36>0,$K36<5), IF($K36=4,\"Unknown\", IF($K36=1, $F36*0.33, IF($K36=2, $F36*0.5+$G36*0.2, SUM(F36:G36)))), 0),\"Not required\")","v":104374.8},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52929,"Hurungwe"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland West","Sanyati",224373,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D37*INTRO!$E$48,0))","v":24681},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D37*INTRO!$E$49,0))","v":69556},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D37*INTRO!$E$50,0))","v":125649},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H37>0,IF($H37=4,\"Unknown\",IF($H37=99,\"Stopped\",$D37)),0),\"Not required\")","v":224373},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I37>0, IF($I37=4,\"Unknown\",IF($I37=99,\"Stopped\",$D37)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J37>1,$J37<5), IF($J37=4, \"Unknown\", E37+F37), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K37>0,$K37<5), IF($K37=4,\"Unknown\", IF($K37=1, $F37*0.33, IF($K37=2, $F37*0.5+$G37*0.2, SUM(F37:G37)))), 0),\"Not required\")","v":59907.8},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52930,"Sanyati"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland West","Kariba",74096,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D38*INTRO!$E$48,0))","v":8151},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D38*INTRO!$E$49,0))","v":22970},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D38*INTRO!$E$50,0))","v":41494},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H38>0,IF($H38=4,\"Unknown\",IF($H38=99,\"Stopped\",$D38)),0),\"Not required\")","v":74096},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I38>0, IF($I38=4,\"Unknown\",IF($I38=99,\"Stopped\",$D38)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J38>1,$J38<5), IF($J38=4, \"Unknown\", E38+F38), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K38>0,$K38<5), IF($K38=4,\"Unknown\", IF($K38=1, $F38*0.33, IF($K38=2, $F38*0.5+$G38*0.2, SUM(F38:G38)))), 0),\"Not required\")","v":19783.800000000003},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52931,"Kariba"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland West","Makonde",252891,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D39*INTRO!$E$48,0))","v":27818},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D39*INTRO!$E$49,0))","v":78396},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D39*INTRO!$E$50,0))","v":141619},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H39>0,IF($H39=4,\"Unknown\",IF($H39=99,\"Stopped\",$D39)),0),\"Not required\")","v":252891},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I39>0, IF($I39=4,\"Unknown\",IF($I39=99,\"Stopped\",$D39)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J39>1,$J39<5), IF($J39=4, \"Unknown\", E39+F39), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K39>0,$K39<5), IF($K39=4,\"Unknown\", IF($K39=1, $F39*0.33, IF($K39=2, $F39*0.5+$G39*0.2, SUM(F39:G39)))), 0),\"Not required\")","v":67521.8},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52932,"Makonde"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland West","Mhondoro-Ngezi",113998,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D40*INTRO!$E$48,0))","v":12540},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D40*INTRO!$E$49,0))","v":35339},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D40*INTRO!$E$50,0))","v":63839},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H40>0,IF($H40=4,\"Unknown\",IF($H40=99,\"Stopped\",$D40)),0),\"Not required\")","v":113998},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I40>0, IF($I40=4,\"Unknown\",IF($I40=99,\"Stopped\",$D40)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J40>1,$J40<5), IF($J40=4, \"Unknown\", E40+F40), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K40>0,$K40<5), IF($K40=4,\"Unknown\", IF($K40=1, $F40*0.33, IF($K40=2, $F40*0.5+$G40*0.2, SUM(F40:G40)))), 0),\"Not required\")","v":30437.300000000003},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52963,"Mhondoro-Ngezi"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Mashonaland West","Zvimba",287363,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D41*INTRO!$E$48,0))","v":31610},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D41*INTRO!$E$49,0))","v":89083},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D41*INTRO!$E$50,0))","v":160923},1,null,0,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H41>0,IF($H41=4,\"Unknown\",IF($H41=99,\"Stopped\",$D41)),0),\"Not required\")","v":287363},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I41>0, IF($I41=4,\"Unknown\",IF($I41=99,\"Stopped\",$D41)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J41>1,$J41<5), IF($J41=4, \"Unknown\", E41+F41), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K41>0,$K41<5), IF($K41=4,\"Unknown\", IF($K41=1, $F41*0.33, IF($K41=2, $F41*0.5+$G41*0.2, SUM(F41:G41)))), 0),\"Not required\")","v":76726.100000000006},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52933,"Zvimba"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland North","Binga",151965,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D42*INTRO!$E$48,0))","v":16716},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D42*INTRO!$E$49,0))","v":47109},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D42*INTRO!$E$50,0))","v":85100},1,null,2,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H42>0,IF($H42=4,\"Unknown\",IF($H42=99,\"Stopped\",$D42)),0),\"Not required\")","v":151965},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I42>0, IF($I42=4,\"Unknown\",IF($I42=99,\"Stopped\",$D42)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J42>1,$J42<5), IF($J42=4, \"Unknown\", E42+F42), 0),\"Not required\")","v":63825},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K42>0,$K42<5), IF($K42=4,\"Unknown\", IF($K42=1, $F42*0.33, IF($K42=2, $F42*0.5+$G42*0.2, SUM(F42:G42)))), 0),\"Not required\")","v":15545.970000000001},1,null,1,0,"Starting late: <4 MDA rounds",null,null,null,null,52948,"Binga"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland North","Bubi",67609,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D43*INTRO!$E$48,0))","v":7437},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D43*INTRO!$E$49,0))","v":20959},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D43*INTRO!$E$50,0))","v":37861},1,null,0,0,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H43>0,IF($H43=4,\"Unknown\",IF($H43=99,\"Stopped\",$D43)),0),\"Not required\")","v":67609},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I43>0, IF($I43=4,\"Unknown\",IF($I43=99,\"Stopped\",$D43)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J43>1,$J43<5), IF($J43=4, \"Unknown\", E43+F43), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K43>0,$K43<5), IF($K43=4,\"Unknown\", IF($K43=1, $F43*0.33, IF($K43=2, $F43*0.5+$G43*0.2, SUM(F43:G43)))), 0),\"Not required\")","v":0},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52949,"Bubi"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland North","Hwange",146336,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D44*INTRO!$E$48,0))","v":16097},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D44*INTRO!$E$49,0))","v":45364},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D44*INTRO!$E$50,0))","v":81948},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H44>0,IF($H44=4,\"Unknown\",IF($H44=99,\"Stopped\",$D44)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I44>0, IF($I44=4,\"Unknown\",IF($I44=99,\"Stopped\",$D44)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J44>1,$J44<5), IF($J44=4, \"Unknown\", E44+F44), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K44>0,$K44<5), IF($K44=4,\"Unknown\", IF($K44=1, $F44*0.33, IF($K44=2, $F44*0.5+$G44*0.2, SUM(F44:G44)))), 0),\"Not required\")","v":39071.600000000006},0,null,0,1,null,null,null,null,null,52950,"Hwange"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland North","Lupane",109431,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D45*INTRO!$E$48,0))","v":12037},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D45*INTRO!$E$49,0))","v":33924},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D45*INTRO!$E$50,0))","v":61281},1,null,1,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H45>0,IF($H45=4,\"Unknown\",IF($H45=99,\"Stopped\",$D45)),0),\"Not required\")","v":109431},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I45>0, IF($I45=4,\"Unknown\",IF($I45=99,\"Stopped\",$D45)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J45>1,$J45<5), IF($J45=4, \"Unknown\", E45+F45), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K45>0,$K45<5), IF($K45=4,\"Unknown\", IF($K45=1, $F45*0.33, IF($K45=2, $F45*0.5+$G45*0.2, SUM(F45:G45)))), 0),\"Not required\")","v":11194.92},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52951,"Lupane"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland North","Nkayi",119235,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D46*INTRO!$E$48,0))","v":13116},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D46*INTRO!$E$49,0))","v":36963},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D46*INTRO!$E$50,0))","v":66772},1,null,1,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H46>0,IF($H46=4,\"Unknown\",IF($H46=99,\"Stopped\",$D46)),0),\"Not required\")","v":119235},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I46>0, IF($I46=4,\"Unknown\",IF($I46=99,\"Stopped\",$D46)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J46>1,$J46<5), IF($J46=4, \"Unknown\", E46+F46), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K46>0,$K46<5), IF($K46=4,\"Unknown\", IF($K46=1, $F46*0.33, IF($K46=2, $F46*0.5+$G46*0.2, SUM(F46:G46)))), 0),\"Not required\")","v":12197.79},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52952,"Nkayi"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland North","Tsholotsho",125773,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D47*INTRO!$E$48,0))","v":13835},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D47*INTRO!$E$49,0))","v":38990},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D47*INTRO!$E$50,0))","v":70433},0,null,0,0,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H47>0,IF($H47=4,\"Unknown\",IF($H47=99,\"Stopped\",$D47)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I47>0, IF($I47=4,\"Unknown\",IF($I47=99,\"Stopped\",$D47)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J47>1,$J47<5), IF($J47=4, \"Unknown\", E47+F47), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K47>0,$K47<5), IF($K47=4,\"Unknown\", IF($K47=1, $F47*0.33, IF($K47=2, $F47*0.5+$G47*0.2, SUM(F47:G47)))), 0),\"Not required\")","v":0},0,null,0,0,null,null,null,null,null,52953,"Tsholotsho"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland North","Umguza",97988,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D48*INTRO!$E$48,0))","v":10779},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D48*INTRO!$E$49,0))","v":30376},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D48*INTRO!$E$50,0))","v":54873},1,null,0,0,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H48>0,IF($H48=4,\"Unknown\",IF($H48=99,\"Stopped\",$D48)),0),\"Not required\")","v":97988},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I48>0, IF($I48=4,\"Unknown\",IF($I48=99,\"Stopped\",$D48)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J48>1,$J48<5), IF($J48=4, \"Unknown\", E48+F48), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K48>0,$K48<5), IF($K48=4,\"Unknown\", IF($K48=1, $F48*0.33, IF($K48=2, $F48*0.5+$G48*0.2, SUM(F48:G48)))), 0),\"Not required\")","v":0},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52954,"Umguza"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland South","Beit Bridge",133531,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D49*INTRO!$E$48,0))","v":14688},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D49*INTRO!$E$49,0))","v":41395},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D49*INTRO!$E$50,0))","v":74777},0,null,0,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H49>0,IF($H49=4,\"Unknown\",IF($H49=99,\"Stopped\",$D49)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I49>0, IF($I49=4,\"Unknown\",IF($I49=99,\"Stopped\",$D49)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J49>1,$J49<5), IF($J49=4, \"Unknown\", E49+F49), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K49>0,$K49<5), IF($K49=4,\"Unknown\", IF($K49=1, $F49*0.33, IF($K49=2, $F49*0.5+$G49*0.2, SUM(F49:G49)))), 0),\"Not required\")","v":13660.35},0,null,0,0,null,null,null,null,null,52941,"Beit Bridge"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland South","Bulilima",98942,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D50*INTRO!$E$48,0))","v":10884},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D50*INTRO!$E$49,0))","v":30672},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D50*INTRO!$E$50,0))","v":55408},1,null,0,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H50>0,IF($H50=4,\"Unknown\",IF($H50=99,\"Stopped\",$D50)),0),\"Not required\")","v":98942},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I50>0, IF($I50=4,\"Unknown\",IF($I50=99,\"Stopped\",$D50)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J50>1,$J50<5), IF($J50=4, \"Unknown\", E50+F50), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K50>0,$K50<5), IF($K50=4,\"Unknown\", IF($K50=1, $F50*0.33, IF($K50=2, $F50*0.5+$G50*0.2, SUM(F50:G50)))), 0),\"Not required\")","v":10121.76},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52942,"Bulilima"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland South","Gwanda",148592,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D51*INTRO!$E$48,0))","v":16345},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D51*INTRO!$E$49,0))","v":46064},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D51*INTRO!$E$50,0))","v":83212},1,null,0,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H51>0,IF($H51=4,\"Unknown\",IF($H51=99,\"Stopped\",$D51)),0),\"Not required\")","v":148592},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I51>0, IF($I51=4,\"Unknown\",IF($I51=99,\"Stopped\",$D51)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J51>1,$J51<5), IF($J51=4, \"Unknown\", E51+F51), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K51>0,$K51<5), IF($K51=4,\"Unknown\", IF($K51=1, $F51*0.33, IF($K51=2, $F51*0.5+$G51*0.2, SUM(F51:G51)))), 0),\"Not required\")","v":39674.400000000001},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52943,"Gwanda"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland South","Insiza",109619,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D52*INTRO!$E$48,0))","v":12058},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D52*INTRO!$E$49,0))","v":33982},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D52*INTRO!$E$50,0))","v":61387},0,null,0,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H52>0,IF($H52=4,\"Unknown\",IF($H52=99,\"Stopped\",$D52)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I52>0, IF($I52=4,\"Unknown\",IF($I52=99,\"Stopped\",$D52)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J52>1,$J52<5), IF($J52=4, \"Unknown\", E52+F52), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K52>0,$K52<5), IF($K52=4,\"Unknown\", IF($K52=1, $F52*0.33, IF($K52=2, $F52*0.5+$G52*0.2, SUM(F52:G52)))), 0),\"Not required\")","v":29268.400000000001},0,null,0,1,null,null,null,null,null,52944,"Insiza"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland South","Mangwe",85048,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D53*INTRO!$E$48,0))","v":9355},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D53*INTRO!$E$49,0))","v":26365},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D53*INTRO!$E$50,0))","v":47627},0,null,0,0,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H53>0,IF($H53=4,\"Unknown\",IF($H53=99,\"Stopped\",$D53)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I53>0, IF($I53=4,\"Unknown\",IF($I53=99,\"Stopped\",$D53)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J53>1,$J53<5), IF($J53=4, \"Unknown\", E53+F53), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K53>0,$K53<5), IF($K53=4,\"Unknown\", IF($K53=1, $F53*0.33, IF($K53=2, $F53*0.5+$G53*0.2, SUM(F53:G53)))), 0),\"Not required\")","v":0},0,null,0,0,null,null,null,null,null,52945,"Mangwe"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland South","Matobo",102634,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D54*INTRO!$E$48,0))","v":11290},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D54*INTRO!$E$49,0))","v":31817},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D54*INTRO!$E$50,0))","v":57475},0,null,0,0,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H54>0,IF($H54=4,\"Unknown\",IF($H54=99,\"Stopped\",$D54)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I54>0, IF($I54=4,\"Unknown\",IF($I54=99,\"Stopped\",$D54)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J54>1,$J54<5), IF($J54=4, \"Unknown\", E54+F54), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K54>0,$K54<5), IF($K54=4,\"Unknown\", IF($K54=1, $F54*0.33, IF($K54=2, $F54*0.5+$G54*0.2, SUM(F54:G54)))), 0),\"Not required\")","v":0},0,null,0,0,null,null,null,null,null,52946,"Matobo"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Matabeleland South","Umzingwane",68820,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D55*INTRO!$E$48,0))","v":7570},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D55*INTRO!$E$49,0))","v":21334},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D55*INTRO!$E$50,0))","v":38539},0,null,0,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H55>0,IF($H55=4,\"Unknown\",IF($H55=99,\"Stopped\",$D55)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I55>0, IF($I55=4,\"Unknown\",IF($I55=99,\"Stopped\",$D55)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J55>1,$J55<5), IF($J55=4, \"Unknown\", E55+F55), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K55>0,$K55<5), IF($K55=4,\"Unknown\", IF($K55=1, $F55*0.33, IF($K55=2, $F55*0.5+$G55*0.2, SUM(F55:G55)))), 0),\"Not required\")","v":7040.22},0,null,0,0,null,null,null,null,null,52947,"Umzingwane"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Midlands","Chirumhanzi",87787,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D56*INTRO!$E$48,0))","v":9657},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D56*INTRO!$E$49,0))","v":27214},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D56*INTRO!$E$50,0))","v":49161},1,null,0,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H56>0,IF($H56=4,\"Unknown\",IF($H56=99,\"Stopped\",$D56)),0),\"Not required\")","v":87787},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I56>0, IF($I56=4,\"Unknown\",IF($I56=99,\"Stopped\",$D56)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J56>1,$J56<5), IF($J56=4, \"Unknown\", E56+F56), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K56>0,$K56<5), IF($K56=4,\"Unknown\", IF($K56=1, $F56*0.33, IF($K56=2, $F56*0.5+$G56*0.2, SUM(F56:G56)))), 0),\"Not required\")","v":23439.200000000001},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52955,"Chirumhanzi"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Midlands","Gokwe North",262597,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D57*INTRO!$E$48,0))","v":28886},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D57*INTRO!$E$49,0))","v":81405},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D57*INTRO!$E$50,0))","v":147054},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H57>0,IF($H57=4,\"Unknown\",IF($H57=99,\"Stopped\",$D57)),0),\"Not required\")","v":262597},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I57>0, IF($I57=4,\"Unknown\",IF($I57=99,\"Stopped\",$D57)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J57>1,$J57<5), IF($J57=4, \"Unknown\", E57+F57), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K57>0,$K57<5), IF($K57=4,\"Unknown\", IF($K57=1, $F57*0.33, IF($K57=2, $F57*0.5+$G57*0.2, SUM(F57:G57)))), 0),\"Not required\")","v":70113.3},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52956,"Gokwe North"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Midlands","Gokwe South",360581,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D58*INTRO!$E$48,0))","v":39664},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D58*INTRO!$E$49,0))","v":111780},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D58*INTRO!$E$50,0))","v":201925},1,null,1,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H58>0,IF($H58=4,\"Unknown\",IF($H58=99,\"Stopped\",$D58)),0),\"Not required\")","v":360581},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I58>0, IF($I58=4,\"Unknown\",IF($I58=99,\"Stopped\",$D58)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J58>1,$J58<5), IF($J58=4, \"Unknown\", E58+F58), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K58>0,$K58<5), IF($K58=4,\"Unknown\", IF($K58=1, $F58*0.33, IF($K58=2, $F58*0.5+$G58*0.2, SUM(F58:G58)))), 0),\"Not required\")","v":36887.4},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52957,"Gokwe South"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Midlands","Gweru",272777,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D59*INTRO!$E$48,0))","v":30005},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D59*INTRO!$E$49,0))","v":84561},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D59*INTRO!$E$50,0))","v":152755},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H59>0,IF($H59=4,\"Unknown\",IF($H59=99,\"Stopped\",$D59)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I59>0, IF($I59=4,\"Unknown\",IF($I59=99,\"Stopped\",$D59)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J59>1,$J59<5), IF($J59=4, \"Unknown\", E59+F59), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K59>0,$K59<5), IF($K59=4,\"Unknown\", IF($K59=1, $F59*0.33, IF($K59=2, $F59*0.5+$G59*0.2, SUM(F59:G59)))), 0),\"Not required\")","v":72831.5},0,null,0,1,null,null,null,null,null,52958,"Gweru"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Midlands","Kwekwe",340391,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D60*INTRO!$E$48,0))","v":37443},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D60*INTRO!$E$49,0))","v":105521},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D60*INTRO!$E$50,0))","v":190619},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H60>0,IF($H60=4,\"Unknown\",IF($H60=99,\"Stopped\",$D60)),0),\"Not required\")","v":340391},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I60>0, IF($I60=4,\"Unknown\",IF($I60=99,\"Stopped\",$D60)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J60>1,$J60<5), IF($J60=4, \"Unknown\", E60+F60), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K60>0,$K60<5), IF($K60=4,\"Unknown\", IF($K60=1, $F60*0.33, IF($K60=2, $F60*0.5+$G60*0.2, SUM(F60:G60)))), 0),\"Not required\")","v":90884.3},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52959,"Kwekwe"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Midlands","Mberengwa",202949,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D61*INTRO!$E$48,0))","v":22324},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D61*INTRO!$E$49,0))","v":62914},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D61*INTRO!$E$50,0))","v":113651},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H61>0,IF($H61=4,\"Unknown\",IF($H61=99,\"Stopped\",$D61)),0),\"Not required\")","v":202949},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I61>0, IF($I61=4,\"Unknown\",IF($I61=99,\"Stopped\",$D61)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J61>1,$J61<5), IF($J61=4, \"Unknown\", E61+F61), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K61>0,$K61<5), IF($K61=4,\"Unknown\", IF($K61=1, $F61*0.33, IF($K61=2, $F61*0.5+$G61*0.2, SUM(F61:G61)))), 0),\"Not required\")","v":54187.199999999997},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52960,"Mberengwa"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Midlands","Shurugwi",108681,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D62*INTRO!$E$48,0))","v":11955},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D62*INTRO!$E$49,0))","v":33691},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D62*INTRO!$E$50,0))","v":60861},1,null,1,3,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H62>0,IF($H62=4,\"Unknown\",IF($H62=99,\"Stopped\",$D62)),0),\"Not required\")","v":108681},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I62>0, IF($I62=4,\"Unknown\",IF($I62=99,\"Stopped\",$D62)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J62>1,$J62<5), IF($J62=4, \"Unknown\", E62+F62), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K62>0,$K62<5), IF($K62=4,\"Unknown\", IF($K62=1, $F62*0.33, IF($K62=2, $F62*0.5+$G62*0.2, SUM(F62:G62)))), 0),\"Not required\")","v":94552},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52961,"Shurugwi"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Midlands","Zvishavane",128640,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D63*INTRO!$E$48,0))","v":14150},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D63*INTRO!$E$49,0))","v":39878},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D63*INTRO!$E$50,0))","v":72038},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H63>0,IF($H63=4,\"Unknown\",IF($H63=99,\"Stopped\",$D63)),0),\"Not required\")","v":128640},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I63>0, IF($I63=4,\"Unknown\",IF($I63=99,\"Stopped\",$D63)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J63>1,$J63<5), IF($J63=4, \"Unknown\", E63+F63), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K63>0,$K63<5), IF($K63=4,\"Unknown\", IF($K63=1, $F63*0.33, IF($K63=2, $F63*0.5+$G63*0.2, SUM(F63:G63)))), 0),\"Not required\")","v":34346.6},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52962,"Zvishavane"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Masvingo","Bikita",177382,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D64*INTRO!$E$48,0))","v":19512},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D64*INTRO!$E$49,0))","v":54988},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D64*INTRO!$E$50,0))","v":99334},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H64>0,IF($H64=4,\"Unknown\",IF($H64=99,\"Stopped\",$D64)),0),\"Not required\")","v":177382},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I64>0, IF($I64=4,\"Unknown\",IF($I64=99,\"Stopped\",$D64)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J64>1,$J64<5), IF($J64=4, \"Unknown\", E64+F64), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K64>0,$K64<5), IF($K64=4,\"Unknown\", IF($K64=1, $F64*0.33, IF($K64=2, $F64*0.5+$G64*0.2, SUM(F64:G64)))), 0),\"Not required\")","v":47360.800000000003},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52934,"Bikita"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Masvingo","Chiredzi",334546,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D65*INTRO!$E$48,0))","v":36800},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D65*INTRO!$E$49,0))","v":103709},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D65*INTRO!$E$50,0))","v":187346},1,null,0,3,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H65>0,IF($H65=4,\"Unknown\",IF($H65=99,\"Stopped\",$D65)),0),\"Not required\")","v":334546},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I65>0, IF($I65=4,\"Unknown\",IF($I65=99,\"Stopped\",$D65)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J65>1,$J65<5), IF($J65=4, \"Unknown\", E65+F65), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K65>0,$K65<5), IF($K65=4,\"Unknown\", IF($K65=1, $F65*0.33, IF($K65=2, $F65*0.5+$G65*0.2, SUM(F65:G65)))), 0),\"Not required\")","v":291055},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52935,"Chiredzi"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Masvingo","Chivi",181416,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D66*INTRO!$E$48,0))","v":19956},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D66*INTRO!$E$49,0))","v":56239},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D66*INTRO!$E$50,0))","v":101593},0,null,0,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H66>0,IF($H66=4,\"Unknown\",IF($H66=99,\"Stopped\",$D66)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I66>0, IF($I66=4,\"Unknown\",IF($I66=99,\"Stopped\",$D66)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J66>1,$J66<5), IF($J66=4, \"Unknown\", E66+F66), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K66>0,$K66<5), IF($K66=4,\"Unknown\", IF($K66=1, $F66*0.33, IF($K66=2, $F66*0.5+$G66*0.2, SUM(F66:G66)))), 0),\"Not required\")","v":48438.100000000006},0,null,0,1,null,null,null,null,null,52936,"Chivi"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Masvingo","Gutu",221879,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D67*INTRO!$E$48,0))","v":24407},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D67*INTRO!$E$49,0))","v":68782},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D67*INTRO!$E$50,0))","v":124252},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H67>0,IF($H67=4,\"Unknown\",IF($H67=99,\"Stopped\",$D67)),0),\"Not required\")","v":221879},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I67>0, IF($I67=4,\"Unknown\",IF($I67=99,\"Stopped\",$D67)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J67>1,$J67<5), IF($J67=4, \"Unknown\", E67+F67), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K67>0,$K67<5), IF($K67=4,\"Unknown\", IF($K67=1, $F67*0.33, IF($K67=2, $F67*0.5+$G67*0.2, SUM(F67:G67)))), 0),\"Not required\")","v":59241.4},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52937,"Gutu"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Masvingo","Masvingo",326782,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D68*INTRO!$E$48,0))","v":35946},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D68*INTRO!$E$49,0))","v":101302},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D68*INTRO!$E$50,0))","v":182998},0,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H68>0,IF($H68=4,\"Unknown\",IF($H68=99,\"Stopped\",$D68)),0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I68>0, IF($I68=4,\"Unknown\",IF($I68=99,\"Stopped\",$D68)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J68>1,$J68<5), IF($J68=4, \"Unknown\", E68+F68), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K68>0,$K68<5), IF($K68=4,\"Unknown\", IF($K68=1, $F68*0.33, IF($K68=2, $F68*0.5+$G68*0.2, SUM(F68:G68)))), 0),\"Not required\")","v":87250.6},0,null,0,1,null,null,null,null,null,52938,"Masvingo"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Masvingo","Mwenezi",182448,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D69*INTRO!$E$48,0))","v":20069},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D69*INTRO!$E$49,0))","v":56559},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D69*INTRO!$E$50,0))","v":102171},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H69>0,IF($H69=4,\"Unknown\",IF($H69=99,\"Stopped\",$D69)),0),\"Not required\")","v":182448},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I69>0, IF($I69=4,\"Unknown\",IF($I69=99,\"Stopped\",$D69)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J69>1,$J69<5), IF($J69=4, \"Unknown\", E69+F69), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K69>0,$K69<5), IF($K69=4,\"Unknown\", IF($K69=1, $F69*0.33, IF($K69=2, $F69*0.5+$G69*0.2, SUM(F69:G69)))), 0),\"Not required\")","v":48713.7},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52939,"Mwenezi"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Masvingo","Zaka",198080,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D70*INTRO!$E$48,0))","v":21789},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D70*INTRO!$E$49,0))","v":61405},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D70*INTRO!$E$50,0))","v":110925},1,null,1,2,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H70>0,IF($H70=4,\"Unknown\",IF($H70=99,\"Stopped\",$D70)),0),\"Not required\")","v":198080},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I70>0, IF($I70=4,\"Unknown\",IF($I70=99,\"Stopped\",$D70)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J70>1,$J70<5), IF($J70=4, \"Unknown\", E70+F70), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K70>0,$K70<5), IF($K70=4,\"Unknown\", IF($K70=1, $F70*0.33, IF($K70=2, $F70*0.5+$G70*0.2, SUM(F70:G70)))), 0),\"Not required\")","v":52887.5},1,null,0,1,"Starting late: <4 MDA rounds",null,null,null,null,52940,"Zaka"]
[{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33, \" \")","v":"Zimbabwe"},"Bulawayo","Bulawayo",713803,{"$f":"IF(INTRO!$E$48=\"\",\"\",ROUND($D71*INTRO!$E$48,0))","v":78518},{"$f":"IF(INTRO!$E$49=\"\",\"\",ROUND($D71*INTRO!$E$49,0))","v":221279},{"$f":"IF(INTRO!$E$50=\"\",\"\",ROUND($D71*INTRO!$E$50,0))","v":399730},1,null,1,1,{"$f":"IF(INTRO!$E$37=\"Endemic\",IF($H71>0,IF($H71=4,\"Unknown\",IF($H71=99,\"Stopped\",$D71)),0),\"Not required\")","v":713803},{"$f":"IF(INTRO!$E$39=\"Endemic\", IF($I71>0, IF($I71=4,\"Unknown\",IF($I71=99,\"Stopped\",$D71)), 0),\"Not required\")","v":"Not required"},{"$f":"IF(INTRO!$E$41=\"Endemic\", IF(AND($J71>1,$J71<5), IF($J71=4, \"Unknown\", E71+F71), 0),\"Not required\")","v":0},{"$f":"IF(INTRO!$E$43=\"Endemic\", IF(AND($K71>0,$K71<5), IF($K71=4,\"Unknown\", IF($K71=1, $F71*0.33, IF($K71=2, $F71*0.5+$G71*0.2, SUM(F71:G71)))), 0),\"Not required\")","v":73022.070000000007},1,null,0,0,"Starting late: <4 MDA rounds",null,null,null,null,52902,"Bulawayo"]

{"sheet":"DEC","index":2,"n_rows":71,"n_cols":13,"rows_kept":71,"cut":false,"hidden":false,"merged":[[6,10,7,10],[6,0,7,0],[6,11,7,11],[5,3,5,6],[5,9,5,12],[6,4,7,4],[6,3,7,3],[6,8,7,8],[6,12,7,12],[6,7,7,7],[6,6,7,6],[6,9,7,9],[3,0,3,2],[5,0,5,2],[6,5,7,5],[6,2,7,2],[6,1,7,1]]}
["Diethylcarbamazine citrate (DEC)"]
["Administrative structure, eligible population by age group, treatment plan and information about tablets"]
[]
["TOTAL",null,null,{"$f":"SUM(D$9:D$1000)","v":883293},{"$f":"SUM(E$9:E$1000)","v":2489277},{"$f":"SUM(F$9:F$1000)","v":4496762},{"$f":"SUM(G$9:G$1000)","v":7869332},null,{"$f":"SUM(I$9:I$1000)","v":7869332},{"$f":"SUM(J$9:J$1000)","v":19673330},{"$f":"SUM(K$9:K$1000)","v":16587000},{"$f":"SUM(L$9:L$1000)","v":18805705},{"$f":"SUM(M$9:M$1000)","v":19694}]
[]
["Country administrative structure",null,null,"Population requiring treatment with DEC",null,null,null,"Treatment plan","Target population","Diethylcarbamazine citrate (DEC)"]
["Country","Province/State","District","PreSAC","SAC","Adults","Total","LF","LF","Total required","Remaining in stock","Tablets to be procured","Bottle (100 mg)\n1000 tablets"]
[]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A9=0,\" \",COUNTRY_INFO!A9)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B9=0,\" \",COUNTRY_INFO!B9)))","v":"Manicaland"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C9=0,\" \",COUNTRY_INFO!C9)))","v":"Buhera"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H9=1,COUNTRY_INFO!E9,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H9=1,COUNTRY_INFO!F9,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H9=1,COUNTRY_INFO!G9,0)))","v":0},{"$f":"SUM(D9:F9)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P9),\"Treat with IVM\")","v":0},{"$f":"IF(H9=1,G9,0)","v":0},{"$f":"IF(I9>0,I9*2.5,0)","v":0},null,{"$f":"IF($J9>$K9,$J9-$K9,0)","v":0},{"$f":"ROUNDUP($J9/1000,0)","v":0}]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A10=0,\" \",COUNTRY_INFO!A10)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B10=0,\" \",COUNTRY_INFO!B10)))","v":"Manicaland"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C10=0,\" \",COUNTRY_INFO!C10)))","v":"Chimanimani"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H10=1,COUNTRY_INFO!E10,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H10=1,COUNTRY_INFO!F10,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H10=1,COUNTRY_INFO!G10,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P10),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A11=0,\" \",COUNTRY_INFO!A11)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B11=0,\" \",COUNTRY_INFO!B11)))","v":"Manicaland"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C11=0,\" \",COUNTRY_INFO!C11)))","v":"Chipinge"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H11=1,COUNTRY_INFO!E11,0)))","v":38955},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H11=1,COUNTRY_INFO!F11,0)))","v":109781},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H11=1,COUNTRY_INFO!G11,0)))","v":198314},347050,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P11),\"Treat with IVM\")","v":1},347050,867625,16587000,0,868]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A12=0,\" \",COUNTRY_INFO!A12)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B12=0,\" \",COUNTRY_INFO!B12)))","v":"Manicaland"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C12=0,\" \",COUNTRY_INFO!C12)))","v":"Makoni"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H12=1,COUNTRY_INFO!E12,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H12=1,COUNTRY_INFO!F12,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H12=1,COUNTRY_INFO!G12,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P12),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A13=0,\" \",COUNTRY_INFO!A13)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B13=0,\" \",COUNTRY_INFO!B13)))","v":"Manicaland"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C13=0,\" \",COUNTRY_INFO!C13)))","v":"Mutare"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H13=1,COUNTRY_INFO!E13,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H13=1,COUNTRY_INFO!F13,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H13=1,COUNTRY_INFO!G13,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P13),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A14=0,\" \",COUNTRY_INFO!A14)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B14=0,\" \",COUNTRY_INFO!B14)))","v":"Manicaland"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C14=0,\" \",COUNTRY_INFO!C14)))","v":"Mutasa"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H14=1,COUNTRY_INFO!E14,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H14=1,COUNTRY_INFO!F14,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H14=1,COUNTRY_INFO!G14,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P14),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A15=0,\" \",COUNTRY_INFO!A15)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B15=0,\" \",COUNTRY_INFO!B15)))","v":"Manicaland"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C15=0,\" \",COUNTRY_INFO!C15)))","v":"Nyanga"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H15=1,COUNTRY_INFO!E15,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H15=1,COUNTRY_INFO!F15,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H15=1,COUNTRY_INFO!G15,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P15),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A16=0,\" \",COUNTRY_INFO!A16)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B16=0,\" \",COUNTRY_INFO!B16)))","v":"Harare"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C16=0,\" \",COUNTRY_INFO!C16)))","v":"Chitungwiza"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H16=1,COUNTRY_INFO!E16,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H16=1,COUNTRY_INFO!F16,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H16=1,COUNTRY_INFO!G16,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P16),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A17=0,\" \",COUNTRY_INFO!A17)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B17=0,\" \",COUNTRY_INFO!B17)))","v":"Harare"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C17=0,\" \",COUNTRY_INFO!C17)))","v":"Harare"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H17=1,COUNTRY_INFO!E17,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H17=1,COUNTRY_INFO!F17,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H17=1,COUNTRY_INFO!G17,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P17),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A18=0,\" \",COUNTRY_INFO!A18)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B18=0,\" \",COUNTRY_INFO!B18)))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C18=0,\" \",COUNTRY_INFO!C18)))","v":"Bindura"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H18=1,COUNTRY_INFO!E18,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H18=1,COUNTRY_INFO!F18,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H18=1,COUNTRY_INFO!G18,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P18),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A19=0,\" \",COUNTRY_INFO!A19)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B19=0,\" \",COUNTRY_INFO!B19)))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C19=0,\" \",COUNTRY_INFO!C19)))","v":"Centenary"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H19=1,COUNTRY_INFO!E19,0)))","v":14757},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H19=1,COUNTRY_INFO!F19,0)))","v":41588},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H19=1,COUNTRY_INFO!G19,0)))","v":75127},131472,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P19),\"Treat with IVM\")","v":1},131472,328680,null,328680,329]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A20=0,\" \",COUNTRY_INFO!A20)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B20=0,\" \",COUNTRY_INFO!B20)))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C20=0,\" \",COUNTRY_INFO!C20)))","v":"Guruve"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H20=1,COUNTRY_INFO!E20,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H20=1,COUNTRY_INFO!F20,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H20=1,COUNTRY_INFO!G20,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P20),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A21=0,\" \",COUNTRY_INFO!A21)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B21=0,\" \",COUNTRY_INFO!B21)))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C21=0,\" \",COUNTRY_INFO!C21)))","v":"Mazowe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H21=1,COUNTRY_INFO!E21,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H21=1,COUNTRY_INFO!F21,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H21=1,COUNTRY_INFO!G21,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P21),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A22=0,\" \",COUNTRY_INFO!A22)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B22=0,\" \",COUNTRY_INFO!B22)))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C22=0,\" \",COUNTRY_INFO!C22)))","v":"Mt Darwin"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H22=1,COUNTRY_INFO!E22,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H22=1,COUNTRY_INFO!F22,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H22=1,COUNTRY_INFO!G22,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P22),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A23=0,\" \",COUNTRY_INFO!A23)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B23=0,\" \",COUNTRY_INFO!B23)))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C23=0,\" \",COUNTRY_INFO!C23)))","v":"Rushinga"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H23=1,COUNTRY_INFO!E23,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H23=1,COUNTRY_INFO!F23,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H23=1,COUNTRY_INFO!G23,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P23),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A24=0,\" \",COUNTRY_INFO!A24)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B24=0,\" \",COUNTRY_INFO!B24)))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C24=0,\" \",COUNTRY_INFO!C24)))","v":"Shamva"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H24=1,COUNTRY_INFO!E24,0)))","v":14860},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H24=1,COUNTRY_INFO!F24,0)))","v":41879},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H24=1,COUNTRY_INFO!G24,0)))","v":75653},132392,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P24),\"Treat with IVM\")","v":1},132392,330980,null,330980,331]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A25=0,\" \",COUNTRY_INFO!A25)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B25=0,\" \",COUNTRY_INFO!B25)))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C25=0,\" \",COUNTRY_INFO!C25)))","v":"Mbire"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H25=1,COUNTRY_INFO!E25,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H25=1,COUNTRY_INFO!F25,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H25=1,COUNTRY_INFO!G25,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P25),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A26=0,\" \",COUNTRY_INFO!A26)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B26=0,\" \",COUNTRY_INFO!B26)))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C26=0,\" \",COUNTRY_INFO!C26)))","v":"Chikomba"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H26=1,COUNTRY_INFO!E26,0)))","v":14540},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H26=1,COUNTRY_INFO!F26,0)))","v":40977},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H26=1,COUNTRY_INFO!G26,0)))","v":74022},129539,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P26),\"Treat with IVM\")","v":1},129539,323847.5,null,323847.5,324]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A27=0,\" \",COUNTRY_INFO!A27)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B27=0,\" \",COUNTRY_INFO!B27)))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C27=0,\" \",COUNTRY_INFO!C27)))","v":"Goromonzi"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H27=1,COUNTRY_INFO!E27,0)))","v":27039},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H27=1,COUNTRY_INFO!F27,0)))","v":76201},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H27=1,COUNTRY_INFO!G27,0)))","v":137653},240893,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P27),\"Treat with IVM\")","v":1},240893,602232.5,null,602232.5,603]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A28=0,\" \",COUNTRY_INFO!A28)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B28=0,\" \",COUNTRY_INFO!B28)))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C28=0,\" \",COUNTRY_INFO!C28)))","v":"UMP"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H28=1,COUNTRY_INFO!E28,0)))","v":13534},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H28=1,COUNTRY_INFO!F28,0)))","v":38140},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H28=1,COUNTRY_INFO!G28,0)))","v":68898},120572,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P28),\"Treat with IVM\")","v":1},120572,301430,null,301430,302]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A29=0,\" \",COUNTRY_INFO!A29)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B29=0,\" \",COUNTRY_INFO!B29)))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C29=0,\" \",COUNTRY_INFO!C29)))","v":"Hwedza"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H29=1,COUNTRY_INFO!E29,0)))","v":8529},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H29=1,COUNTRY_INFO!F29,0)))","v":24036},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H29=1,COUNTRY_INFO!G29,0)))","v":43421},75986,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P29),\"Treat with IVM\")","v":1},75986,189965,null,189965,190]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A30=0,\" \",COUNTRY_INFO!A30)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B30=0,\" \",COUNTRY_INFO!B30)))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C30=0,\" \",COUNTRY_INFO!C30)))","v":"Marondera"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H30=1,COUNTRY_INFO!E30,0)))","v":21510},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H30=1,COUNTRY_INFO!F30,0)))","v":60620},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H30=1,COUNTRY_INFO!G30,0)))","v":109507},191637,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P30),\"Treat with IVM\")","v":1},191637,479092.5,null,479092.5,480]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A31=0,\" \",COUNTRY_INFO!A31)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B31=0,\" \",COUNTRY_INFO!B31)))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C31=0,\" \",COUNTRY_INFO!C31)))","v":"Mudzi"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H31=1,COUNTRY_INFO!E31,0)))","v":16014},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H31=1,COUNTRY_INFO!F31,0)))","v":45131},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H31=1,COUNTRY_INFO!G31,0)))","v":81528},142673,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P31),\"Treat with IVM\")","v":1},142673,356682.5,null,356682.5,357]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A32=0,\" \",COUNTRY_INFO!A32)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B32=0,\" \",COUNTRY_INFO!B32)))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C32=0,\" \",COUNTRY_INFO!C32)))","v":"Murewa"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H32=1,COUNTRY_INFO!E32,0)))","v":23989},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H32=1,COUNTRY_INFO!F32,0)))","v":67605},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H32=1,COUNTRY_INFO!G32,0)))","v":122125},213719,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P32),\"Treat with IVM\")","v":1},213719,534297.5,null,534297.5,535]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A33=0,\" \",COUNTRY_INFO!A33)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B33=0,\" \",COUNTRY_INFO!B33)))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C33=0,\" \",COUNTRY_INFO!C33)))","v":"Mutoko"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H33=1,COUNTRY_INFO!E33,0)))","v":17562},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H33=1,COUNTRY_INFO!F33,0)))","v":49492},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H33=1,COUNTRY_INFO!G33,0)))","v":89405},156459,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P33),\"Treat with IVM\")","v":1},156459,391147.5,null,391147.5,392]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A34=0,\" \",COUNTRY_INFO!A34)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B34=0,\" \",COUNTRY_INFO!B34)))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C34=0,\" \",COUNTRY_INFO!C34)))","v":"Seke"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H34=1,COUNTRY_INFO!E34,0)))","v":39046},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H34=1,COUNTRY_INFO!F34,0)))","v":110039},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H34=1,COUNTRY_INFO!G34,0)))","v":198780},347865,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P34),\"Treat with IVM\")","v":1},347865,869662.5,null,869662.5,870]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A35=0,\" \",COUNTRY_INFO!A35)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B35=0,\" \",COUNTRY_INFO!B35)))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C35=0,\" \",COUNTRY_INFO!C35)))","v":"Chegutu"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H35=1,COUNTRY_INFO!E35,0)))","v":32669},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H35=1,COUNTRY_INFO!F35,0)))","v":92068},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H35=1,COUNTRY_INFO!G35,0)))","v":166317},291054,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P35),\"Treat with IVM\")","v":1},291054,727635,null,727635,728]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A36=0,\" \",COUNTRY_INFO!A36)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B36=0,\" \",COUNTRY_INFO!B36)))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C36=0,\" \",COUNTRY_INFO!C36)))","v":"Hurungwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H36=1,COUNTRY_INFO!E36,0)))","v":43001},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H36=1,COUNTRY_INFO!F36,0)))","v":121184},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H36=1,COUNTRY_INFO!G36,0)))","v":218914},383099,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P36),\"Treat with IVM\")","v":1},383099,957747.5,null,957747.5,958]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A37=0,\" \",COUNTRY_INFO!A37)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B37=0,\" \",COUNTRY_INFO!B37)))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C37=0,\" \",COUNTRY_INFO!C37)))","v":"Sanyati"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H37=1,COUNTRY_INFO!E37,0)))","v":24681},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H37=1,COUNTRY_INFO!F37,0)))","v":69556},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H37=1,COUNTRY_INFO!G37,0)))","v":125649},219886,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P37),\"Treat with IVM\")","v":1},219886,549715,null,549715,550]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A38=0,\" \",COUNTRY_INFO!A38)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B38=0,\" \",COUNTRY_INFO!B38)))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C38=0,\" \",COUNTRY_INFO!C38)))","v":"Kariba"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H38=1,COUNTRY_INFO!E38,0)))","v":8151},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H38=1,COUNTRY_INFO!F38,0)))","v":22970},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H38=1,COUNTRY_INFO!G38,0)))","v":41494},72615,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P38),\"Treat with IVM\")","v":1},72615,181537.5,null,181537.5,182]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A39=0,\" \",COUNTRY_INFO!A39)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B39=0,\" \",COUNTRY_INFO!B39)))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C39=0,\" \",COUNTRY_INFO!C39)))","v":"Makonde"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H39=1,COUNTRY_INFO!E39,0)))","v":27818},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H39=1,COUNTRY_INFO!F39,0)))","v":78396},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H39=1,COUNTRY_INFO!G39,0)))","v":141619},247833,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P39),\"Treat with IVM\")","v":1},247833,619582.5,null,619582.5,620]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A40=0,\" \",COUNTRY_INFO!A40)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B40=0,\" \",COUNTRY_INFO!B40)))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C40=0,\" \",COUNTRY_INFO!C40)))","v":"Mhondoro-Ngezi"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H40=1,COUNTRY_INFO!E40,0)))","v":12540},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H40=1,COUNTRY_INFO!F40,0)))","v":35339},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H40=1,COUNTRY_INFO!G40,0)))","v":63839},111718,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P40),\"Treat with IVM\")","v":1},111718,279295,null,279295,280]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A41=0,\" \",COUNTRY_INFO!A41)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B41=0,\" \",COUNTRY_INFO!B41)))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C41=0,\" \",COUNTRY_INFO!C41)))","v":"Zvimba"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H41=1,COUNTRY_INFO!E41,0)))","v":31610},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H41=1,COUNTRY_INFO!F41,0)))","v":89083},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H41=1,COUNTRY_INFO!G41,0)))","v":160923},{"$f":"SUM(D41:F41)","v":281616},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P41),\"Treat with IVM\")","v":1},{"$f":"IF(H41=1,G41,0)","v":281616},{"$f":"IF(I41>0,I41*2.5,0)","v":704040},null,{"$f":"IF($J41>$K41,$J41-$K41,0)","v":704040},{"$f":"ROUNDUP($J41/1000,0)","v":705}]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A42=0,\" \",COUNTRY_INFO!A42)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B42=0,\" \",COUNTRY_INFO!B42)))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C42=0,\" \",COUNTRY_INFO!C42)))","v":"Binga"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H42=1,COUNTRY_INFO!E42,0)))","v":16716},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H42=1,COUNTRY_INFO!F42,0)))","v":47109},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H42=1,COUNTRY_INFO!G42,0)))","v":85100},148925,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P42),\"Treat with IVM\")","v":1},148925,372312.5,null,372312.5,373]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A43=0,\" \",COUNTRY_INFO!A43)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B43=0,\" \",COUNTRY_INFO!B43)))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C43=0,\" \",COUNTRY_INFO!C43)))","v":"Bubi"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H43=1,COUNTRY_INFO!E43,0)))","v":7437},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H43=1,COUNTRY_INFO!F43,0)))","v":20959},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H43=1,COUNTRY_INFO!G43,0)))","v":37861},66257,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P43),\"Treat with IVM\")","v":1},66257,165642.5,null,165642.5,166]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A44=0,\" \",COUNTRY_INFO!A44)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B44=0,\" \",COUNTRY_INFO!B44)))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C44=0,\" \",COUNTRY_INFO!C44)))","v":"Hwange"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H44=1,COUNTRY_INFO!E44,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H44=1,COUNTRY_INFO!F44,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H44=1,COUNTRY_INFO!G44,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P44),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A45=0,\" \",COUNTRY_INFO!A45)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B45=0,\" \",COUNTRY_INFO!B45)))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C45=0,\" \",COUNTRY_INFO!C45)))","v":"Lupane"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H45=1,COUNTRY_INFO!E45,0)))","v":12037},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H45=1,COUNTRY_INFO!F45,0)))","v":33924},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H45=1,COUNTRY_INFO!G45,0)))","v":61281},107242,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P45),\"Treat with IVM\")","v":1},107242,268105,null,268105,269]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A46=0,\" \",COUNTRY_INFO!A46)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B46=0,\" \",COUNTRY_INFO!B46)))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C46=0,\" \",COUNTRY_INFO!C46)))","v":"Nkayi"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H46=1,COUNTRY_INFO!E46,0)))","v":13116},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H46=1,COUNTRY_INFO!F46,0)))","v":36963},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H46=1,COUNTRY_INFO!G46,0)))","v":66772},116851,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P46),\"Treat with IVM\")","v":1},116851,292127.5,null,292127.5,293]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A47=0,\" \",COUNTRY_INFO!A47)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B47=0,\" \",COUNTRY_INFO!B47)))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C47=0,\" \",COUNTRY_INFO!C47)))","v":"Tsholotsho"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H47=1,COUNTRY_INFO!E47,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H47=1,COUNTRY_INFO!F47,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H47=1,COUNTRY_INFO!G47,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P47),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A48=0,\" \",COUNTRY_INFO!A48)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B48=0,\" \",COUNTRY_INFO!B48)))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C48=0,\" \",COUNTRY_INFO!C48)))","v":"Umguza"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H48=1,COUNTRY_INFO!E48,0)))","v":10779},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H48=1,COUNTRY_INFO!F48,0)))","v":30376},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H48=1,COUNTRY_INFO!G48,0)))","v":54873},96028,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P48),\"Treat with IVM\")","v":1},96028,240070,null,240070,241]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A49=0,\" \",COUNTRY_INFO!A49)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B49=0,\" \",COUNTRY_INFO!B49)))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C49=0,\" \",COUNTRY_INFO!C49)))","v":"Beit Bridge"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H49=1,COUNTRY_INFO!E49,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H49=1,COUNTRY_INFO!F49,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H49=1,COUNTRY_INFO!G49,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P49),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A50=0,\" \",COUNTRY_INFO!A50)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B50=0,\" \",COUNTRY_INFO!B50)))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C50=0,\" \",COUNTRY_INFO!C50)))","v":"Bulilima"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H50=1,COUNTRY_INFO!E50,0)))","v":10884},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H50=1,COUNTRY_INFO!F50,0)))","v":30672},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H50=1,COUNTRY_INFO!G50,0)))","v":55408},96964,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P50),\"Treat with IVM\")","v":1},96964,242410,null,242410,243]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A51=0,\" \",COUNTRY_INFO!A51)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B51=0,\" \",COUNTRY_INFO!B51)))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C51=0,\" \",COUNTRY_INFO!C51)))","v":"Gwanda"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H51=1,COUNTRY_INFO!E51,0)))","v":16345},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H51=1,COUNTRY_INFO!F51,0)))","v":46064},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H51=1,COUNTRY_INFO!G51,0)))","v":83212},145621,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P51),\"Treat with IVM\")","v":1},145621,364052.5,null,364052.5,365]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A52=0,\" \",COUNTRY_INFO!A52)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B52=0,\" \",COUNTRY_INFO!B52)))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C52=0,\" \",COUNTRY_INFO!C52)))","v":"Insiza"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H52=1,COUNTRY_INFO!E52,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H52=1,COUNTRY_INFO!F52,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H52=1,COUNTRY_INFO!G52,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P52),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A53=0,\" \",COUNTRY_INFO!A53)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B53=0,\" \",COUNTRY_INFO!B53)))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C53=0,\" \",COUNTRY_INFO!C53)))","v":"Mangwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H53=1,COUNTRY_INFO!E53,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H53=1,COUNTRY_INFO!F53,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H53=1,COUNTRY_INFO!G53,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P53),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A54=0,\" \",COUNTRY_INFO!A54)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B54=0,\" \",COUNTRY_INFO!B54)))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C54=0,\" \",COUNTRY_INFO!C54)))","v":"Matobo"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H54=1,COUNTRY_INFO!E54,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H54=1,COUNTRY_INFO!F54,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H54=1,COUNTRY_INFO!G54,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P54),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A55=0,\" \",COUNTRY_INFO!A55)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B55=0,\" \",COUNTRY_INFO!B55)))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C55=0,\" \",COUNTRY_INFO!C55)))","v":"Umzingwane"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H55=1,COUNTRY_INFO!E55,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H55=1,COUNTRY_INFO!F55,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H55=1,COUNTRY_INFO!G55,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P55),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A56=0,\" \",COUNTRY_INFO!A56)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B56=0,\" \",COUNTRY_INFO!B56)))","v":"Midlands"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C56=0,\" \",COUNTRY_INFO!C56)))","v":"Chirumhanzi"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H56=1,COUNTRY_INFO!E56,0)))","v":9657},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H56=1,COUNTRY_INFO!F56,0)))","v":27214},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H56=1,COUNTRY_INFO!G56,0)))","v":49161},86032,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P56),\"Treat with IVM\")","v":1},86032,215080,null,215080,216]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A57=0,\" \",COUNTRY_INFO!A57)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B57=0,\" \",COUNTRY_INFO!B57)))","v":"Midlands"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C57=0,\" \",COUNTRY_INFO!C57)))","v":"Gokwe North"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H57=1,COUNTRY_INFO!E57,0)))","v":28886},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H57=1,COUNTRY_INFO!F57,0)))","v":81405},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H57=1,COUNTRY_INFO!G57,0)))","v":147054},257345,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P57),\"Treat with IVM\")","v":1},257345,643362.5,null,643362.5,644]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A58=0,\" \",COUNTRY_INFO!A58)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B58=0,\" \",COUNTRY_INFO!B58)))","v":"Midlands"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C58=0,\" \",COUNTRY_INFO!C58)))","v":"Gokwe South"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H58=1,COUNTRY_INFO!E58,0)))","v":39664},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H58=1,COUNTRY_INFO!F58,0)))","v":111780},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H58=1,COUNTRY_INFO!G58,0)))","v":201925},353369,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P58),\"Treat with IVM\")","v":1},353369,883422.5,null,883422.5,884]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A59=0,\" \",COUNTRY_INFO!A59)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B59=0,\" \",COUNTRY_INFO!B59)))","v":"Midlands"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C59=0,\" \",COUNTRY_INFO!C59)))","v":"Gweru"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H59=1,COUNTRY_INFO!E59,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H59=1,COUNTRY_INFO!F59,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H59=1,COUNTRY_INFO!G59,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P59),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A60=0,\" \",COUNTRY_INFO!A60)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B60=0,\" \",COUNTRY_INFO!B60)))","v":"Midlands"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C60=0,\" \",COUNTRY_INFO!C60)))","v":"Kwekwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H60=1,COUNTRY_INFO!E60,0)))","v":37443},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H60=1,COUNTRY_INFO!F60,0)))","v":105521},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H60=1,COUNTRY_INFO!G60,0)))","v":190619},333583,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P60),\"Treat with IVM\")","v":1},333583,833957.5,null,833957.5,834]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A61=0,\" \",COUNTRY_INFO!A61)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B61=0,\" \",COUNTRY_INFO!B61)))","v":"Midlands"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C61=0,\" \",COUNTRY_INFO!C61)))","v":"Mberengwa"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H61=1,COUNTRY_INFO!E61,0)))","v":22324},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H61=1,COUNTRY_INFO!F61,0)))","v":62914},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H61=1,COUNTRY_INFO!G61,0)))","v":113651},198889,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P61),\"Treat with IVM\")","v":1},198889,497222.5,null,497222.5,498]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A62=0,\" \",COUNTRY_INFO!A62)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B62=0,\" \",COUNTRY_INFO!B62)))","v":"Midlands"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C62=0,\" \",COUNTRY_INFO!C62)))","v":"Shurugwi"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H62=1,COUNTRY_INFO!E62,0)))","v":11955},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H62=1,COUNTRY_INFO!F62,0)))","v":33691},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H62=1,COUNTRY_INFO!G62,0)))","v":60861},106507,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P62),\"Treat with IVM\")","v":1},106507,266267.5,null,266267.5,267]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A63=0,\" \",COUNTRY_INFO!A63)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B63=0,\" \",COUNTRY_INFO!B63)))","v":"Midlands"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C63=0,\" \",COUNTRY_INFO!C63)))","v":"Zvishavane"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H63=1,COUNTRY_INFO!E63,0)))","v":14150},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H63=1,COUNTRY_INFO!F63,0)))","v":39878},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H63=1,COUNTRY_INFO!G63,0)))","v":72038},126066,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P63),\"Treat with IVM\")","v":1},126066,315165,null,315165,316]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A64=0,\" \",COUNTRY_INFO!A64)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B64=0,\" \",COUNTRY_INFO!B64)))","v":"Masvingo"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C64=0,\" \",COUNTRY_INFO!C64)))","v":"Bikita"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H64=1,COUNTRY_INFO!E64,0)))","v":19512},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H64=1,COUNTRY_INFO!F64,0)))","v":54988},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H64=1,COUNTRY_INFO!G64,0)))","v":99334},173834,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P64),\"Treat with IVM\")","v":1},173834,434585,null,434585,435]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A65=0,\" \",COUNTRY_INFO!A65)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B65=0,\" \",COUNTRY_INFO!B65)))","v":"Masvingo"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C65=0,\" \",COUNTRY_INFO!C65)))","v":"Chiredzi"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H65=1,COUNTRY_INFO!E65,0)))","v":36800},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H65=1,COUNTRY_INFO!F65,0)))","v":103709},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H65=1,COUNTRY_INFO!G65,0)))","v":187346},327855,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P65),\"Treat with IVM\")","v":1},327855,819637.5,null,819637.5,820]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A66=0,\" \",COUNTRY_INFO!A66)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B66=0,\" \",COUNTRY_INFO!B66)))","v":"Masvingo"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C66=0,\" \",COUNTRY_INFO!C66)))","v":"Chivi"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H66=1,COUNTRY_INFO!E66,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H66=1,COUNTRY_INFO!F66,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H66=1,COUNTRY_INFO!G66,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P66),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A67=0,\" \",COUNTRY_INFO!A67)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B67=0,\" \",COUNTRY_INFO!B67)))","v":"Masvingo"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C67=0,\" \",COUNTRY_INFO!C67)))","v":"Gutu"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H67=1,COUNTRY_INFO!E67,0)))","v":24407},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H67=1,COUNTRY_INFO!F67,0)))","v":68782},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H67=1,COUNTRY_INFO!G67,0)))","v":124252},217441,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P67),\"Treat with IVM\")","v":1},217441,543602.5,null,543602.5,544]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A68=0,\" \",COUNTRY_INFO!A68)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B68=0,\" \",COUNTRY_INFO!B68)))","v":"Masvingo"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C68=0,\" \",COUNTRY_INFO!C68)))","v":"Masvingo"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H68=1,COUNTRY_INFO!E68,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H68=1,COUNTRY_INFO!F68,0)))","v":0},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H68=1,COUNTRY_INFO!G68,0)))","v":0},0,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P68),\"Treat with IVM\")","v":0},0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A69=0,\" \",COUNTRY_INFO!A69)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B69=0,\" \",COUNTRY_INFO!B69)))","v":"Masvingo"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C69=0,\" \",COUNTRY_INFO!C69)))","v":"Mwenezi"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H69=1,COUNTRY_INFO!E69,0)))","v":20069},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H69=1,COUNTRY_INFO!F69,0)))","v":56559},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H69=1,COUNTRY_INFO!G69,0)))","v":102171},178799,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P69),\"Treat with IVM\")","v":1},178799,446997.5,null,446997.5,447]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A70=0,\" \",COUNTRY_INFO!A70)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B70=0,\" \",COUNTRY_INFO!B70)))","v":"Masvingo"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C70=0,\" \",COUNTRY_INFO!C70)))","v":"Zaka"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H70=1,COUNTRY_INFO!E70,0)))","v":21789},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H70=1,COUNTRY_INFO!F70,0)))","v":61405},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H70=1,COUNTRY_INFO!G70,0)))","v":110925},194119,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P70),\"Treat with IVM\")","v":1},194119,485297.5,null,485297.5,486]
[{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A71=0,\" \",COUNTRY_INFO!A71)))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B71=0,\" \",COUNTRY_INFO!B71)))","v":"Bulawayo"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", \" \", IF(INTRO!$E$37=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C71=0,\" \",COUNTRY_INFO!C71)))","v":"Bulawayo"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H71=1,COUNTRY_INFO!E71,0)))","v":78518},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H71=1,COUNTRY_INFO!F71,0)))","v":221279},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\", 0, IF(INTRO!$E$37=\"Non-endemic\",0,IF(COUNTRY_INFO!$H71=1,COUNTRY_INFO!G71,0)))","v":399730},699527,{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF(INTRO!$E$37=\"Non-endemic\",\"Not required\",COUNTRY_INFO!P71),\"Treat with IVM\")","v":1},699527,1748817.5,null,1748817.5,1749]

{"sheet":"ALB_MBD","index":3,"n_rows":71,"n_cols":27,"rows_kept":71,"cut":false,"hidden":false,"merged":[[5,10,5,17],[5,8,7,8],[5,18,5,23],[6,26,7,26],[5,24,5,26],[6,24,7,24],[6,25,7,25],[6,22,7,22],[3,0,3,2],[3,6,3,7],[5,0,5,2],[5,6,5,7],[5,3,5,5],[6,0,7,0],[6,1,7,1],[6,2,7,2],[6,3,7,3],[6,23,7,23],[6,21,7,21],[6,18,7,18],[6,19,7,19],[6,20,7,20],[6,4,7,4],[6,5,7,5],[6,6,7,6],[6,7,7,7],[6,14,6,17],[5,9,7,9],[6,10,6,13]]}
["Albendazole (ALB) and Mebendazole (MBD)"]
["Administrative structure, eligible population by age group, treatment plan and information about tablets"]
[]
["TOTAL",null,null,{"$f":"SUM(D$9:D$1000)","v":1449449},{"$f":"SUM(E$9:E$1000)","v":4084812},{"$f":"SUM(F$9:F$1000)","v":5534261},null,null,{"$f":"SUM(I$9:I$1000)","v":7869332},null,{"$f":"SUM(K$9:K$1000)","v":0},{"$f":"SUM(L$9:L$1000)","v":0},{"$f":"SUM(M$9:M$1000)","v":0},{"$f":"SUM(N$9:N$1000)","v":0},{"$f":"SUM(O$9:O$1000)","v":0},{"$f":"SUM(P$9:P$1000)","v":0},0,0,3431500,7522282,39368,0,0,0,0,0,0]
[]
["Country administrative structure",null,null,"Population requiring treatment with ALB/MBD",null,null,"Treatment plan",null,"People covered by PELF with ALB","Select medicine for treatment of STH","Target population",null,null,null,null,null,null,null,"Albendazole (ALB)",null,null,null,null,null,"Mebendazole (MBD)"]
["Country","Province/State","District","PreSAC","SAC","Total","LF","STH",null,null,"STH (ALB)",null,null,null,"STH (MBD)",null,null,null,"Remaining in stock (LF)","Tablets to be procured (LF)","Bottle (400 mg)\n200 tablets (LF)","Remaining in stock (STH)","Tablets to be procured for SAC (STH)","Bottle (400 mg)\n200 tablets (STH)","Remaining in stock","Tablets to be procured for SAC","Bottles (500 mg)\n150 tablets"]
[null,null,null,null,null,null,null,null,null,null,"PreSAC","SAC","Other","Total","PreSAC","SAC","Other","Total"]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A9=0,\" \",COUNTRY_INFO!A9))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B9=0,\" \",COUNTRY_INFO!B9))","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C9=0,\" \",COUNTRY_INFO!C9))","v":"Buhera"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H9=0,COUNTRY_INFO!$H9=4,COUNTRY_INFO!$H9=99),OR(COUNTRY_INFO!$J9=0,COUNTRY_INFO!$J9=4)),0,COUNTRY_INFO!$E9))","v":29550},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H9=0,COUNTRY_INFO!$H9=4,COUNTRY_INFO!$H9=99),OR(COUNTRY_INFO!$J9=0,COUNTRY_INFO!$J9=4)),0,COUNTRY_INFO!$F9))","v":83276},{"$f":"SUM(D9:E9)","v":112826},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P9)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R9)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G9=1,DEC!I9,0),IF($G9=1,IVM!G9,0))","v":0},"ALB",{"$f":"IF($J9=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H9<>0, IF($I9=0, $D9*$H9, $D9*($H9-$G9)), 0), $D9*$H9), 0)","v":0},{"$f":"IF($J9=\"ALB\", IF($H9<>0, IF($I9=0, $E9*$H9, $E9*($H9-$G9)),0), 0)","v":0},null,{"$f":"SUM(K9:M9)","v":0},{"$f":"IF($J9=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H9<>0, IF($I9=0, $D9*$H9, $D9*($H9-$G9)), 0), $D9*$H9), 0)","v":0},{"$f":"IF($J9=\"MBD\", IF($H9<>0,IF($I9=0, $E9*$H9, $E9*($H9-$G9)),0), 0 )","v":0},null,{"$f":"SUM(O9:Q9)","v":0},null,{"$f":"IF($I9>$S9, $I9-$S9,0)","v":0},{"$f":"ROUNDUP($I9/200,0)","v":0},null,{"$f":"IF($L9>$V9,$L9-$V9,0)","v":0},{"$f":"ROUNDUP($L9/200,0)","v":0},null,{"$f":"IF($P9>$Y9,$P9-$Y9,0)","v":0},{"$f":"ROUNDUP($P9/150,0)","v":0}]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A10=0,\" \",COUNTRY_INFO!A10))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B10=0,\" \",COUNTRY_INFO!B10))","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C10=0,\" \",COUNTRY_INFO!C10))","v":"Chimanimani"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H10=0,COUNTRY_INFO!$H10=4,COUNTRY_INFO!$H10=99),OR(COUNTRY_INFO!$J10=0,COUNTRY_INFO!$J10=4)),0,COUNTRY_INFO!$E10))","v":16217},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H10=0,COUNTRY_INFO!$H10=4,COUNTRY_INFO!$H10=99),OR(COUNTRY_INFO!$J10=0,COUNTRY_INFO!$J10=4)),0,COUNTRY_INFO!$F10))","v":45703},61920,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P10)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R10)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G10=1,DEC!I10,0),IF($G10=1,IVM!G10,0))","v":0},null,{"$f":"IF($J10=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H10<>0, IF($I10=0, $D10*$H10, $D10*($H10-$G10)), 0), $D10*$H10), 0)","v":0},0,null,0,{"$f":"IF($J10=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H10<>0, IF($I10=0, $D10*$H10, $D10*($H10-$G10)), 0), $D10*$H10), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A11=0,\" \",COUNTRY_INFO!A11))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B11=0,\" \",COUNTRY_INFO!B11))","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C11=0,\" \",COUNTRY_INFO!C11))","v":"Chipinge"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H11=0,COUNTRY_INFO!$H11=4,COUNTRY_INFO!$H11=99),OR(COUNTRY_INFO!$J11=0,COUNTRY_INFO!$J11=4)),0,COUNTRY_INFO!$E11))","v":38955},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H11=0,COUNTRY_INFO!$H11=4,COUNTRY_INFO!$H11=99),OR(COUNTRY_INFO!$J11=0,COUNTRY_INFO!$J11=4)),0,COUNTRY_INFO!$F11))","v":109781},148736,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P11)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R11)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G11=1,DEC!I11,0),IF($G11=1,IVM!G11,0))","v":347050},null,{"$f":"IF($J11=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H11<>0, IF($I11=0, $D11*$H11, $D11*($H11-$G11)), 0), $D11*$H11), 0)","v":0},0,null,0,{"$f":"IF($J11=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H11<>0, IF($I11=0, $D11*$H11, $D11*($H11-$G11)), 0), $D11*$H11), 0)","v":0},0,null,0,3431500,0,1736,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A12=0,\" \",COUNTRY_INFO!A12))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B12=0,\" \",COUNTRY_INFO!B12))","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C12=0,\" \",COUNTRY_INFO!C12))","v":"Makoni"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H12=0,COUNTRY_INFO!$H12=4,COUNTRY_INFO!$H12=99),OR(COUNTRY_INFO!$J12=0,COUNTRY_INFO!$J12=4)),0,COUNTRY_INFO!$E12))","v":36373},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H12=0,COUNTRY_INFO!$H12=4,COUNTRY_INFO!$H12=99),OR(COUNTRY_INFO!$J12=0,COUNTRY_INFO!$J12=4)),0,COUNTRY_INFO!$F12))","v":102507},138880,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P12)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R12)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G12=1,DEC!I12,0),IF($G12=1,IVM!G12,0))","v":0},null,{"$f":"IF($J12=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H12<>0, IF($I12=0, $D12*$H12, $D12*($H12-$G12)), 0), $D12*$H12), 0)","v":0},0,null,0,{"$f":"IF($J12=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H12<>0, IF($I12=0, $D12*$H12, $D12*($H12-$G12)), 0), $D12*$H12), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A13=0,\" \",COUNTRY_INFO!A13))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B13=0,\" \",COUNTRY_INFO!B13))","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C13=0,\" \",COUNTRY_INFO!C13))","v":"Mutare"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H13=0,COUNTRY_INFO!$H13=4,COUNTRY_INFO!$H13=99),OR(COUNTRY_INFO!$J13=0,COUNTRY_INFO!$J13=4)),0,COUNTRY_INFO!$E13))","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H13=0,COUNTRY_INFO!$H13=4,COUNTRY_INFO!$H13=99),OR(COUNTRY_INFO!$J13=0,COUNTRY_INFO!$J13=4)),0,COUNTRY_INFO!$F13))","v":0},0,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P13)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R13)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G13=1,DEC!I13,0),IF($G13=1,IVM!G13,0))","v":0},null,{"$f":"IF($J13=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H13<>0, IF($I13=0, $D13*$H13, $D13*($H13-$G13)), 0), $D13*$H13), 0)","v":0},0,null,0,{"$f":"IF($J13=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H13<>0, IF($I13=0, $D13*$H13, $D13*($H13-$G13)), 0), $D13*$H13), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A14=0,\" \",COUNTRY_INFO!A14))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B14=0,\" \",COUNTRY_INFO!B14))","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C14=0,\" \",COUNTRY_INFO!C14))","v":"Mutasa"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H14=0,COUNTRY_INFO!$H14=4,COUNTRY_INFO!$H14=99),OR(COUNTRY_INFO!$J14=0,COUNTRY_INFO!$J14=4)),0,COUNTRY_INFO!$E14))","v":20280},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H14=0,COUNTRY_INFO!$H14=4,COUNTRY_INFO!$H14=99),OR(COUNTRY_INFO!$J14=0,COUNTRY_INFO!$J14=4)),0,COUNTRY_INFO!$F14))","v":57153},77433,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P14)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R14)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G14=1,DEC!I14,0),IF($G14=1,IVM!G14,0))","v":0},null,{"$f":"IF($J14=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H14<>0, IF($I14=0, $D14*$H14, $D14*($H14-$G14)), 0), $D14*$H14), 0)","v":0},0,null,0,{"$f":"IF($J14=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H14<>0, IF($I14=0, $D14*$H14, $D14*($H14-$G14)), 0), $D14*$H14), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A15=0,\" \",COUNTRY_INFO!A15))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B15=0,\" \",COUNTRY_INFO!B15))","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C15=0,\" \",COUNTRY_INFO!C15))","v":"Nyanga"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H15=0,COUNTRY_INFO!$H15=4,COUNTRY_INFO!$H15=99),OR(COUNTRY_INFO!$J15=0,COUNTRY_INFO!$J15=4)),0,COUNTRY_INFO!$E15))","v":37763},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H15=0,COUNTRY_INFO!$H15=4,COUNTRY_INFO!$H15=99),OR(COUNTRY_INFO!$J15=0,COUNTRY_INFO!$J15=4)),0,COUNTRY_INFO!$F15))","v":106423},144186,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P15)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R15)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G15=1,DEC!I15,0),IF($G15=1,IVM!G15,0))","v":0},null,{"$f":"IF($J15=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H15<>0, IF($I15=0, $D15*$H15, $D15*($H15-$G15)), 0), $D15*$H15), 0)","v":0},0,null,0,{"$f":"IF($J15=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H15<>0, IF($I15=0, $D15*$H15, $D15*($H15-$G15)), 0), $D15*$H15), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A16=0,\" \",COUNTRY_INFO!A16))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B16=0,\" \",COUNTRY_INFO!B16))","v":"Harare"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C16=0,\" \",COUNTRY_INFO!C16))","v":"Chitungwiza"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H16=0,COUNTRY_INFO!$H16=4,COUNTRY_INFO!$H16=99),OR(COUNTRY_INFO!$J16=0,COUNTRY_INFO!$J16=4)),0,COUNTRY_INFO!$E16))","v":42885},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H16=0,COUNTRY_INFO!$H16=4,COUNTRY_INFO!$H16=99),OR(COUNTRY_INFO!$J16=0,COUNTRY_INFO!$J16=4)),0,COUNTRY_INFO!$F16))","v":120858},163743,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P16)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R16)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G16=1,DEC!I16,0),IF($G16=1,IVM!G16,0))","v":0},null,{"$f":"IF($J16=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H16<>0, IF($I16=0, $D16*$H16, $D16*($H16-$G16)), 0), $D16*$H16), 0)","v":0},0,null,0,{"$f":"IF($J16=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H16<>0, IF($I16=0, $D16*$H16, $D16*($H16-$G16)), 0), $D16*$H16), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A17=0,\" \",COUNTRY_INFO!A17))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B17=0,\" \",COUNTRY_INFO!B17))","v":"Harare"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C17=0,\" \",COUNTRY_INFO!C17))","v":"Harare"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H17=0,COUNTRY_INFO!$H17=4,COUNTRY_INFO!$H17=99),OR(COUNTRY_INFO!$J17=0,COUNTRY_INFO!$J17=4)),0,COUNTRY_INFO!$E17))","v":192148},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H17=0,COUNTRY_INFO!$H17=4,COUNTRY_INFO!$H17=99),OR(COUNTRY_INFO!$J17=0,COUNTRY_INFO!$J17=4)),0,COUNTRY_INFO!$F17))","v":541508},733656,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P17)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R17)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G17=1,DEC!I17,0),IF($G17=1,IVM!G17,0))","v":0},null,{"$f":"IF($J17=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H17<>0, IF($I17=0, $D17*$H17, $D17*($H17-$G17)), 0), $D17*$H17), 0)","v":0},0,null,0,{"$f":"IF($J17=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H17<>0, IF($I17=0, $D17*$H17, $D17*($H17-$G17)), 0), $D17*$H17), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A18=0,\" \",COUNTRY_INFO!A18))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B18=0,\" \",COUNTRY_INFO!B18))","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C18=0,\" \",COUNTRY_INFO!C18))","v":"Bindura"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H18=0,COUNTRY_INFO!$H18=4,COUNTRY_INFO!$H18=99),OR(COUNTRY_INFO!$J18=0,COUNTRY_INFO!$J18=4)),0,COUNTRY_INFO!$E18))","v":20298},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H18=0,COUNTRY_INFO!$H18=4,COUNTRY_INFO!$H18=99),OR(COUNTRY_INFO!$J18=0,COUNTRY_INFO!$J18=4)),0,COUNTRY_INFO!$F18))","v":57203},77501,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P18)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R18)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G18=1,DEC!I18,0),IF($G18=1,IVM!G18,0))","v":0},null,{"$f":"IF($J18=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H18<>0, IF($I18=0, $D18*$H18, $D18*($H18-$G18)), 0), $D18*$H18), 0)","v":0},0,null,0,{"$f":"IF($J18=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H18<>0, IF($I18=0, $D18*$H18, $D18*($H18-$G18)), 0), $D18*$H18), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A19=0,\" \",COUNTRY_INFO!A19))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B19=0,\" \",COUNTRY_INFO!B19))","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C19=0,\" \",COUNTRY_INFO!C19))","v":"Centenary"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H19=0,COUNTRY_INFO!$H19=4,COUNTRY_INFO!$H19=99),OR(COUNTRY_INFO!$J19=0,COUNTRY_INFO!$J19=4)),0,COUNTRY_INFO!$E19))","v":14757},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H19=0,COUNTRY_INFO!$H19=4,COUNTRY_INFO!$H19=99),OR(COUNTRY_INFO!$J19=0,COUNTRY_INFO!$J19=4)),0,COUNTRY_INFO!$F19))","v":41588},56345,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P19)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R19)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G19=1,DEC!I19,0),IF($G19=1,IVM!G19,0))","v":131472},null,{"$f":"IF($J19=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H19<>0, IF($I19=0, $D19*$H19, $D19*($H19-$G19)), 0), $D19*$H19), 0)","v":0},0,null,0,{"$f":"IF($J19=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H19<>0, IF($I19=0, $D19*$H19, $D19*($H19-$G19)), 0), $D19*$H19), 0)","v":0},0,null,0,null,131472,658,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A20=0,\" \",COUNTRY_INFO!A20))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B20=0,\" \",COUNTRY_INFO!B20))","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C20=0,\" \",COUNTRY_INFO!C20))","v":"Guruve"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H20=0,COUNTRY_INFO!$H20=4,COUNTRY_INFO!$H20=99),OR(COUNTRY_INFO!$J20=0,COUNTRY_INFO!$J20=4)),0,COUNTRY_INFO!$E20))","v":14907},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H20=0,COUNTRY_INFO!$H20=4,COUNTRY_INFO!$H20=99),OR(COUNTRY_INFO!$J20=0,COUNTRY_INFO!$J20=4)),0,COUNTRY_INFO!$F20))","v":42011},56918,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P20)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R20)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G20=1,DEC!I20,0),IF($G20=1,IVM!G20,0))","v":0},null,{"$f":"IF($J20=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H20<>0, IF($I20=0, $D20*$H20, $D20*($H20-$G20)), 0), $D20*$H20), 0)","v":0},0,null,0,{"$f":"IF($J20=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H20<>0, IF($I20=0, $D20*$H20, $D20*($H20-$G20)), 0), $D20*$H20), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A21=0,\" \",COUNTRY_INFO!A21))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B21=0,\" \",COUNTRY_INFO!B21))","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C21=0,\" \",COUNTRY_INFO!C21))","v":"Mazowe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H21=0,COUNTRY_INFO!$H21=4,COUNTRY_INFO!$H21=99),OR(COUNTRY_INFO!$J21=0,COUNTRY_INFO!$J21=4)),0,COUNTRY_INFO!$E21))","v":29324},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H21=0,COUNTRY_INFO!$H21=4,COUNTRY_INFO!$H21=99),OR(COUNTRY_INFO!$J21=0,COUNTRY_INFO!$J21=4)),0,COUNTRY_INFO!$F21))","v":82640},111964,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P21)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R21)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G21=1,DEC!I21,0),IF($G21=1,IVM!G21,0))","v":0},null,{"$f":"IF($J21=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H21<>0, IF($I21=0, $D21*$H21, $D21*($H21-$G21)), 0), $D21*$H21), 0)","v":0},0,null,0,{"$f":"IF($J21=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H21<>0, IF($I21=0, $D21*$H21, $D21*($H21-$G21)), 0), $D21*$H21), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A22=0,\" \",COUNTRY_INFO!A22))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B22=0,\" \",COUNTRY_INFO!B22))","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C22=0,\" \",COUNTRY_INFO!C22))","v":"Mt Darwin"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H22=0,COUNTRY_INFO!$H22=4,COUNTRY_INFO!$H22=99),OR(COUNTRY_INFO!$J22=0,COUNTRY_INFO!$J22=4)),0,COUNTRY_INFO!$E22))","v":25565},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H22=0,COUNTRY_INFO!$H22=4,COUNTRY_INFO!$H22=99),OR(COUNTRY_INFO!$J22=0,COUNTRY_INFO!$J22=4)),0,COUNTRY_INFO!$F22))","v":72048},97613,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P22)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R22)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G22=1,DEC!I22,0),IF($G22=1,IVM!G22,0))","v":0},null,{"$f":"IF($J22=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H22<>0, IF($I22=0, $D22*$H22, $D22*($H22-$G22)), 0), $D22*$H22), 0)","v":0},0,null,0,{"$f":"IF($J22=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H22<>0, IF($I22=0, $D22*$H22, $D22*($H22-$G22)), 0), $D22*$H22), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A23=0,\" \",COUNTRY_INFO!A23))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B23=0,\" \",COUNTRY_INFO!B23))","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C23=0,\" \",COUNTRY_INFO!C23))","v":"Rushinga"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H23=0,COUNTRY_INFO!$H23=4,COUNTRY_INFO!$H23=99),OR(COUNTRY_INFO!$J23=0,COUNTRY_INFO!$J23=4)),0,COUNTRY_INFO!$E23))","v":8898},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H23=0,COUNTRY_INFO!$H23=4,COUNTRY_INFO!$H23=99),OR(COUNTRY_INFO!$J23=0,COUNTRY_INFO!$J23=4)),0,COUNTRY_INFO!$F23))","v":25077},33975,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P23)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R23)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G23=1,DEC!I23,0),IF($G23=1,IVM!G23,0))","v":0},null,{"$f":"IF($J23=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H23<>0, IF($I23=0, $D23*$H23, $D23*($H23-$G23)), 0), $D23*$H23), 0)","v":0},0,null,0,{"$f":"IF($J23=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H23<>0, IF($I23=0, $D23*$H23, $D23*($H23-$G23)), 0), $D23*$H23), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A24=0,\" \",COUNTRY_INFO!A24))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B24=0,\" \",COUNTRY_INFO!B24))","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C24=0,\" \",COUNTRY_INFO!C24))","v":"Shamva"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H24=0,COUNTRY_INFO!$H24=4,COUNTRY_INFO!$H24=99),OR(COUNTRY_INFO!$J24=0,COUNTRY_INFO!$J24=4)),0,COUNTRY_INFO!$E24))","v":14860},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H24=0,COUNTRY_INFO!$H24=4,COUNTRY_INFO!$H24=99),OR(COUNTRY_INFO!$J24=0,COUNTRY_INFO!$J24=4)),0,COUNTRY_INFO!$F24))","v":41879},56739,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P24)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R24)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G24=1,DEC!I24,0),IF($G24=1,IVM!G24,0))","v":132392},null,{"$f":"IF($J24=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H24<>0, IF($I24=0, $D24*$H24, $D24*($H24-$G24)), 0), $D24*$H24), 0)","v":0},0,null,0,{"$f":"IF($J24=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H24<>0, IF($I24=0, $D24*$H24, $D24*($H24-$G24)), 0), $D24*$H24), 0)","v":0},0,null,0,null,132392,662,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A25=0,\" \",COUNTRY_INFO!A25))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B25=0,\" \",COUNTRY_INFO!B25))","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C25=0,\" \",COUNTRY_INFO!C25))","v":"Mbire"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H25=0,COUNTRY_INFO!$H25=4,COUNTRY_INFO!$H25=99),OR(COUNTRY_INFO!$J25=0,COUNTRY_INFO!$J25=4)),0,COUNTRY_INFO!$E25))","v":9900},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H25=0,COUNTRY_INFO!$H25=4,COUNTRY_INFO!$H25=99),OR(COUNTRY_INFO!$J25=0,COUNTRY_INFO!$J25=4)),0,COUNTRY_INFO!$F25))","v":27901},37801,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P25)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R25)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G25=1,DEC!I25,0),IF($G25=1,IVM!G25,0))","v":0},null,{"$f":"IF($J25=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H25<>0, IF($I25=0, $D25*$H25, $D25*($H25-$G25)), 0), $D25*$H25), 0)","v":0},0,null,0,{"$f":"IF($J25=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H25<>0, IF($I25=0, $D25*$H25, $D25*($H25-$G25)), 0), $D25*$H25), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A26=0,\" \",COUNTRY_INFO!A26))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B26=0,\" \",COUNTRY_INFO!B26))","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C26=0,\" \",COUNTRY_INFO!C26))","v":"Chikomba"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H26=0,COUNTRY_INFO!$H26=4,COUNTRY_INFO!$H26=99),OR(COUNTRY_INFO!$J26=0,COUNTRY_INFO!$J26=4)),0,COUNTRY_INFO!$E26))","v":14540},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H26=0,COUNTRY_INFO!$H26=4,COUNTRY_INFO!$H26=99),OR(COUNTRY_INFO!$J26=0,COUNTRY_INFO!$J26=4)),0,COUNTRY_INFO!$F26))","v":40977},55517,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P26)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R26)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G26=1,DEC!I26,0),IF($G26=1,IVM!G26,0))","v":129539},null,{"$f":"IF($J26=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H26<>0, IF($I26=0, $D26*$H26, $D26*($H26-$G26)), 0), $D26*$H26), 0)","v":0},0,null,0,{"$f":"IF($J26=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H26<>0, IF($I26=0, $D26*$H26, $D26*($H26-$G26)), 0), $D26*$H26), 0)","v":0},0,null,0,null,129539,648,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A27=0,\" \",COUNTRY_INFO!A27))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B27=0,\" \",COUNTRY_INFO!B27))","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C27=0,\" \",COUNTRY_INFO!C27))","v":"Goromonzi"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H27=0,COUNTRY_INFO!$H27=4,COUNTRY_INFO!$H27=99),OR(COUNTRY_INFO!$J27=0,COUNTRY_INFO!$J27=4)),0,COUNTRY_INFO!$E27))","v":27039},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H27=0,COUNTRY_INFO!$H27=4,COUNTRY_INFO!$H27=99),OR(COUNTRY_INFO!$J27=0,COUNTRY_INFO!$J27=4)),0,COUNTRY_INFO!$F27))","v":76201},103240,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P27)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R27)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G27=1,DEC!I27,0),IF($G27=1,IVM!G27,0))","v":240893},null,{"$f":"IF($J27=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H27<>0, IF($I27=0, $D27*$H27, $D27*($H27-$G27)), 0), $D27*$H27), 0)","v":0},0,null,0,{"$f":"IF($J27=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H27<>0, IF($I27=0, $D27*$H27, $D27*($H27-$G27)), 0), $D27*$H27), 0)","v":0},0,null,0,null,240893,1205,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A28=0,\" \",COUNTRY_INFO!A28))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B28=0,\" \",COUNTRY_INFO!B28))","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C28=0,\" \",COUNTRY_INFO!C28))","v":"UMP"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H28=0,COUNTRY_INFO!$H28=4,COUNTRY_INFO!$H28=99),OR(COUNTRY_INFO!$J28=0,COUNTRY_INFO!$J28=4)),0,COUNTRY_INFO!$E28))","v":13534},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H28=0,COUNTRY_INFO!$H28=4,COUNTRY_INFO!$H28=99),OR(COUNTRY_INFO!$J28=0,COUNTRY_INFO!$J28=4)),0,COUNTRY_INFO!$F28))","v":38140},51674,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P28)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R28)","v":1},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G28=1,DEC!I28,0),IF($G28=1,IVM!G28,0))","v":120572},null,{"$f":"IF($J28=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H28<>0, IF($I28=0, $D28*$H28, $D28*($H28-$G28)), 0), $D28*$H28), 0)","v":0},0,null,0,{"$f":"IF($J28=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H28<>0, IF($I28=0, $D28*$H28, $D28*($H28-$G28)), 0), $D28*$H28), 0)","v":0},0,null,0,null,120572,603,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A29=0,\" \",COUNTRY_INFO!A29))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B29=0,\" \",COUNTRY_INFO!B29))","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C29=0,\" \",COUNTRY_INFO!C29))","v":"Hwedza"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H29=0,COUNTRY_INFO!$H29=4,COUNTRY_INFO!$H29=99),OR(COUNTRY_INFO!$J29=0,COUNTRY_INFO!$J29=4)),0,COUNTRY_INFO!$E29))","v":8529},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H29=0,COUNTRY_INFO!$H29=4,COUNTRY_INFO!$H29=99),OR(COUNTRY_INFO!$J29=0,COUNTRY_INFO!$J29=4)),0,COUNTRY_INFO!$F29))","v":24036},32565,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P29)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R29)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G29=1,DEC!I29,0),IF($G29=1,IVM!G29,0))","v":75986},null,{"$f":"IF($J29=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H29<>0, IF($I29=0, $D29*$H29, $D29*($H29-$G29)), 0), $D29*$H29), 0)","v":0},0,null,0,{"$f":"IF($J29=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H29<>0, IF($I29=0, $D29*$H29, $D29*($H29-$G29)), 0), $D29*$H29), 0)","v":0},0,null,0,null,75986,380,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A30=0,\" \",COUNTRY_INFO!A30))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B30=0,\" \",COUNTRY_INFO!B30))","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C30=0,\" \",COUNTRY_INFO!C30))","v":"Marondera"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H30=0,COUNTRY_INFO!$H30=4,COUNTRY_INFO!$H30=99),OR(COUNTRY_INFO!$J30=0,COUNTRY_INFO!$J30=4)),0,COUNTRY_INFO!$E30))","v":21510},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H30=0,COUNTRY_INFO!$H30=4,COUNTRY_INFO!$H30=99),OR(COUNTRY_INFO!$J30=0,COUNTRY_INFO!$J30=4)),0,COUNTRY_INFO!$F30))","v":60620},82130,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P30)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R30)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G30=1,DEC!I30,0),IF($G30=1,IVM!G30,0))","v":191637},null,{"$f":"IF($J30=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H30<>0, IF($I30=0, $D30*$H30, $D30*($H30-$G30)), 0), $D30*$H30), 0)","v":0},0,null,0,{"$f":"IF($J30=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H30<>0, IF($I30=0, $D30*$H30, $D30*($H30-$G30)), 0), $D30*$H30), 0)","v":0},0,null,0,null,191637,959,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A31=0,\" \",COUNTRY_INFO!A31))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B31=0,\" \",COUNTRY_INFO!B31))","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C31=0,\" \",COUNTRY_INFO!C31))","v":"Mudzi"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H31=0,COUNTRY_INFO!$H31=4,COUNTRY_INFO!$H31=99),OR(COUNTRY_INFO!$J31=0,COUNTRY_INFO!$J31=4)),0,COUNTRY_INFO!$E31))","v":16014},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H31=0,COUNTRY_INFO!$H31=4,COUNTRY_INFO!$H31=99),OR(COUNTRY_INFO!$J31=0,COUNTRY_INFO!$J31=4)),0,COUNTRY_INFO!$F31))","v":45131},61145,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P31)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R31)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G31=1,DEC!I31,0),IF($G31=1,IVM!G31,0))","v":142673},null,{"$f":"IF($J31=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H31<>0, IF($I31=0, $D31*$H31, $D31*($H31-$G31)), 0), $D31*$H31), 0)","v":0},0,null,0,{"$f":"IF($J31=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H31<>0, IF($I31=0, $D31*$H31, $D31*($H31-$G31)), 0), $D31*$H31), 0)","v":0},0,null,0,null,142673,714,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A32=0,\" \",COUNTRY_INFO!A32))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B32=0,\" \",COUNTRY_INFO!B32))","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C32=0,\" \",COUNTRY_INFO!C32))","v":"Murewa"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H32=0,COUNTRY_INFO!$H32=4,COUNTRY_INFO!$H32=99),OR(COUNTRY_INFO!$J32=0,COUNTRY_INFO!$J32=4)),0,COUNTRY_INFO!$E32))","v":23989},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H32=0,COUNTRY_INFO!$H32=4,COUNTRY_INFO!$H32=99),OR(COUNTRY_INFO!$J32=0,COUNTRY_INFO!$J32=4)),0,COUNTRY_INFO!$F32))","v":67605},91594,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P32)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R32)","v":1},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G32=1,DEC!I32,0),IF($G32=1,IVM!G32,0))","v":213719},null,{"$f":"IF($J32=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H32<>0, IF($I32=0, $D32*$H32, $D32*($H32-$G32)), 0), $D32*$H32), 0)","v":0},0,null,0,{"$f":"IF($J32=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H32<>0, IF($I32=0, $D32*$H32, $D32*($H32-$G32)), 0), $D32*$H32), 0)","v":0},0,null,0,null,213719,1069,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A33=0,\" \",COUNTRY_INFO!A33))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B33=0,\" \",COUNTRY_INFO!B33))","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C33=0,\" \",COUNTRY_INFO!C33))","v":"Mutoko"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H33=0,COUNTRY_INFO!$H33=4,COUNTRY_INFO!$H33=99),OR(COUNTRY_INFO!$J33=0,COUNTRY_INFO!$J33=4)),0,COUNTRY_INFO!$E33))","v":17562},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H33=0,COUNTRY_INFO!$H33=4,COUNTRY_INFO!$H33=99),OR(COUNTRY_INFO!$J33=0,COUNTRY_INFO!$J33=4)),0,COUNTRY_INFO!$F33))","v":49492},67054,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P33)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R33)","v":1},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G33=1,DEC!I33,0),IF($G33=1,IVM!G33,0))","v":156459},null,{"$f":"IF($J33=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H33<>0, IF($I33=0, $D33*$H33, $D33*($H33-$G33)), 0), $D33*$H33), 0)","v":0},0,null,0,{"$f":"IF($J33=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H33<>0, IF($I33=0, $D33*$H33, $D33*($H33-$G33)), 0), $D33*$H33), 0)","v":0},0,null,0,null,156459,783,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A34=0,\" \",COUNTRY_INFO!A34))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B34=0,\" \",COUNTRY_INFO!B34))","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C34=0,\" \",COUNTRY_INFO!C34))","v":"Seke"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H34=0,COUNTRY_INFO!$H34=4,COUNTRY_INFO!$H34=99),OR(COUNTRY_INFO!$J34=0,COUNTRY_INFO!$J34=4)),0,COUNTRY_INFO!$E34))","v":39046},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H34=0,COUNTRY_INFO!$H34=4,COUNTRY_INFO!$H34=99),OR(COUNTRY_INFO!$J34=0,COUNTRY_INFO!$J34=4)),0,COUNTRY_INFO!$F34))","v":110039},149085,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P34)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R34)","v":1},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G34=1,DEC!I34,0),IF($G34=1,IVM!G34,0))","v":347865},null,{"$f":"IF($J34=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H34<>0, IF($I34=0, $D34*$H34, $D34*($H34-$G34)), 0), $D34*$H34), 0)","v":0},0,null,0,{"$f":"IF($J34=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H34<>0, IF($I34=0, $D34*$H34, $D34*($H34-$G34)), 0), $D34*$H34), 0)","v":0},0,null,0,null,347865,1740,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A35=0,\" \",COUNTRY_INFO!A35))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B35=0,\" \",COUNTRY_INFO!B35))","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C35=0,\" \",COUNTRY_INFO!C35))","v":"Chegutu"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H35=0,COUNTRY_INFO!$H35=4,COUNTRY_INFO!$H35=99),OR(COUNTRY_INFO!$J35=0,COUNTRY_INFO!$J35=4)),0,COUNTRY_INFO!$E35))","v":32669},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H35=0,COUNTRY_INFO!$H35=4,COUNTRY_INFO!$H35=99),OR(COUNTRY_INFO!$J35=0,COUNTRY_INFO!$J35=4)),0,COUNTRY_INFO!$F35))","v":92068},124737,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P35)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R35)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G35=1,DEC!I35,0),IF($G35=1,IVM!G35,0))","v":291054},null,{"$f":"IF($J35=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H35<>0, IF($I35=0, $D35*$H35, $D35*($H35-$G35)), 0), $D35*$H35), 0)","v":0},0,null,0,{"$f":"IF($J35=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H35<>0, IF($I35=0, $D35*$H35, $D35*($H35-$G35)), 0), $D35*$H35), 0)","v":0},0,null,0,null,291054,1456,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A36=0,\" \",COUNTRY_INFO!A36))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B36=0,\" \",COUNTRY_INFO!B36))","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C36=0,\" \",COUNTRY_INFO!C36))","v":"Hurungwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H36=0,COUNTRY_INFO!$H36=4,COUNTRY_INFO!$H36=99),OR(COUNTRY_INFO!$J36=0,COUNTRY_INFO!$J36=4)),0,COUNTRY_INFO!$E36))","v":43001},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H36=0,COUNTRY_INFO!$H36=4,COUNTRY_INFO!$H36=99),OR(COUNTRY_INFO!$J36=0,COUNTRY_INFO!$J36=4)),0,COUNTRY_INFO!$F36))","v":121184},164185,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P36)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R36)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G36=1,DEC!I36,0),IF($G36=1,IVM!G36,0))","v":383099},null,{"$f":"IF($J36=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H36<>0, IF($I36=0, $D36*$H36, $D36*($H36-$G36)), 0), $D36*$H36), 0)","v":0},0,null,0,{"$f":"IF($J36=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H36<>0, IF($I36=0, $D36*$H36, $D36*($H36-$G36)), 0), $D36*$H36), 0)","v":0},0,null,0,null,383099,1916,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A37=0,\" \",COUNTRY_INFO!A37))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B37=0,\" \",COUNTRY_INFO!B37))","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C37=0,\" \",COUNTRY_INFO!C37))","v":"Sanyati"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H37=0,COUNTRY_INFO!$H37=4,COUNTRY_INFO!$H37=99),OR(COUNTRY_INFO!$J37=0,COUNTRY_INFO!$J37=4)),0,COUNTRY_INFO!$E37))","v":24681},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H37=0,COUNTRY_INFO!$H37=4,COUNTRY_INFO!$H37=99),OR(COUNTRY_INFO!$J37=0,COUNTRY_INFO!$J37=4)),0,COUNTRY_INFO!$F37))","v":69556},94237,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P37)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R37)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G37=1,DEC!I37,0),IF($G37=1,IVM!G37,0))","v":219886},null,{"$f":"IF($J37=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H37<>0, IF($I37=0, $D37*$H37, $D37*($H37-$G37)), 0), $D37*$H37), 0)","v":0},0,null,0,{"$f":"IF($J37=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H37<>0, IF($I37=0, $D37*$H37, $D37*($H37-$G37)), 0), $D37*$H37), 0)","v":0},0,null,0,null,219886,1100,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A38=0,\" \",COUNTRY_INFO!A38))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B38=0,\" \",COUNTRY_INFO!B38))","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C38=0,\" \",COUNTRY_INFO!C38))","v":"Kariba"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H38=0,COUNTRY_INFO!$H38=4,COUNTRY_INFO!$H38=99),OR(COUNTRY_INFO!$J38=0,COUNTRY_INFO!$J38=4)),0,COUNTRY_INFO!$E38))","v":8151},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H38=0,COUNTRY_INFO!$H38=4,COUNTRY_INFO!$H38=99),OR(COUNTRY_INFO!$J38=0,COUNTRY_INFO!$J38=4)),0,COUNTRY_INFO!$F38))","v":22970},31121,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P38)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R38)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G38=1,DEC!I38,0),IF($G38=1,IVM!G38,0))","v":72615},null,{"$f":"IF($J38=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H38<>0, IF($I38=0, $D38*$H38, $D38*($H38-$G38)), 0), $D38*$H38), 0)","v":0},0,null,0,{"$f":"IF($J38=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H38<>0, IF($I38=0, $D38*$H38, $D38*($H38-$G38)), 0), $D38*$H38), 0)","v":0},0,null,0,null,72615,364,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A39=0,\" \",COUNTRY_INFO!A39))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B39=0,\" \",COUNTRY_INFO!B39))","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C39=0,\" \",COUNTRY_INFO!C39))","v":"Makonde"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H39=0,COUNTRY_INFO!$H39=4,COUNTRY_INFO!$H39=99),OR(COUNTRY_INFO!$J39=0,COUNTRY_INFO!$J39=4)),0,COUNTRY_INFO!$E39))","v":27818},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H39=0,COUNTRY_INFO!$H39=4,COUNTRY_INFO!$H39=99),OR(COUNTRY_INFO!$J39=0,COUNTRY_INFO!$J39=4)),0,COUNTRY_INFO!$F39))","v":78396},106214,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P39)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R39)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G39=1,DEC!I39,0),IF($G39=1,IVM!G39,0))","v":247833},null,{"$f":"IF($J39=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H39<>0, IF($I39=0, $D39*$H39, $D39*($H39-$G39)), 0), $D39*$H39), 0)","v":0},0,null,0,{"$f":"IF($J39=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H39<>0, IF($I39=0, $D39*$H39, $D39*($H39-$G39)), 0), $D39*$H39), 0)","v":0},0,null,0,null,247833,1240,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A40=0,\" \",COUNTRY_INFO!A40))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B40=0,\" \",COUNTRY_INFO!B40))","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C40=0,\" \",COUNTRY_INFO!C40))","v":"Mhondoro-Ngezi"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H40=0,COUNTRY_INFO!$H40=4,COUNTRY_INFO!$H40=99),OR(COUNTRY_INFO!$J40=0,COUNTRY_INFO!$J40=4)),0,COUNTRY_INFO!$E40))","v":12540},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H40=0,COUNTRY_INFO!$H40=4,COUNTRY_INFO!$H40=99),OR(COUNTRY_INFO!$J40=0,COUNTRY_INFO!$J40=4)),0,COUNTRY_INFO!$F40))","v":35339},47879,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P40)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R40)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G40=1,DEC!I40,0),IF($G40=1,IVM!G40,0))","v":111718},null,{"$f":"IF($J40=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H40<>0, IF($I40=0, $D40*$H40, $D40*($H40-$G40)), 0), $D40*$H40), 0)","v":0},0,null,0,{"$f":"IF($J40=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H40<>0, IF($I40=0, $D40*$H40, $D40*($H40-$G40)), 0), $D40*$H40), 0)","v":0},0,null,0,null,111718,559,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A41=0,\" \",COUNTRY_INFO!A41))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B41=0,\" \",COUNTRY_INFO!B41))","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C41=0,\" \",COUNTRY_INFO!C41))","v":"Zvimba"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H41=0,COUNTRY_INFO!$H41=4,COUNTRY_INFO!$H41=99),OR(COUNTRY_INFO!$J41=0,COUNTRY_INFO!$J41=4)),0,COUNTRY_INFO!$E41))","v":31610},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H41=0,COUNTRY_INFO!$H41=4,COUNTRY_INFO!$H41=99),OR(COUNTRY_INFO!$J41=0,COUNTRY_INFO!$J41=4)),0,COUNTRY_INFO!$F41))","v":89083},{"$f":"SUM(D41:E41)","v":120693},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P41)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R41)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G41=1,DEC!I41,0),IF($G41=1,IVM!G41,0))","v":281616},null,{"$f":"IF($J41=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H41<>0, IF($I41=0, $D41*$H41, $D41*($H41-$G41)), 0), $D41*$H41), 0)","v":0},{"$f":"IF($J41=\"ALB\", IF($H41<>0, IF($I41=0, $E41*$H41, $E41*($H41-$G41)),0), 0)","v":0},null,{"$f":"SUM(K41:M41)","v":0},{"$f":"IF($J41=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H41<>0, IF($I41=0, $D41*$H41, $D41*($H41-$G41)), 0), $D41*$H41), 0)","v":0},{"$f":"IF($J41=\"MBD\", IF($H41<>0,IF($I41=0, $E41*$H41, $E41*($H41-$G41)),0), 0 )","v":0},null,{"$f":"SUM(O41:Q41)","v":0},null,{"$f":"IF($I41>$S41, $I41-$S41,0)","v":281616},{"$f":"ROUNDUP($I41/200,0)","v":1409},null,{"$f":"IF($L41>$V41,$L41-$V41,0)","v":0},{"$f":"ROUNDUP($L41/200,0)","v":0},null,{"$f":"IF($P41>$Y41,$P41-$Y41,0)","v":0},{"$f":"ROUNDUP($P41/150,0)","v":0}]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A42=0,\" \",COUNTRY_INFO!A42))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B42=0,\" \",COUNTRY_INFO!B42))","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C42=0,\" \",COUNTRY_INFO!C42))","v":"Binga"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H42=0,COUNTRY_INFO!$H42=4,COUNTRY_INFO!$H42=99),OR(COUNTRY_INFO!$J42=0,COUNTRY_INFO!$J42=4)),0,COUNTRY_INFO!$E42))","v":16716},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H42=0,COUNTRY_INFO!$H42=4,COUNTRY_INFO!$H42=99),OR(COUNTRY_INFO!$J42=0,COUNTRY_INFO!$J42=4)),0,COUNTRY_INFO!$F42))","v":47109},63825,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P42)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R42)","v":1},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G42=1,DEC!I42,0),IF($G42=1,IVM!G42,0))","v":148925},null,{"$f":"IF($J42=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H42<>0, IF($I42=0, $D42*$H42, $D42*($H42-$G42)), 0), $D42*$H42), 0)","v":0},0,null,0,{"$f":"IF($J42=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H42<>0, IF($I42=0, $D42*$H42, $D42*($H42-$G42)), 0), $D42*$H42), 0)","v":0},0,null,0,null,148925,745,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A43=0,\" \",COUNTRY_INFO!A43))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B43=0,\" \",COUNTRY_INFO!B43))","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C43=0,\" \",COUNTRY_INFO!C43))","v":"Bubi"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H43=0,COUNTRY_INFO!$H43=4,COUNTRY_INFO!$H43=99),OR(COUNTRY_INFO!$J43=0,COUNTRY_INFO!$J43=4)),0,COUNTRY_INFO!$E43))","v":7437},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H43=0,COUNTRY_INFO!$H43=4,COUNTRY_INFO!$H43=99),OR(COUNTRY_INFO!$J43=0,COUNTRY_INFO!$J43=4)),0,COUNTRY_INFO!$F43))","v":20959},28396,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P43)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R43)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G43=1,DEC!I43,0),IF($G43=1,IVM!G43,0))","v":66257},null,{"$f":"IF($J43=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H43<>0, IF($I43=0, $D43*$H43, $D43*($H43-$G43)), 0), $D43*$H43), 0)","v":0},0,null,0,{"$f":"IF($J43=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H43<>0, IF($I43=0, $D43*$H43, $D43*($H43-$G43)), 0), $D43*$H43), 0)","v":0},0,null,0,null,66257,332,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A44=0,\" \",COUNTRY_INFO!A44))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B44=0,\" \",COUNTRY_INFO!B44))","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C44=0,\" \",COUNTRY_INFO!C44))","v":"Hwange"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H44=0,COUNTRY_INFO!$H44=4,COUNTRY_INFO!$H44=99),OR(COUNTRY_INFO!$J44=0,COUNTRY_INFO!$J44=4)),0,COUNTRY_INFO!$E44))","v":16097},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H44=0,COUNTRY_INFO!$H44=4,COUNTRY_INFO!$H44=99),OR(COUNTRY_INFO!$J44=0,COUNTRY_INFO!$J44=4)),0,COUNTRY_INFO!$F44))","v":45364},61461,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P44)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R44)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G44=1,DEC!I44,0),IF($G44=1,IVM!G44,0))","v":0},null,{"$f":"IF($J44=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H44<>0, IF($I44=0, $D44*$H44, $D44*($H44-$G44)), 0), $D44*$H44), 0)","v":0},0,null,0,{"$f":"IF($J44=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H44<>0, IF($I44=0, $D44*$H44, $D44*($H44-$G44)), 0), $D44*$H44), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A45=0,\" \",COUNTRY_INFO!A45))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B45=0,\" \",COUNTRY_INFO!B45))","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C45=0,\" \",COUNTRY_INFO!C45))","v":"Lupane"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H45=0,COUNTRY_INFO!$H45=4,COUNTRY_INFO!$H45=99),OR(COUNTRY_INFO!$J45=0,COUNTRY_INFO!$J45=4)),0,COUNTRY_INFO!$E45))","v":12037},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H45=0,COUNTRY_INFO!$H45=4,COUNTRY_INFO!$H45=99),OR(COUNTRY_INFO!$J45=0,COUNTRY_INFO!$J45=4)),0,COUNTRY_INFO!$F45))","v":33924},45961,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P45)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R45)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G45=1,DEC!I45,0),IF($G45=1,IVM!G45,0))","v":107242},null,{"$f":"IF($J45=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H45<>0, IF($I45=0, $D45*$H45, $D45*($H45-$G45)), 0), $D45*$H45), 0)","v":0},0,null,0,{"$f":"IF($J45=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H45<>0, IF($I45=0, $D45*$H45, $D45*($H45-$G45)), 0), $D45*$H45), 0)","v":0},0,null,0,null,107242,537,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A46=0,\" \",COUNTRY_INFO!A46))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B46=0,\" \",COUNTRY_INFO!B46))","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C46=0,\" \",COUNTRY_INFO!C46))","v":"Nkayi"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H46=0,COUNTRY_INFO!$H46=4,COUNTRY_INFO!$H46=99),OR(COUNTRY_INFO!$J46=0,COUNTRY_INFO!$J46=4)),0,COUNTRY_INFO!$E46))","v":13116},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H46=0,COUNTRY_INFO!$H46=4,COUNTRY_INFO!$H46=99),OR(COUNTRY_INFO!$J46=0,COUNTRY_INFO!$J46=4)),0,COUNTRY_INFO!$F46))","v":36963},50079,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P46)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R46)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G46=1,DEC!I46,0),IF($G46=1,IVM!G46,0))","v":116851},null,{"$f":"IF($J46=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H46<>0, IF($I46=0, $D46*$H46, $D46*($H46-$G46)), 0), $D46*$H46), 0)","v":0},0,null,0,{"$f":"IF($J46=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H46<>0, IF($I46=0, $D46*$H46, $D46*($H46-$G46)), 0), $D46*$H46), 0)","v":0},0,null,0,null,116851,585,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A47=0,\" \",COUNTRY_INFO!A47))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B47=0,\" \",COUNTRY_INFO!B47))","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C47=0,\" \",COUNTRY_INFO!C47))","v":"Tsholotsho"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H47=0,COUNTRY_INFO!$H47=4,COUNTRY_INFO!$H47=99),OR(COUNTRY_INFO!$J47=0,COUNTRY_INFO!$J47=4)),0,COUNTRY_INFO!$E47))","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H47=0,COUNTRY_INFO!$H47=4,COUNTRY_INFO!$H47=99),OR(COUNTRY_INFO!$J47=0,COUNTRY_INFO!$J47=4)),0,COUNTRY_INFO!$F47))","v":0},0,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P47)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R47)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G47=1,DEC!I47,0),IF($G47=1,IVM!G47,0))","v":0},null,{"$f":"IF($J47=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H47<>0, IF($I47=0, $D47*$H47, $D47*($H47-$G47)), 0), $D47*$H47), 0)","v":0},0,null,0,{"$f":"IF($J47=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H47<>0, IF($I47=0, $D47*$H47, $D47*($H47-$G47)), 0), $D47*$H47), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A48=0,\" \",COUNTRY_INFO!A48))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B48=0,\" \",COUNTRY_INFO!B48))","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C48=0,\" \",COUNTRY_INFO!C48))","v":"Umguza"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H48=0,COUNTRY_INFO!$H48=4,COUNTRY_INFO!$H48=99),OR(COUNTRY_INFO!$J48=0,COUNTRY_INFO!$J48=4)),0,COUNTRY_INFO!$E48))","v":10779},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H48=0,COUNTRY_INFO!$H48=4,COUNTRY_INFO!$H48=99),OR(COUNTRY_INFO!$J48=0,COUNTRY_INFO!$J48=4)),0,COUNTRY_INFO!$F48))","v":30376},41155,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P48)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R48)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G48=1,DEC!I48,0),IF($G48=1,IVM!G48,0))","v":96028},null,{"$f":"IF($J48=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H48<>0, IF($I48=0, $D48*$H48, $D48*($H48-$G48)), 0), $D48*$H48), 0)","v":0},0,null,0,{"$f":"IF($J48=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H48<>0, IF($I48=0, $D48*$H48, $D48*($H48-$G48)), 0), $D48*$H48), 0)","v":0},0,null,0,null,96028,481,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A49=0,\" \",COUNTRY_INFO!A49))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B49=0,\" \",COUNTRY_INFO!B49))","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C49=0,\" \",COUNTRY_INFO!C49))","v":"Beit Bridge"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H49=0,COUNTRY_INFO!$H49=4,COUNTRY_INFO!$H49=99),OR(COUNTRY_INFO!$J49=0,COUNTRY_INFO!$J49=4)),0,COUNTRY_INFO!$E49))","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H49=0,COUNTRY_INFO!$H49=4,COUNTRY_INFO!$H49=99),OR(COUNTRY_INFO!$J49=0,COUNTRY_INFO!$J49=4)),0,COUNTRY_INFO!$F49))","v":0},0,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P49)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R49)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G49=1,DEC!I49,0),IF($G49=1,IVM!G49,0))","v":0},null,{"$f":"IF($J49=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H49<>0, IF($I49=0, $D49*$H49, $D49*($H49-$G49)), 0), $D49*$H49), 0)","v":0},0,null,0,{"$f":"IF($J49=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H49<>0, IF($I49=0, $D49*$H49, $D49*($H49-$G49)), 0), $D49*$H49), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A50=0,\" \",COUNTRY_INFO!A50))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B50=0,\" \",COUNTRY_INFO!B50))","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C50=0,\" \",COUNTRY_INFO!C50))","v":"Bulilima"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H50=0,COUNTRY_INFO!$H50=4,COUNTRY_INFO!$H50=99),OR(COUNTRY_INFO!$J50=0,COUNTRY_INFO!$J50=4)),0,COUNTRY_INFO!$E50))","v":10884},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H50=0,COUNTRY_INFO!$H50=4,COUNTRY_INFO!$H50=99),OR(COUNTRY_INFO!$J50=0,COUNTRY_INFO!$J50=4)),0,COUNTRY_INFO!$F50))","v":30672},41556,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P50)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R50)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G50=1,DEC!I50,0),IF($G50=1,IVM!G50,0))","v":96964},null,{"$f":"IF($J50=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H50<>0, IF($I50=0, $D50*$H50, $D50*($H50-$G50)), 0), $D50*$H50), 0)","v":0},0,null,0,{"$f":"IF($J50=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H50<>0, IF($I50=0, $D50*$H50, $D50*($H50-$G50)), 0), $D50*$H50), 0)","v":0},0,null,0,null,96964,485,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A51=0,\" \",COUNTRY_INFO!A51))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B51=0,\" \",COUNTRY_INFO!B51))","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C51=0,\" \",COUNTRY_INFO!C51))","v":"Gwanda"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H51=0,COUNTRY_INFO!$H51=4,COUNTRY_INFO!$H51=99),OR(COUNTRY_INFO!$J51=0,COUNTRY_INFO!$J51=4)),0,COUNTRY_INFO!$E51))","v":16345},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H51=0,COUNTRY_INFO!$H51=4,COUNTRY_INFO!$H51=99),OR(COUNTRY_INFO!$J51=0,COUNTRY_INFO!$J51=4)),0,COUNTRY_INFO!$F51))","v":46064},62409,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P51)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R51)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G51=1,DEC!I51,0),IF($G51=1,IVM!G51,0))","v":145621},null,{"$f":"IF($J51=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H51<>0, IF($I51=0, $D51*$H51, $D51*($H51-$G51)), 0), $D51*$H51), 0)","v":0},0,null,0,{"$f":"IF($J51=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H51<>0, IF($I51=0, $D51*$H51, $D51*($H51-$G51)), 0), $D51*$H51), 0)","v":0},0,null,0,null,145621,729,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A52=0,\" \",COUNTRY_INFO!A52))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B52=0,\" \",COUNTRY_INFO!B52))","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C52=0,\" \",COUNTRY_INFO!C52))","v":"Insiza"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H52=0,COUNTRY_INFO!$H52=4,COUNTRY_INFO!$H52=99),OR(COUNTRY_INFO!$J52=0,COUNTRY_INFO!$J52=4)),0,COUNTRY_INFO!$E52))","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H52=0,COUNTRY_INFO!$H52=4,COUNTRY_INFO!$H52=99),OR(COUNTRY_INFO!$J52=0,COUNTRY_INFO!$J52=4)),0,COUNTRY_INFO!$F52))","v":0},0,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P52)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R52)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G52=1,DEC!I52,0),IF($G52=1,IVM!G52,0))","v":0},null,{"$f":"IF($J52=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H52<>0, IF($I52=0, $D52*$H52, $D52*($H52-$G52)), 0), $D52*$H52), 0)","v":0},0,null,0,{"$f":"IF($J52=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H52<>0, IF($I52=0, $D52*$H52, $D52*($H52-$G52)), 0), $D52*$H52), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A53=0,\" \",COUNTRY_INFO!A53))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B53=0,\" \",COUNTRY_INFO!B53))","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C53=0,\" \",COUNTRY_INFO!C53))","v":"Mangwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H53=0,COUNTRY_INFO!$H53=4,COUNTRY_INFO!$H53=99),OR(COUNTRY_INFO!$J53=0,COUNTRY_INFO!$J53=4)),0,COUNTRY_INFO!$E53))","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H53=0,COUNTRY_INFO!$H53=4,COUNTRY_INFO!$H53=99),OR(COUNTRY_INFO!$J53=0,COUNTRY_INFO!$J53=4)),0,COUNTRY_INFO!$F53))","v":0},0,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P53)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R53)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G53=1,DEC!I53,0),IF($G53=1,IVM!G53,0))","v":0},null,{"$f":"IF($J53=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H53<>0, IF($I53=0, $D53*$H53, $D53*($H53-$G53)), 0), $D53*$H53), 0)","v":0},0,null,0,{"$f":"IF($J53=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H53<>0, IF($I53=0, $D53*$H53, $D53*($H53-$G53)), 0), $D53*$H53), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A54=0,\" \",COUNTRY_INFO!A54))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B54=0,\" \",COUNTRY_INFO!B54))","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C54=0,\" \",COUNTRY_INFO!C54))","v":"Matobo"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H54=0,COUNTRY_INFO!$H54=4,COUNTRY_INFO!$H54=99),OR(COUNTRY_INFO!$J54=0,COUNTRY_INFO!$J54=4)),0,COUNTRY_INFO!$E54))","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H54=0,COUNTRY_INFO!$H54=4,COUNTRY_INFO!$H54=99),OR(COUNTRY_INFO!$J54=0,COUNTRY_INFO!$J54=4)),0,COUNTRY_INFO!$F54))","v":0},0,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P54)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R54)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G54=1,DEC!I54,0),IF($G54=1,IVM!G54,0))","v":0},null,{"$f":"IF($J54=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H54<>0, IF($I54=0, $D54*$H54, $D54*($H54-$G54)), 0), $D54*$H54), 0)","v":0},0,null,0,{"$f":"IF($J54=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H54<>0, IF($I54=0, $D54*$H54, $D54*($H54-$G54)), 0), $D54*$H54), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A55=0,\" \",COUNTRY_INFO!A55))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B55=0,\" \",COUNTRY_INFO!B55))","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C55=0,\" \",COUNTRY_INFO!C55))","v":"Umzingwane"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H55=0,COUNTRY_INFO!$H55=4,COUNTRY_INFO!$H55=99),OR(COUNTRY_INFO!$J55=0,COUNTRY_INFO!$J55=4)),0,COUNTRY_INFO!$E55))","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H55=0,COUNTRY_INFO!$H55=4,COUNTRY_INFO!$H55=99),OR(COUNTRY_INFO!$J55=0,COUNTRY_INFO!$J55=4)),0,COUNTRY_INFO!$F55))","v":0},0,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P55)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R55)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G55=1,DEC!I55,0),IF($G55=1,IVM!G55,0))","v":0},null,{"$f":"IF($J55=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H55<>0, IF($I55=0, $D55*$H55, $D55*($H55-$G55)), 0), $D55*$H55), 0)","v":0},0,null,0,{"$f":"IF($J55=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H55<>0, IF($I55=0, $D55*$H55, $D55*($H55-$G55)), 0), $D55*$H55), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A56=0,\" \",COUNTRY_INFO!A56))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B56=0,\" \",COUNTRY_INFO!B56))","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C56=0,\" \",COUNTRY_INFO!C56))","v":"Chirumhanzi"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H56=0,COUNTRY_INFO!$H56=4,COUNTRY_INFO!$H56=99),OR(COUNTRY_INFO!$J56=0,COUNTRY_INFO!$J56=4)),0,COUNTRY_INFO!$E56))","v":9657},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H56=0,COUNTRY_INFO!$H56=4,COUNTRY_INFO!$H56=99),OR(COUNTRY_INFO!$J56=0,COUNTRY_INFO!$J56=4)),0,COUNTRY_INFO!$F56))","v":27214},36871,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P56)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R56)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G56=1,DEC!I56,0),IF($G56=1,IVM!G56,0))","v":86032},null,{"$f":"IF($J56=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H56<>0, IF($I56=0, $D56*$H56, $D56*($H56-$G56)), 0), $D56*$H56), 0)","v":0},0,null,0,{"$f":"IF($J56=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H56<>0, IF($I56=0, $D56*$H56, $D56*($H56-$G56)), 0), $D56*$H56), 0)","v":0},0,null,0,null,86032,431,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A57=0,\" \",COUNTRY_INFO!A57))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B57=0,\" \",COUNTRY_INFO!B57))","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C57=0,\" \",COUNTRY_INFO!C57))","v":"Gokwe North"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H57=0,COUNTRY_INFO!$H57=4,COUNTRY_INFO!$H57=99),OR(COUNTRY_INFO!$J57=0,COUNTRY_INFO!$J57=4)),0,COUNTRY_INFO!$E57))","v":28886},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H57=0,COUNTRY_INFO!$H57=4,COUNTRY_INFO!$H57=99),OR(COUNTRY_INFO!$J57=0,COUNTRY_INFO!$J57=4)),0,COUNTRY_INFO!$F57))","v":81405},110291,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P57)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R57)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G57=1,DEC!I57,0),IF($G57=1,IVM!G57,0))","v":257345},null,{"$f":"IF($J57=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H57<>0, IF($I57=0, $D57*$H57, $D57*($H57-$G57)), 0), $D57*$H57), 0)","v":0},0,null,0,{"$f":"IF($J57=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H57<>0, IF($I57=0, $D57*$H57, $D57*($H57-$G57)), 0), $D57*$H57), 0)","v":0},0,null,0,null,257345,1287,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A58=0,\" \",COUNTRY_INFO!A58))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B58=0,\" \",COUNTRY_INFO!B58))","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C58=0,\" \",COUNTRY_INFO!C58))","v":"Gokwe South"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H58=0,COUNTRY_INFO!$H58=4,COUNTRY_INFO!$H58=99),OR(COUNTRY_INFO!$J58=0,COUNTRY_INFO!$J58=4)),0,COUNTRY_INFO!$E58))","v":39664},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H58=0,COUNTRY_INFO!$H58=4,COUNTRY_INFO!$H58=99),OR(COUNTRY_INFO!$J58=0,COUNTRY_INFO!$J58=4)),0,COUNTRY_INFO!$F58))","v":111780},151444,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P58)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R58)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G58=1,DEC!I58,0),IF($G58=1,IVM!G58,0))","v":353369},null,{"$f":"IF($J58=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H58<>0, IF($I58=0, $D58*$H58, $D58*($H58-$G58)), 0), $D58*$H58), 0)","v":0},0,null,0,{"$f":"IF($J58=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H58<>0, IF($I58=0, $D58*$H58, $D58*($H58-$G58)), 0), $D58*$H58), 0)","v":0},0,null,0,null,353369,1767,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A59=0,\" \",COUNTRY_INFO!A59))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B59=0,\" \",COUNTRY_INFO!B59))","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C59=0,\" \",COUNTRY_INFO!C59))","v":"Gweru"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H59=0,COUNTRY_INFO!$H59=4,COUNTRY_INFO!$H59=99),OR(COUNTRY_INFO!$J59=0,COUNTRY_INFO!$J59=4)),0,COUNTRY_INFO!$E59))","v":30005},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H59=0,COUNTRY_INFO!$H59=4,COUNTRY_INFO!$H59=99),OR(COUNTRY_INFO!$J59=0,COUNTRY_INFO!$J59=4)),0,COUNTRY_INFO!$F59))","v":84561},114566,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P59)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R59)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G59=1,DEC!I59,0),IF($G59=1,IVM!G59,0))","v":0},null,{"$f":"IF($J59=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H59<>0, IF($I59=0, $D59*$H59, $D59*($H59-$G59)), 0), $D59*$H59), 0)","v":0},0,null,0,{"$f":"IF($J59=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H59<>0, IF($I59=0, $D59*$H59, $D59*($H59-$G59)), 0), $D59*$H59), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A60=0,\" \",COUNTRY_INFO!A60))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B60=0,\" \",COUNTRY_INFO!B60))","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C60=0,\" \",COUNTRY_INFO!C60))","v":"Kwekwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H60=0,COUNTRY_INFO!$H60=4,COUNTRY_INFO!$H60=99),OR(COUNTRY_INFO!$J60=0,COUNTRY_INFO!$J60=4)),0,COUNTRY_INFO!$E60))","v":37443},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H60=0,COUNTRY_INFO!$H60=4,COUNTRY_INFO!$H60=99),OR(COUNTRY_INFO!$J60=0,COUNTRY_INFO!$J60=4)),0,COUNTRY_INFO!$F60))","v":105521},142964,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P60)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R60)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G60=1,DEC!I60,0),IF($G60=1,IVM!G60,0))","v":333583},null,{"$f":"IF($J60=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H60<>0, IF($I60=0, $D60*$H60, $D60*($H60-$G60)), 0), $D60*$H60), 0)","v":0},0,null,0,{"$f":"IF($J60=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H60<>0, IF($I60=0, $D60*$H60, $D60*($H60-$G60)), 0), $D60*$H60), 0)","v":0},0,null,0,null,333583,1668,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A61=0,\" \",COUNTRY_INFO!A61))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B61=0,\" \",COUNTRY_INFO!B61))","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C61=0,\" \",COUNTRY_INFO!C61))","v":"Mberengwa"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H61=0,COUNTRY_INFO!$H61=4,COUNTRY_INFO!$H61=99),OR(COUNTRY_INFO!$J61=0,COUNTRY_INFO!$J61=4)),0,COUNTRY_INFO!$E61))","v":22324},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H61=0,COUNTRY_INFO!$H61=4,COUNTRY_INFO!$H61=99),OR(COUNTRY_INFO!$J61=0,COUNTRY_INFO!$J61=4)),0,COUNTRY_INFO!$F61))","v":62914},85238,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P61)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R61)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G61=1,DEC!I61,0),IF($G61=1,IVM!G61,0))","v":198889},null,{"$f":"IF($J61=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H61<>0, IF($I61=0, $D61*$H61, $D61*($H61-$G61)), 0), $D61*$H61), 0)","v":0},0,null,0,{"$f":"IF($J61=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H61<>0, IF($I61=0, $D61*$H61, $D61*($H61-$G61)), 0), $D61*$H61), 0)","v":0},0,null,0,null,198889,995,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A62=0,\" \",COUNTRY_INFO!A62))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B62=0,\" \",COUNTRY_INFO!B62))","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C62=0,\" \",COUNTRY_INFO!C62))","v":"Shurugwi"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H62=0,COUNTRY_INFO!$H62=4,COUNTRY_INFO!$H62=99),OR(COUNTRY_INFO!$J62=0,COUNTRY_INFO!$J62=4)),0,COUNTRY_INFO!$E62))","v":11955},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H62=0,COUNTRY_INFO!$H62=4,COUNTRY_INFO!$H62=99),OR(COUNTRY_INFO!$J62=0,COUNTRY_INFO!$J62=4)),0,COUNTRY_INFO!$F62))","v":33691},45646,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P62)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R62)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G62=1,DEC!I62,0),IF($G62=1,IVM!G62,0))","v":106507},null,{"$f":"IF($J62=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H62<>0, IF($I62=0, $D62*$H62, $D62*($H62-$G62)), 0), $D62*$H62), 0)","v":0},0,null,0,{"$f":"IF($J62=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H62<>0, IF($I62=0, $D62*$H62, $D62*($H62-$G62)), 0), $D62*$H62), 0)","v":0},0,null,0,null,106507,533,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A63=0,\" \",COUNTRY_INFO!A63))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B63=0,\" \",COUNTRY_INFO!B63))","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C63=0,\" \",COUNTRY_INFO!C63))","v":"Zvishavane"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H63=0,COUNTRY_INFO!$H63=4,COUNTRY_INFO!$H63=99),OR(COUNTRY_INFO!$J63=0,COUNTRY_INFO!$J63=4)),0,COUNTRY_INFO!$E63))","v":14150},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H63=0,COUNTRY_INFO!$H63=4,COUNTRY_INFO!$H63=99),OR(COUNTRY_INFO!$J63=0,COUNTRY_INFO!$J63=4)),0,COUNTRY_INFO!$F63))","v":39878},54028,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P63)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R63)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G63=1,DEC!I63,0),IF($G63=1,IVM!G63,0))","v":126066},null,{"$f":"IF($J63=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H63<>0, IF($I63=0, $D63*$H63, $D63*($H63-$G63)), 0), $D63*$H63), 0)","v":0},0,null,0,{"$f":"IF($J63=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H63<>0, IF($I63=0, $D63*$H63, $D63*($H63-$G63)), 0), $D63*$H63), 0)","v":0},0,null,0,null,126066,631,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A64=0,\" \",COUNTRY_INFO!A64))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B64=0,\" \",COUNTRY_INFO!B64))","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C64=0,\" \",COUNTRY_INFO!C64))","v":"Bikita"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H64=0,COUNTRY_INFO!$H64=4,COUNTRY_INFO!$H64=99),OR(COUNTRY_INFO!$J64=0,COUNTRY_INFO!$J64=4)),0,COUNTRY_INFO!$E64))","v":19512},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H64=0,COUNTRY_INFO!$H64=4,COUNTRY_INFO!$H64=99),OR(COUNTRY_INFO!$J64=0,COUNTRY_INFO!$J64=4)),0,COUNTRY_INFO!$F64))","v":54988},74500,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P64)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R64)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G64=1,DEC!I64,0),IF($G64=1,IVM!G64,0))","v":173834},null,{"$f":"IF($J64=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H64<>0, IF($I64=0, $D64*$H64, $D64*($H64-$G64)), 0), $D64*$H64), 0)","v":0},0,null,0,{"$f":"IF($J64=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H64<>0, IF($I64=0, $D64*$H64, $D64*($H64-$G64)), 0), $D64*$H64), 0)","v":0},0,null,0,null,173834,870,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A65=0,\" \",COUNTRY_INFO!A65))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B65=0,\" \",COUNTRY_INFO!B65))","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C65=0,\" \",COUNTRY_INFO!C65))","v":"Chiredzi"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H65=0,COUNTRY_INFO!$H65=4,COUNTRY_INFO!$H65=99),OR(COUNTRY_INFO!$J65=0,COUNTRY_INFO!$J65=4)),0,COUNTRY_INFO!$E65))","v":36800},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H65=0,COUNTRY_INFO!$H65=4,COUNTRY_INFO!$H65=99),OR(COUNTRY_INFO!$J65=0,COUNTRY_INFO!$J65=4)),0,COUNTRY_INFO!$F65))","v":103709},140509,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P65)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R65)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G65=1,DEC!I65,0),IF($G65=1,IVM!G65,0))","v":327855},null,{"$f":"IF($J65=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H65<>0, IF($I65=0, $D65*$H65, $D65*($H65-$G65)), 0), $D65*$H65), 0)","v":0},0,null,0,{"$f":"IF($J65=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H65<>0, IF($I65=0, $D65*$H65, $D65*($H65-$G65)), 0), $D65*$H65), 0)","v":0},0,null,0,null,327855,1640,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A66=0,\" \",COUNTRY_INFO!A66))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B66=0,\" \",COUNTRY_INFO!B66))","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C66=0,\" \",COUNTRY_INFO!C66))","v":"Chivi"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H66=0,COUNTRY_INFO!$H66=4,COUNTRY_INFO!$H66=99),OR(COUNTRY_INFO!$J66=0,COUNTRY_INFO!$J66=4)),0,COUNTRY_INFO!$E66))","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H66=0,COUNTRY_INFO!$H66=4,COUNTRY_INFO!$H66=99),OR(COUNTRY_INFO!$J66=0,COUNTRY_INFO!$J66=4)),0,COUNTRY_INFO!$F66))","v":0},0,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P66)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R66)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G66=1,DEC!I66,0),IF($G66=1,IVM!G66,0))","v":0},null,{"$f":"IF($J66=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H66<>0, IF($I66=0, $D66*$H66, $D66*($H66-$G66)), 0), $D66*$H66), 0)","v":0},0,null,0,{"$f":"IF($J66=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H66<>0, IF($I66=0, $D66*$H66, $D66*($H66-$G66)), 0), $D66*$H66), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A67=0,\" \",COUNTRY_INFO!A67))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B67=0,\" \",COUNTRY_INFO!B67))","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C67=0,\" \",COUNTRY_INFO!C67))","v":"Gutu"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H67=0,COUNTRY_INFO!$H67=4,COUNTRY_INFO!$H67=99),OR(COUNTRY_INFO!$J67=0,COUNTRY_INFO!$J67=4)),0,COUNTRY_INFO!$E67))","v":24407},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H67=0,COUNTRY_INFO!$H67=4,COUNTRY_INFO!$H67=99),OR(COUNTRY_INFO!$J67=0,COUNTRY_INFO!$J67=4)),0,COUNTRY_INFO!$F67))","v":68782},93189,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P67)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R67)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G67=1,DEC!I67,0),IF($G67=1,IVM!G67,0))","v":217441},null,{"$f":"IF($J67=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H67<>0, IF($I67=0, $D67*$H67, $D67*($H67-$G67)), 0), $D67*$H67), 0)","v":0},0,null,0,{"$f":"IF($J67=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H67<>0, IF($I67=0, $D67*$H67, $D67*($H67-$G67)), 0), $D67*$H67), 0)","v":0},0,null,0,null,217441,1088,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A68=0,\" \",COUNTRY_INFO!A68))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B68=0,\" \",COUNTRY_INFO!B68))","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C68=0,\" \",COUNTRY_INFO!C68))","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H68=0,COUNTRY_INFO!$H68=4,COUNTRY_INFO!$H68=99),OR(COUNTRY_INFO!$J68=0,COUNTRY_INFO!$J68=4)),0,COUNTRY_INFO!$E68))","v":35946},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H68=0,COUNTRY_INFO!$H68=4,COUNTRY_INFO!$H68=99),OR(COUNTRY_INFO!$J68=0,COUNTRY_INFO!$J68=4)),0,COUNTRY_INFO!$F68))","v":101302},137248,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P68)","v":0},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R68)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G68=1,DEC!I68,0),IF($G68=1,IVM!G68,0))","v":0},null,{"$f":"IF($J68=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H68<>0, IF($I68=0, $D68*$H68, $D68*($H68-$G68)), 0), $D68*$H68), 0)","v":0},0,null,0,{"$f":"IF($J68=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H68<>0, IF($I68=0, $D68*$H68, $D68*($H68-$G68)), 0), $D68*$H68), 0)","v":0},0,null,0,null,0,0,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A69=0,\" \",COUNTRY_INFO!A69))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B69=0,\" \",COUNTRY_INFO!B69))","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C69=0,\" \",COUNTRY_INFO!C69))","v":"Mwenezi"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H69=0,COUNTRY_INFO!$H69=4,COUNTRY_INFO!$H69=99),OR(COUNTRY_INFO!$J69=0,COUNTRY_INFO!$J69=4)),0,COUNTRY_INFO!$E69))","v":20069},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H69=0,COUNTRY_INFO!$H69=4,COUNTRY_INFO!$H69=99),OR(COUNTRY_INFO!$J69=0,COUNTRY_INFO!$J69=4)),0,COUNTRY_INFO!$F69))","v":56559},76628,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P69)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R69)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G69=1,DEC!I69,0),IF($G69=1,IVM!G69,0))","v":178799},null,{"$f":"IF($J69=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H69<>0, IF($I69=0, $D69*$H69, $D69*($H69-$G69)), 0), $D69*$H69), 0)","v":0},0,null,0,{"$f":"IF($J69=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H69<>0, IF($I69=0, $D69*$H69, $D69*($H69-$G69)), 0), $D69*$H69), 0)","v":0},0,null,0,null,178799,894,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A70=0,\" \",COUNTRY_INFO!A70))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B70=0,\" \",COUNTRY_INFO!B70))","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C70=0,\" \",COUNTRY_INFO!C70))","v":"Zaka"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H70=0,COUNTRY_INFO!$H70=4,COUNTRY_INFO!$H70=99),OR(COUNTRY_INFO!$J70=0,COUNTRY_INFO!$J70=4)),0,COUNTRY_INFO!$E70))","v":21789},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H70=0,COUNTRY_INFO!$H70=4,COUNTRY_INFO!$H70=99),OR(COUNTRY_INFO!$J70=0,COUNTRY_INFO!$J70=4)),0,COUNTRY_INFO!$F70))","v":61405},83194,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P70)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R70)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G70=1,DEC!I70,0),IF($G70=1,IVM!G70,0))","v":194119},null,{"$f":"IF($J70=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H70<>0, IF($I70=0, $D70*$H70, $D70*($H70-$G70)), 0), $D70*$H70), 0)","v":0},0,null,0,{"$f":"IF($J70=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H70<>0, IF($I70=0, $D70*$H70, $D70*($H70-$G70)), 0), $D70*$H70), 0)","v":0},0,null,0,null,194119,971,null,0,0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!A71=0,\" \",COUNTRY_INFO!A71))","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!B71=0,\" \",COUNTRY_INFO!B71))","v":"Bulawayo"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),\" \",IF(COUNTRY_INFO!C71=0,\" \",COUNTRY_INFO!C71))","v":"Bulawayo"},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H71=0,COUNTRY_INFO!$H71=4,COUNTRY_INFO!$H71=99),OR(COUNTRY_INFO!$J71=0,COUNTRY_INFO!$J71=4)),0,COUNTRY_INFO!$E71))","v":78518},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,IF(AND(OR(COUNTRY_INFO!$H71=0,COUNTRY_INFO!$H71=4,COUNTRY_INFO!$H71=99),OR(COUNTRY_INFO!$J71=0,COUNTRY_INFO!$J71=4)),0,COUNTRY_INFO!$F71))","v":221279},299797,{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!P71)","v":1},{"$f":"IF(AND(INTRO!$E$37=\"Non-endemic\",INTRO!$E$41=\"Non-endemic\"),0,COUNTRY_INFO!R71)","v":0},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",IF($G71=1,DEC!I71,0),IF($G71=1,IVM!G71,0))","v":699527},null,{"$f":"IF($J71=\"ALB\", IF(INTRO!$E$39=\"Non-endemic\", IF($H71<>0, IF($I71=0, $D71*$H71, $D71*($H71-$G71)), 0), $D71*$H71), 0)","v":0},0,null,0,{"$f":"IF($J71=\"MBD\", IF(INTRO!$E$39=\"Non-endemic\", IF($H71<>0, IF($I71=0, $D71*$H71, $D71*($H71-$G71)), 0), $D71*$H71), 0)","v":0},0,null,0,null,699527,3498,null,0,0,null,0,0]

{"sheet":"PZQ","index":4,"n_rows":71,"n_cols":18,"rows_kept":71,"cut":false,"hidden":false,"merged":[[5,12,5,17],[6,6,7,6],[6,8,7,8],[6,9,7,9],[3,0,3,2],[5,0,5,2],[5,3,5,5],[5,8,5,11],[5,6,5,7],[6,10,7,10],[6,17,7,17],[6,13,7,13],[6,14,7,14],[6,15,7,15],[6,11,7,11],[6,12,7,12],[6,16,7,16],[6,4,7,4],[6,5,7,5],[6,7,7,7],[6,0,7,0],[6,1,7,1],[6,2,7,2],[6,3,7,3]]}
["Praziquantel (PZQ)"]
["Administrative structure, eligible population by age group, treatment plan and information about tablets"]
[]
["TOTAL",null,null,{"$f":"SUM(D$9:D$1000)","v":2021613.68},{"$f":"SUM(E$9:E$1000)","v":1391540.0000000005},{"$f":"SUM(F$9:F$1000)","v":3413153.68},null,null,{"$f":"SUM(I$9:I$1000)","v":2630757},0,1303510.4000000001,3934267.4,6576892.5,3910531.1999999993,6576892.5,0,6576892.5,6599]
[]
["Country administrative structure",null,null,"Population requiring treatment with PZQ",null,null,"Treatment plan",null,"Target population",null,null,null,"Praziquantel (PZQ)"]
["Country","Province/State","District","SAC","Adults","Total","SCH","All SAC targeted?","SAC","SAC\nat lower level","Adults","Total","SAC","Adults","Total required\nfor SAC","Remaining in stock","Tablets to be procured","Bottle (600 mg)\n1000 tablets"]
[]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A9=0,\" \",COUNTRY_INFO!A9))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B9=0,\" \",COUNTRY_INFO!B9))","v":"Manicaland"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C9=0,\" \",COUNTRY_INFO!C9))","v":"Buhera"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K9>0, IF(COUNTRY_INFO!$K9=4, 0, IF(COUNTRY_INFO!$K9=1, COUNTRY_INFO!$F9*0.33, IF(COUNTRY_INFO!$K9=2, COUNTRY_INFO!$F9*0.5, COUNTRY_INFO!$F9))), 0))","v":41638},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K9>0, IF(COUNTRY_INFO!$K9=4, 0, IF(COUNTRY_INFO!$K9=1, 0, IF(COUNTRY_INFO!$K9=2, COUNTRY_INFO!$G9*0.2, COUNTRY_INFO!$G9))), 0))","v":30086.800000000003},{"$f":"SUM(D9:E9)","v":71724.800000000003},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S9)","v":1},"Yes",{"$f":"IF($D9=0,0,IF(AND($G9>0,$H9<>\"Yes\"),D9,IF(AND($G9>0,$H9=\"Yes\"),COUNTRY_INFO!$F9,0)))","v":83276},null,{"$f":"IF($G9>0,E9, 0)","v":30086.800000000003},{"$f":"IF($J9=0,SUM(I9,K9),SUM(J9,K9))","v":113362.8},{"$f":"IF($J9=0,$I9*2.5,$J9*2.5)","v":208190},{"$f":"$K9*3","v":90260.400000000009},{"$f":"M9","v":208190},null,{"$f":"IF($O9>$P9,O9-P9,0)","v":208190},{"$f":"ROUNDUP($O9/1000,0)","v":209}]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A10=0,\" \",COUNTRY_INFO!A10))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B10=0,\" \",COUNTRY_INFO!B10))","v":"Manicaland"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C10=0,\" \",COUNTRY_INFO!C10))","v":"Chimanimani"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K10>0, IF(COUNTRY_INFO!$K10=4, 0, IF(COUNTRY_INFO!$K10=1, COUNTRY_INFO!$F10*0.33, IF(COUNTRY_INFO!$K10=2, COUNTRY_INFO!$F10*0.5, COUNTRY_INFO!$F10))), 0))","v":22851.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K10>0, IF(COUNTRY_INFO!$K10=4, 0, IF(COUNTRY_INFO!$K10=1, 0, IF(COUNTRY_INFO!$K10=2, COUNTRY_INFO!$G10*0.2, COUNTRY_INFO!$G10))), 0))","v":16512},39363.5,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S10)","v":1},"Yes",{"$f":"IF($D10=0,0,IF(AND($G10>0,$H10<>\"Yes\"),D10,IF(AND($G10>0,$H10=\"Yes\"),COUNTRY_INFO!$F10,0)))","v":45703},null,16512,62215,114257.5,49536,114257.5,0,114257.5,115]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A11=0,\" \",COUNTRY_INFO!A11))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B11=0,\" \",COUNTRY_INFO!B11))","v":"Manicaland"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C11=0,\" \",COUNTRY_INFO!C11))","v":"Chipinge"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K11>0, IF(COUNTRY_INFO!$K11=4, 0, IF(COUNTRY_INFO!$K11=1, COUNTRY_INFO!$F11*0.33, IF(COUNTRY_INFO!$K11=2, COUNTRY_INFO!$F11*0.5, COUNTRY_INFO!$F11))), 0))","v":54890.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K11>0, IF(COUNTRY_INFO!$K11=4, 0, IF(COUNTRY_INFO!$K11=1, 0, IF(COUNTRY_INFO!$K11=2, COUNTRY_INFO!$G11*0.2, COUNTRY_INFO!$G11))), 0))","v":39662.800000000003},94553.3,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S11)","v":1},"Yes",{"$f":"IF($D11=0,0,IF(AND($G11>0,$H11<>\"Yes\"),D11,IF(AND($G11>0,$H11=\"Yes\"),COUNTRY_INFO!$F11,0)))","v":109781},null,39662.800000000003,149443.79999999999,274452.5,118988.40000000001,274452.5,null,274452.5,275]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A12=0,\" \",COUNTRY_INFO!A12))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B12=0,\" \",COUNTRY_INFO!B12))","v":"Manicaland"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C12=0,\" \",COUNTRY_INFO!C12))","v":"Makoni"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K12>0, IF(COUNTRY_INFO!$K12=4, 0, IF(COUNTRY_INFO!$K12=1, COUNTRY_INFO!$F12*0.33, IF(COUNTRY_INFO!$K12=2, COUNTRY_INFO!$F12*0.5, COUNTRY_INFO!$F12))), 0))","v":51253.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K12>0, IF(COUNTRY_INFO!$K12=4, 0, IF(COUNTRY_INFO!$K12=1, 0, IF(COUNTRY_INFO!$K12=2, COUNTRY_INFO!$G12*0.2, COUNTRY_INFO!$G12))), 0))","v":37034.800000000003},88288.3,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S12)","v":1},"Yes",{"$f":"IF($D12=0,0,IF(AND($G12>0,$H12<>\"Yes\"),D12,IF(AND($G12>0,$H12=\"Yes\"),COUNTRY_INFO!$F12,0)))","v":102507},null,37034.800000000003,139541.79999999999,256267.5,111104.40000000001,256267.5,null,256267.5,257]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A13=0,\" \",COUNTRY_INFO!A13))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B13=0,\" \",COUNTRY_INFO!B13))","v":"Manicaland"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C13=0,\" \",COUNTRY_INFO!C13))","v":"Mutare"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K13>0, IF(COUNTRY_INFO!$K13=4, 0, IF(COUNTRY_INFO!$K13=1, COUNTRY_INFO!$F13*0.33, IF(COUNTRY_INFO!$K13=2, COUNTRY_INFO!$F13*0.5, COUNTRY_INFO!$F13))), 0))","v":44389.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K13>0, IF(COUNTRY_INFO!$K13=4, 0, IF(COUNTRY_INFO!$K13=1, 0, IF(COUNTRY_INFO!$K13=2, COUNTRY_INFO!$G13*0.2, COUNTRY_INFO!$G13))), 0))","v":32075},76464.5,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S13)","v":1},"Yes",{"$f":"IF($D13=0,0,IF(AND($G13>0,$H13<>\"Yes\"),D13,IF(AND($G13>0,$H13=\"Yes\"),COUNTRY_INFO!$F13,0)))","v":88779},null,32075,120854,221947.5,96225,221947.5,null,221947.5,222]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A14=0,\" \",COUNTRY_INFO!A14))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B14=0,\" \",COUNTRY_INFO!B14))","v":"Manicaland"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C14=0,\" \",COUNTRY_INFO!C14))","v":"Mutasa"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K14>0, IF(COUNTRY_INFO!$K14=4, 0, IF(COUNTRY_INFO!$K14=1, COUNTRY_INFO!$F14*0.33, IF(COUNTRY_INFO!$K14=2, COUNTRY_INFO!$F14*0.5, COUNTRY_INFO!$F14))), 0))","v":18860.490000000002},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K14>0, IF(COUNTRY_INFO!$K14=4, 0, IF(COUNTRY_INFO!$K14=1, 0, IF(COUNTRY_INFO!$K14=2, COUNTRY_INFO!$G14*0.2, COUNTRY_INFO!$G14))), 0))","v":0},18860.490000000002,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S14)","v":0},"Yes",{"$f":"IF($D14=0,0,IF(AND($G14>0,$H14<>\"Yes\"),D14,IF(AND($G14>0,$H14=\"Yes\"),COUNTRY_INFO!$F14,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A15=0,\" \",COUNTRY_INFO!A15))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B15=0,\" \",COUNTRY_INFO!B15))","v":"Manicaland"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C15=0,\" \",COUNTRY_INFO!C15))","v":"Nyanga"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K15>0, IF(COUNTRY_INFO!$K15=4, 0, IF(COUNTRY_INFO!$K15=1, COUNTRY_INFO!$F15*0.33, IF(COUNTRY_INFO!$K15=2, COUNTRY_INFO!$F15*0.5, COUNTRY_INFO!$F15))), 0))","v":53211.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K15>0, IF(COUNTRY_INFO!$K15=4, 0, IF(COUNTRY_INFO!$K15=1, 0, IF(COUNTRY_INFO!$K15=2, COUNTRY_INFO!$G15*0.2, COUNTRY_INFO!$G15))), 0))","v":38449.800000000003},91661.3,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S15)","v":1},"Yes",{"$f":"IF($D15=0,0,IF(AND($G15>0,$H15<>\"Yes\"),D15,IF(AND($G15>0,$H15=\"Yes\"),COUNTRY_INFO!$F15,0)))","v":106423},null,38449.800000000003,144872.79999999999,266057.5,115349.40000000001,266057.5,null,266057.5,267]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A16=0,\" \",COUNTRY_INFO!A16))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B16=0,\" \",COUNTRY_INFO!B16))","v":"Harare"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C16=0,\" \",COUNTRY_INFO!C16))","v":"Chitungwiza"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K16>0, IF(COUNTRY_INFO!$K16=4, 0, IF(COUNTRY_INFO!$K16=1, COUNTRY_INFO!$F16*0.33, IF(COUNTRY_INFO!$K16=2, COUNTRY_INFO!$F16*0.5, COUNTRY_INFO!$F16))), 0))","v":39883.14},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K16>0, IF(COUNTRY_INFO!$K16=4, 0, IF(COUNTRY_INFO!$K16=1, 0, IF(COUNTRY_INFO!$K16=2, COUNTRY_INFO!$G16*0.2, COUNTRY_INFO!$G16))), 0))","v":0},39883.14,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S16)","v":0},"Yes",{"$f":"IF($D16=0,0,IF(AND($G16>0,$H16<>\"Yes\"),D16,IF(AND($G16>0,$H16=\"Yes\"),COUNTRY_INFO!$F16,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A17=0,\" \",COUNTRY_INFO!A17))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B17=0,\" \",COUNTRY_INFO!B17))","v":"Harare"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C17=0,\" \",COUNTRY_INFO!C17))","v":"Harare"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K17>0, IF(COUNTRY_INFO!$K17=4, 0, IF(COUNTRY_INFO!$K17=1, COUNTRY_INFO!$F17*0.33, IF(COUNTRY_INFO!$K17=2, COUNTRY_INFO!$F17*0.5, COUNTRY_INFO!$F17))), 0))","v":178697.64},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K17>0, IF(COUNTRY_INFO!$K17=4, 0, IF(COUNTRY_INFO!$K17=1, 0, IF(COUNTRY_INFO!$K17=2, COUNTRY_INFO!$G17*0.2, COUNTRY_INFO!$G17))), 0))","v":0},178697.64,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S17)","v":0},"Yes",{"$f":"IF($D17=0,0,IF(AND($G17>0,$H17<>\"Yes\"),D17,IF(AND($G17>0,$H17=\"Yes\"),COUNTRY_INFO!$F17,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A18=0,\" \",COUNTRY_INFO!A18))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B18=0,\" \",COUNTRY_INFO!B18))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C18=0,\" \",COUNTRY_INFO!C18))","v":"Bindura"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K18>0, IF(COUNTRY_INFO!$K18=4, 0, IF(COUNTRY_INFO!$K18=1, COUNTRY_INFO!$F18*0.33, IF(COUNTRY_INFO!$K18=2, COUNTRY_INFO!$F18*0.5, COUNTRY_INFO!$F18))), 0))","v":28601.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K18>0, IF(COUNTRY_INFO!$K18=4, 0, IF(COUNTRY_INFO!$K18=1, 0, IF(COUNTRY_INFO!$K18=2, COUNTRY_INFO!$G18*0.2, COUNTRY_INFO!$G18))), 0))","v":20666.800000000003},49268.3,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S18)","v":1},"Yes",{"$f":"IF($D18=0,0,IF(AND($G18>0,$H18<>\"Yes\"),D18,IF(AND($G18>0,$H18=\"Yes\"),COUNTRY_INFO!$F18,0)))","v":57203},null,20666.800000000003,77869.8,143007.5,62000.400000000009,143007.5,null,143007.5,144]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A19=0,\" \",COUNTRY_INFO!A19))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B19=0,\" \",COUNTRY_INFO!B19))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C19=0,\" \",COUNTRY_INFO!C19))","v":"Centenary"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K19>0, IF(COUNTRY_INFO!$K19=4, 0, IF(COUNTRY_INFO!$K19=1, COUNTRY_INFO!$F19*0.33, IF(COUNTRY_INFO!$K19=2, COUNTRY_INFO!$F19*0.5, COUNTRY_INFO!$F19))), 0))","v":20794},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K19>0, IF(COUNTRY_INFO!$K19=4, 0, IF(COUNTRY_INFO!$K19=1, 0, IF(COUNTRY_INFO!$K19=2, COUNTRY_INFO!$G19*0.2, COUNTRY_INFO!$G19))), 0))","v":15025.400000000001},35819.4,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S19)","v":1},"Yes",{"$f":"IF($D19=0,0,IF(AND($G19>0,$H19<>\"Yes\"),D19,IF(AND($G19>0,$H19=\"Yes\"),COUNTRY_INFO!$F19,0)))","v":41588},null,15025.400000000001,56613.4,103970,45076.200000000004,103970,null,103970,104]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A20=0,\" \",COUNTRY_INFO!A20))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B20=0,\" \",COUNTRY_INFO!B20))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C20=0,\" \",COUNTRY_INFO!C20))","v":"Guruve"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K20>0, IF(COUNTRY_INFO!$K20=4, 0, IF(COUNTRY_INFO!$K20=1, COUNTRY_INFO!$F20*0.33, IF(COUNTRY_INFO!$K20=2, COUNTRY_INFO!$F20*0.5, COUNTRY_INFO!$F20))), 0))","v":21005.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K20>0, IF(COUNTRY_INFO!$K20=4, 0, IF(COUNTRY_INFO!$K20=1, 0, IF(COUNTRY_INFO!$K20=2, COUNTRY_INFO!$G20*0.2, COUNTRY_INFO!$G20))), 0))","v":15178.2},36183.699999999997,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S20)","v":1},"Yes",{"$f":"IF($D20=0,0,IF(AND($G20>0,$H20<>\"Yes\"),D20,IF(AND($G20>0,$H20=\"Yes\"),COUNTRY_INFO!$F20,0)))","v":42011},null,15178.2,57189.2,105027.5,45534.600000000006,105027.5,null,105027.5,106]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A21=0,\" \",COUNTRY_INFO!A21))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B21=0,\" \",COUNTRY_INFO!B21))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C21=0,\" \",COUNTRY_INFO!C21))","v":"Mazowe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K21>0, IF(COUNTRY_INFO!$K21=4, 0, IF(COUNTRY_INFO!$K21=1, COUNTRY_INFO!$F21*0.33, IF(COUNTRY_INFO!$K21=2, COUNTRY_INFO!$F21*0.5, COUNTRY_INFO!$F21))), 0))","v":41320},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K21>0, IF(COUNTRY_INFO!$K21=4, 0, IF(COUNTRY_INFO!$K21=1, 0, IF(COUNTRY_INFO!$K21=2, COUNTRY_INFO!$G21*0.2, COUNTRY_INFO!$G21))), 0))","v":29857},71177,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S21)","v":1},"Yes",{"$f":"IF($D21=0,0,IF(AND($G21>0,$H21<>\"Yes\"),D21,IF(AND($G21>0,$H21=\"Yes\"),COUNTRY_INFO!$F21,0)))","v":82640},null,29857,112497,206600,89571,206600,null,206600,207]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A22=0,\" \",COUNTRY_INFO!A22))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B22=0,\" \",COUNTRY_INFO!B22))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C22=0,\" \",COUNTRY_INFO!C22))","v":"Mt Darwin"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K22>0, IF(COUNTRY_INFO!$K22=4, 0, IF(COUNTRY_INFO!$K22=1, COUNTRY_INFO!$F22*0.33, IF(COUNTRY_INFO!$K22=2, COUNTRY_INFO!$F22*0.5, COUNTRY_INFO!$F22))), 0))","v":36024},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K22>0, IF(COUNTRY_INFO!$K22=4, 0, IF(COUNTRY_INFO!$K22=1, 0, IF(COUNTRY_INFO!$K22=2, COUNTRY_INFO!$G22*0.2, COUNTRY_INFO!$G22))), 0))","v":26030.2},62054.2,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S22)","v":1},"Yes",{"$f":"IF($D22=0,0,IF(AND($G22>0,$H22<>\"Yes\"),D22,IF(AND($G22>0,$H22=\"Yes\"),COUNTRY_INFO!$F22,0)))","v":72048},null,26030.2,98078.2,180120,78090.600000000006,180120,null,180120,181]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A23=0,\" \",COUNTRY_INFO!A23))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B23=0,\" \",COUNTRY_INFO!B23))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C23=0,\" \",COUNTRY_INFO!C23))","v":"Rushinga"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K23>0, IF(COUNTRY_INFO!$K23=4, 0, IF(COUNTRY_INFO!$K23=1, COUNTRY_INFO!$F23*0.33, IF(COUNTRY_INFO!$K23=2, COUNTRY_INFO!$F23*0.5, COUNTRY_INFO!$F23))), 0))","v":12538.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K23>0, IF(COUNTRY_INFO!$K23=4, 0, IF(COUNTRY_INFO!$K23=1, 0, IF(COUNTRY_INFO!$K23=2, COUNTRY_INFO!$G23*0.2, COUNTRY_INFO!$G23))), 0))","v":9060},21598.5,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S23)","v":1},"Yes",{"$f":"IF($D23=0,0,IF(AND($G23>0,$H23<>\"Yes\"),D23,IF(AND($G23>0,$H23=\"Yes\"),COUNTRY_INFO!$F23,0)))","v":25077},null,9060,34137,62692.5,27180,62692.5,null,62692.5,63]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A24=0,\" \",COUNTRY_INFO!A24))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B24=0,\" \",COUNTRY_INFO!B24))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C24=0,\" \",COUNTRY_INFO!C24))","v":"Shamva"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K24>0, IF(COUNTRY_INFO!$K24=4, 0, IF(COUNTRY_INFO!$K24=1, COUNTRY_INFO!$F24*0.33, IF(COUNTRY_INFO!$K24=2, COUNTRY_INFO!$F24*0.5, COUNTRY_INFO!$F24))), 0))","v":41879},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K24>0, IF(COUNTRY_INFO!$K24=4, 0, IF(COUNTRY_INFO!$K24=1, 0, IF(COUNTRY_INFO!$K24=2, COUNTRY_INFO!$G24*0.2, COUNTRY_INFO!$G24))), 0))","v":75653},117532,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S24)","v":1},"Yes",{"$f":"IF($D24=0,0,IF(AND($G24>0,$H24<>\"Yes\"),D24,IF(AND($G24>0,$H24=\"Yes\"),COUNTRY_INFO!$F24,0)))","v":41879},null,75653,117532,104697.5,226959,104697.5,null,104697.5,105]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A25=0,\" \",COUNTRY_INFO!A25))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B25=0,\" \",COUNTRY_INFO!B25))","v":"Mashnaland Central"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C25=0,\" \",COUNTRY_INFO!C25))","v":"Mbire"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K25>0, IF(COUNTRY_INFO!$K25=4, 0, IF(COUNTRY_INFO!$K25=1, COUNTRY_INFO!$F25*0.33, IF(COUNTRY_INFO!$K25=2, COUNTRY_INFO!$F25*0.5, COUNTRY_INFO!$F25))), 0))","v":13950.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K25>0, IF(COUNTRY_INFO!$K25=4, 0, IF(COUNTRY_INFO!$K25=1, 0, IF(COUNTRY_INFO!$K25=2, COUNTRY_INFO!$G25*0.2, COUNTRY_INFO!$G25))), 0))","v":10080.400000000001},24030.9,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S25)","v":1},"Yes",{"$f":"IF($D25=0,0,IF(AND($G25>0,$H25<>\"Yes\"),D25,IF(AND($G25>0,$H25=\"Yes\"),COUNTRY_INFO!$F25,0)))","v":27901},null,10080.400000000001,37981.4,69752.5,30241.200000000004,69752.5,null,69752.5,70]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A26=0,\" \",COUNTRY_INFO!A26))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B26=0,\" \",COUNTRY_INFO!B26))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C26=0,\" \",COUNTRY_INFO!C26))","v":"Chikomba"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K26>0, IF(COUNTRY_INFO!$K26=4, 0, IF(COUNTRY_INFO!$K26=1, COUNTRY_INFO!$F26*0.33, IF(COUNTRY_INFO!$K26=2, COUNTRY_INFO!$F26*0.5, COUNTRY_INFO!$F26))), 0))","v":40977},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K26>0, IF(COUNTRY_INFO!$K26=4, 0, IF(COUNTRY_INFO!$K26=1, 0, IF(COUNTRY_INFO!$K26=2, COUNTRY_INFO!$G26*0.2, COUNTRY_INFO!$G26))), 0))","v":74022},114999,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S26)","v":1},"Yes",{"$f":"IF($D26=0,0,IF(AND($G26>0,$H26<>\"Yes\"),D26,IF(AND($G26>0,$H26=\"Yes\"),COUNTRY_INFO!$F26,0)))","v":40977},null,74022,114999,102442.5,222066,102442.5,null,102442.5,103]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A27=0,\" \",COUNTRY_INFO!A27))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B27=0,\" \",COUNTRY_INFO!B27))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C27=0,\" \",COUNTRY_INFO!C27))","v":"Goromonzi"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K27>0, IF(COUNTRY_INFO!$K27=4, 0, IF(COUNTRY_INFO!$K27=1, COUNTRY_INFO!$F27*0.33, IF(COUNTRY_INFO!$K27=2, COUNTRY_INFO!$F27*0.5, COUNTRY_INFO!$F27))), 0))","v":25146.33},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K27>0, IF(COUNTRY_INFO!$K27=4, 0, IF(COUNTRY_INFO!$K27=1, 0, IF(COUNTRY_INFO!$K27=2, COUNTRY_INFO!$G27*0.2, COUNTRY_INFO!$G27))), 0))","v":0},25146.33,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S27)","v":0},"Yes",{"$f":"IF($D27=0,0,IF(AND($G27>0,$H27<>\"Yes\"),D27,IF(AND($G27>0,$H27=\"Yes\"),COUNTRY_INFO!$F27,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A28=0,\" \",COUNTRY_INFO!A28))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B28=0,\" \",COUNTRY_INFO!B28))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C28=0,\" \",COUNTRY_INFO!C28))","v":"UMP"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K28>0, IF(COUNTRY_INFO!$K28=4, 0, IF(COUNTRY_INFO!$K28=1, COUNTRY_INFO!$F28*0.33, IF(COUNTRY_INFO!$K28=2, COUNTRY_INFO!$F28*0.5, COUNTRY_INFO!$F28))), 0))","v":19070},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K28>0, IF(COUNTRY_INFO!$K28=4, 0, IF(COUNTRY_INFO!$K28=1, 0, IF(COUNTRY_INFO!$K28=2, COUNTRY_INFO!$G28*0.2, COUNTRY_INFO!$G28))), 0))","v":13779.6},32849.599999999999,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S28)","v":1},"Yes",{"$f":"IF($D28=0,0,IF(AND($G28>0,$H28<>\"Yes\"),D28,IF(AND($G28>0,$H28=\"Yes\"),COUNTRY_INFO!$F28,0)))","v":38140},null,13779.6,51919.6,95350,41338.800000000003,95350,null,95350,96]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A29=0,\" \",COUNTRY_INFO!A29))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B29=0,\" \",COUNTRY_INFO!B29))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C29=0,\" \",COUNTRY_INFO!C29))","v":"Hwedza"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K29>0, IF(COUNTRY_INFO!$K29=4, 0, IF(COUNTRY_INFO!$K29=1, COUNTRY_INFO!$F29*0.33, IF(COUNTRY_INFO!$K29=2, COUNTRY_INFO!$F29*0.5, COUNTRY_INFO!$F29))), 0))","v":24036},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K29>0, IF(COUNTRY_INFO!$K29=4, 0, IF(COUNTRY_INFO!$K29=1, 0, IF(COUNTRY_INFO!$K29=2, COUNTRY_INFO!$G29*0.2, COUNTRY_INFO!$G29))), 0))","v":43421},67457,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S29)","v":1},"Yes",{"$f":"IF($D29=0,0,IF(AND($G29>0,$H29<>\"Yes\"),D29,IF(AND($G29>0,$H29=\"Yes\"),COUNTRY_INFO!$F29,0)))","v":24036},null,43421,67457,60090,130263,60090,null,60090,61]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A30=0,\" \",COUNTRY_INFO!A30))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B30=0,\" \",COUNTRY_INFO!B30))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C30=0,\" \",COUNTRY_INFO!C30))","v":"Marondera"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K30>0, IF(COUNTRY_INFO!$K30=4, 0, IF(COUNTRY_INFO!$K30=1, COUNTRY_INFO!$F30*0.33, IF(COUNTRY_INFO!$K30=2, COUNTRY_INFO!$F30*0.5, COUNTRY_INFO!$F30))), 0))","v":20004.600000000002},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K30>0, IF(COUNTRY_INFO!$K30=4, 0, IF(COUNTRY_INFO!$K30=1, 0, IF(COUNTRY_INFO!$K30=2, COUNTRY_INFO!$G30*0.2, COUNTRY_INFO!$G30))), 0))","v":0},20004.600000000002,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S30)","v":0},"Yes",{"$f":"IF($D30=0,0,IF(AND($G30>0,$H30<>\"Yes\"),D30,IF(AND($G30>0,$H30=\"Yes\"),COUNTRY_INFO!$F30,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A31=0,\" \",COUNTRY_INFO!A31))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B31=0,\" \",COUNTRY_INFO!B31))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C31=0,\" \",COUNTRY_INFO!C31))","v":"Mudzi"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K31>0, IF(COUNTRY_INFO!$K31=4, 0, IF(COUNTRY_INFO!$K31=1, COUNTRY_INFO!$F31*0.33, IF(COUNTRY_INFO!$K31=2, COUNTRY_INFO!$F31*0.5, COUNTRY_INFO!$F31))), 0))","v":22565.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K31>0, IF(COUNTRY_INFO!$K31=4, 0, IF(COUNTRY_INFO!$K31=1, 0, IF(COUNTRY_INFO!$K31=2, COUNTRY_INFO!$G31*0.2, COUNTRY_INFO!$G31))), 0))","v":16305.6},38871.1,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S31)","v":1},"Yes",{"$f":"IF($D31=0,0,IF(AND($G31>0,$H31<>\"Yes\"),D31,IF(AND($G31>0,$H31=\"Yes\"),COUNTRY_INFO!$F31,0)))","v":45131},null,16305.6,61436.6,112827.5,48916.800000000003,112827.5,null,112827.5,113]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A32=0,\" \",COUNTRY_INFO!A32))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B32=0,\" \",COUNTRY_INFO!B32))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C32=0,\" \",COUNTRY_INFO!C32))","v":"Murewa"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K32>0, IF(COUNTRY_INFO!$K32=4, 0, IF(COUNTRY_INFO!$K32=1, COUNTRY_INFO!$F32*0.33, IF(COUNTRY_INFO!$K32=2, COUNTRY_INFO!$F32*0.5, COUNTRY_INFO!$F32))), 0))","v":33802.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K32>0, IF(COUNTRY_INFO!$K32=4, 0, IF(COUNTRY_INFO!$K32=1, 0, IF(COUNTRY_INFO!$K32=2, COUNTRY_INFO!$G32*0.2, COUNTRY_INFO!$G32))), 0))","v":24425},58227.5,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S32)","v":1},"Yes",{"$f":"IF($D32=0,0,IF(AND($G32>0,$H32<>\"Yes\"),D32,IF(AND($G32>0,$H32=\"Yes\"),COUNTRY_INFO!$F32,0)))","v":67605},null,24425,92030,169012.5,73275,169012.5,null,169012.5,170]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A33=0,\" \",COUNTRY_INFO!A33))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B33=0,\" \",COUNTRY_INFO!B33))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C33=0,\" \",COUNTRY_INFO!C33))","v":"Mutoko"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K33>0, IF(COUNTRY_INFO!$K33=4, 0, IF(COUNTRY_INFO!$K33=1, COUNTRY_INFO!$F33*0.33, IF(COUNTRY_INFO!$K33=2, COUNTRY_INFO!$F33*0.5, COUNTRY_INFO!$F33))), 0))","v":24746},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K33>0, IF(COUNTRY_INFO!$K33=4, 0, IF(COUNTRY_INFO!$K33=1, 0, IF(COUNTRY_INFO!$K33=2, COUNTRY_INFO!$G33*0.2, COUNTRY_INFO!$G33))), 0))","v":17881},42627,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S33)","v":1},"Yes",{"$f":"IF($D33=0,0,IF(AND($G33>0,$H33<>\"Yes\"),D33,IF(AND($G33>0,$H33=\"Yes\"),COUNTRY_INFO!$F33,0)))","v":49492},null,17881,67373,123730,53643,123730,null,123730,124]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A34=0,\" \",COUNTRY_INFO!A34))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B34=0,\" \",COUNTRY_INFO!B34))","v":"Mashonaland East"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C34=0,\" \",COUNTRY_INFO!C34))","v":"Seke"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K34>0, IF(COUNTRY_INFO!$K34=4, 0, IF(COUNTRY_INFO!$K34=1, COUNTRY_INFO!$F34*0.33, IF(COUNTRY_INFO!$K34=2, COUNTRY_INFO!$F34*0.5, COUNTRY_INFO!$F34))), 0))","v":55019.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K34>0, IF(COUNTRY_INFO!$K34=4, 0, IF(COUNTRY_INFO!$K34=1, 0, IF(COUNTRY_INFO!$K34=2, COUNTRY_INFO!$G34*0.2, COUNTRY_INFO!$G34))), 0))","v":39756},94775.5,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S34)","v":1},"Yes",{"$f":"IF($D34=0,0,IF(AND($G34>0,$H34<>\"Yes\"),D34,IF(AND($G34>0,$H34=\"Yes\"),COUNTRY_INFO!$F34,0)))","v":110039},null,39756,149795,275097.5,119268,275097.5,null,275097.5,276]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A35=0,\" \",COUNTRY_INFO!A35))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B35=0,\" \",COUNTRY_INFO!B35))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C35=0,\" \",COUNTRY_INFO!C35))","v":"Chegutu"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K35>0, IF(COUNTRY_INFO!$K35=4, 0, IF(COUNTRY_INFO!$K35=1, COUNTRY_INFO!$F35*0.33, IF(COUNTRY_INFO!$K35=2, COUNTRY_INFO!$F35*0.5, COUNTRY_INFO!$F35))), 0))","v":46034},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K35>0, IF(COUNTRY_INFO!$K35=4, 0, IF(COUNTRY_INFO!$K35=1, 0, IF(COUNTRY_INFO!$K35=2, COUNTRY_INFO!$G35*0.2, COUNTRY_INFO!$G35))), 0))","v":33263.4},79297.399999999994,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S35)","v":0},"Yes",{"$f":"IF($D35=0,0,IF(AND($G35>0,$H35<>\"Yes\"),D35,IF(AND($G35>0,$H35=\"Yes\"),COUNTRY_INFO!$F35,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A36=0,\" \",COUNTRY_INFO!A36))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B36=0,\" \",COUNTRY_INFO!B36))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C36=0,\" \",COUNTRY_INFO!C36))","v":"Hurungwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K36>0, IF(COUNTRY_INFO!$K36=4, 0, IF(COUNTRY_INFO!$K36=1, COUNTRY_INFO!$F36*0.33, IF(COUNTRY_INFO!$K36=2, COUNTRY_INFO!$F36*0.5, COUNTRY_INFO!$F36))), 0))","v":60592},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K36>0, IF(COUNTRY_INFO!$K36=4, 0, IF(COUNTRY_INFO!$K36=1, 0, IF(COUNTRY_INFO!$K36=2, COUNTRY_INFO!$G36*0.2, COUNTRY_INFO!$G36))), 0))","v":43782.8},104374.8,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S36)","v":1},"Yes",{"$f":"IF($D36=0,0,IF(AND($G36>0,$H36<>\"Yes\"),D36,IF(AND($G36>0,$H36=\"Yes\"),COUNTRY_INFO!$F36,0)))","v":121184},null,43782.8,164966.79999999999,302960,131348.40000000002,302960,null,302960,303]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A37=0,\" \",COUNTRY_INFO!A37))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B37=0,\" \",COUNTRY_INFO!B37))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C37=0,\" \",COUNTRY_INFO!C37))","v":"Sanyati"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K37>0, IF(COUNTRY_INFO!$K37=4, 0, IF(COUNTRY_INFO!$K37=1, COUNTRY_INFO!$F37*0.33, IF(COUNTRY_INFO!$K37=2, COUNTRY_INFO!$F37*0.5, COUNTRY_INFO!$F37))), 0))","v":34778},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K37>0, IF(COUNTRY_INFO!$K37=4, 0, IF(COUNTRY_INFO!$K37=1, 0, IF(COUNTRY_INFO!$K37=2, COUNTRY_INFO!$G37*0.2, COUNTRY_INFO!$G37))), 0))","v":25129.800000000003},59907.8,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S37)","v":1},"Yes",{"$f":"IF($D37=0,0,IF(AND($G37>0,$H37<>\"Yes\"),D37,IF(AND($G37>0,$H37=\"Yes\"),COUNTRY_INFO!$F37,0)))","v":69556},null,25129.800000000003,94685.8,173890,75389.400000000009,173890,null,173890,174]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A38=0,\" \",COUNTRY_INFO!A38))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B38=0,\" \",COUNTRY_INFO!B38))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C38=0,\" \",COUNTRY_INFO!C38))","v":"Kariba"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K38>0, IF(COUNTRY_INFO!$K38=4, 0, IF(COUNTRY_INFO!$K38=1, COUNTRY_INFO!$F38*0.33, IF(COUNTRY_INFO!$K38=2, COUNTRY_INFO!$F38*0.5, COUNTRY_INFO!$F38))), 0))","v":11485},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K38>0, IF(COUNTRY_INFO!$K38=4, 0, IF(COUNTRY_INFO!$K38=1, 0, IF(COUNTRY_INFO!$K38=2, COUNTRY_INFO!$G38*0.2, COUNTRY_INFO!$G38))), 0))","v":8298.8000000000011},19783.800000000003,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S38)","v":1},"Yes",{"$f":"IF($D38=0,0,IF(AND($G38>0,$H38<>\"Yes\"),D38,IF(AND($G38>0,$H38=\"Yes\"),COUNTRY_INFO!$F38,0)))","v":22970},null,8298.8000000000011,31268.800000000003,57425,24896.400000000001,57425,null,57425,58]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A39=0,\" \",COUNTRY_INFO!A39))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B39=0,\" \",COUNTRY_INFO!B39))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C39=0,\" \",COUNTRY_INFO!C39))","v":"Makonde"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K39>0, IF(COUNTRY_INFO!$K39=4, 0, IF(COUNTRY_INFO!$K39=1, COUNTRY_INFO!$F39*0.33, IF(COUNTRY_INFO!$K39=2, COUNTRY_INFO!$F39*0.5, COUNTRY_INFO!$F39))), 0))","v":39198},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K39>0, IF(COUNTRY_INFO!$K39=4, 0, IF(COUNTRY_INFO!$K39=1, 0, IF(COUNTRY_INFO!$K39=2, COUNTRY_INFO!$G39*0.2, COUNTRY_INFO!$G39))), 0))","v":28323.800000000003},67521.8,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S39)","v":1},"Yes",{"$f":"IF($D39=0,0,IF(AND($G39>0,$H39<>\"Yes\"),D39,IF(AND($G39>0,$H39=\"Yes\"),COUNTRY_INFO!$F39,0)))","v":78396},null,28323.800000000003,106719.8,195990,84971.400000000009,195990,null,195990,196]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A40=0,\" \",COUNTRY_INFO!A40))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B40=0,\" \",COUNTRY_INFO!B40))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C40=0,\" \",COUNTRY_INFO!C40))","v":"Mhondoro-Ngezi"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K40>0, IF(COUNTRY_INFO!$K40=4, 0, IF(COUNTRY_INFO!$K40=1, COUNTRY_INFO!$F40*0.33, IF(COUNTRY_INFO!$K40=2, COUNTRY_INFO!$F40*0.5, COUNTRY_INFO!$F40))), 0))","v":17669.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K40>0, IF(COUNTRY_INFO!$K40=4, 0, IF(COUNTRY_INFO!$K40=1, 0, IF(COUNTRY_INFO!$K40=2, COUNTRY_INFO!$G40*0.2, COUNTRY_INFO!$G40))), 0))","v":12767.800000000001},30437.300000000003,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S40)","v":1},"Yes",{"$f":"IF($D40=0,0,IF(AND($G40>0,$H40<>\"Yes\"),D40,IF(AND($G40>0,$H40=\"Yes\"),COUNTRY_INFO!$F40,0)))","v":35339},null,12767.800000000001,48106.8,88347.5,38303.4,88347.5,null,88347.5,89]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A41=0,\" \",COUNTRY_INFO!A41))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B41=0,\" \",COUNTRY_INFO!B41))","v":"Mashonaland West"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C41=0,\" \",COUNTRY_INFO!C41))","v":"Zvimba"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K41>0, IF(COUNTRY_INFO!$K41=4, 0, IF(COUNTRY_INFO!$K41=1, COUNTRY_INFO!$F41*0.33, IF(COUNTRY_INFO!$K41=2, COUNTRY_INFO!$F41*0.5, COUNTRY_INFO!$F41))), 0))","v":44541.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K41>0, IF(COUNTRY_INFO!$K41=4, 0, IF(COUNTRY_INFO!$K41=1, 0, IF(COUNTRY_INFO!$K41=2, COUNTRY_INFO!$G41*0.2, COUNTRY_INFO!$G41))), 0))","v":32184.600000000002},{"$f":"SUM(D41:E41)","v":76726.100000000006},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S41)","v":1},"Yes",{"$f":"IF($D41=0,0,IF(AND($G41>0,$H41<>\"Yes\"),D41,IF(AND($G41>0,$H41=\"Yes\"),COUNTRY_INFO!$F41,0)))","v":89083},null,{"$f":"IF($G41>0,E41, 0)","v":32184.600000000002},{"$f":"IF($J41=0,SUM(I41,K41),SUM(J41,K41))","v":121267.6},{"$f":"IF($J41=0,$I41*2.5,$J41*2.5)","v":222707.5},{"$f":"$K41*3","v":96553.8},{"$f":"M41","v":222707.5},null,{"$f":"IF($O41>$P41,O41-P41,0)","v":222707.5},{"$f":"ROUNDUP($O41/1000,0)","v":223}]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A42=0,\" \",COUNTRY_INFO!A42))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B42=0,\" \",COUNTRY_INFO!B42))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C42=0,\" \",COUNTRY_INFO!C42))","v":"Binga"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K42>0, IF(COUNTRY_INFO!$K42=4, 0, IF(COUNTRY_INFO!$K42=1, COUNTRY_INFO!$F42*0.33, IF(COUNTRY_INFO!$K42=2, COUNTRY_INFO!$F42*0.5, COUNTRY_INFO!$F42))), 0))","v":15545.970000000001},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K42>0, IF(COUNTRY_INFO!$K42=4, 0, IF(COUNTRY_INFO!$K42=1, 0, IF(COUNTRY_INFO!$K42=2, COUNTRY_INFO!$G42*0.2, COUNTRY_INFO!$G42))), 0))","v":0},15545.970000000001,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S42)","v":0},"Yes",{"$f":"IF($D42=0,0,IF(AND($G42>0,$H42<>\"Yes\"),D42,IF(AND($G42>0,$H42=\"Yes\"),COUNTRY_INFO!$F42,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A43=0,\" \",COUNTRY_INFO!A43))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B43=0,\" \",COUNTRY_INFO!B43))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C43=0,\" \",COUNTRY_INFO!C43))","v":"Bubi"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K43>0, IF(COUNTRY_INFO!$K43=4, 0, IF(COUNTRY_INFO!$K43=1, COUNTRY_INFO!$F43*0.33, IF(COUNTRY_INFO!$K43=2, COUNTRY_INFO!$F43*0.5, COUNTRY_INFO!$F43))), 0))","v":0},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K43>0, IF(COUNTRY_INFO!$K43=4, 0, IF(COUNTRY_INFO!$K43=1, 0, IF(COUNTRY_INFO!$K43=2, COUNTRY_INFO!$G43*0.2, COUNTRY_INFO!$G43))), 0))","v":0},0,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S43)","v":0},"Yes",{"$f":"IF($D43=0,0,IF(AND($G43>0,$H43<>\"Yes\"),D43,IF(AND($G43>0,$H43=\"Yes\"),COUNTRY_INFO!$F43,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A44=0,\" \",COUNTRY_INFO!A44))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B44=0,\" \",COUNTRY_INFO!B44))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C44=0,\" \",COUNTRY_INFO!C44))","v":"Hwange"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K44>0, IF(COUNTRY_INFO!$K44=4, 0, IF(COUNTRY_INFO!$K44=1, COUNTRY_INFO!$F44*0.33, IF(COUNTRY_INFO!$K44=2, COUNTRY_INFO!$F44*0.5, COUNTRY_INFO!$F44))), 0))","v":22682},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K44>0, IF(COUNTRY_INFO!$K44=4, 0, IF(COUNTRY_INFO!$K44=1, 0, IF(COUNTRY_INFO!$K44=2, COUNTRY_INFO!$G44*0.2, COUNTRY_INFO!$G44))), 0))","v":16389.600000000002},39071.600000000006,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S44)","v":1},"Yes",{"$f":"IF($D44=0,0,IF(AND($G44>0,$H44<>\"Yes\"),D44,IF(AND($G44>0,$H44=\"Yes\"),COUNTRY_INFO!$F44,0)))","v":45364},null,16389.600000000002,61753.600000000006,113410,49168.800000000003,113410,null,113410,114]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A45=0,\" \",COUNTRY_INFO!A45))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B45=0,\" \",COUNTRY_INFO!B45))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C45=0,\" \",COUNTRY_INFO!C45))","v":"Lupane"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K45>0, IF(COUNTRY_INFO!$K45=4, 0, IF(COUNTRY_INFO!$K45=1, COUNTRY_INFO!$F45*0.33, IF(COUNTRY_INFO!$K45=2, COUNTRY_INFO!$F45*0.5, COUNTRY_INFO!$F45))), 0))","v":11194.92},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K45>0, IF(COUNTRY_INFO!$K45=4, 0, IF(COUNTRY_INFO!$K45=1, 0, IF(COUNTRY_INFO!$K45=2, COUNTRY_INFO!$G45*0.2, COUNTRY_INFO!$G45))), 0))","v":0},11194.92,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S45)","v":0},"Yes",{"$f":"IF($D45=0,0,IF(AND($G45>0,$H45<>\"Yes\"),D45,IF(AND($G45>0,$H45=\"Yes\"),COUNTRY_INFO!$F45,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A46=0,\" \",COUNTRY_INFO!A46))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B46=0,\" \",COUNTRY_INFO!B46))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C46=0,\" \",COUNTRY_INFO!C46))","v":"Nkayi"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K46>0, IF(COUNTRY_INFO!$K46=4, 0, IF(COUNTRY_INFO!$K46=1, COUNTRY_INFO!$F46*0.33, IF(COUNTRY_INFO!$K46=2, COUNTRY_INFO!$F46*0.5, COUNTRY_INFO!$F46))), 0))","v":12197.79},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K46>0, IF(COUNTRY_INFO!$K46=4, 0, IF(COUNTRY_INFO!$K46=1, 0, IF(COUNTRY_INFO!$K46=2, COUNTRY_INFO!$G46*0.2, COUNTRY_INFO!$G46))), 0))","v":0},12197.79,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S46)","v":0},"Yes",{"$f":"IF($D46=0,0,IF(AND($G46>0,$H46<>\"Yes\"),D46,IF(AND($G46>0,$H46=\"Yes\"),COUNTRY_INFO!$F46,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A47=0,\" \",COUNTRY_INFO!A47))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B47=0,\" \",COUNTRY_INFO!B47))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C47=0,\" \",COUNTRY_INFO!C47))","v":"Tsholotsho"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K47>0, IF(COUNTRY_INFO!$K47=4, 0, IF(COUNTRY_INFO!$K47=1, COUNTRY_INFO!$F47*0.33, IF(COUNTRY_INFO!$K47=2, COUNTRY_INFO!$F47*0.5, COUNTRY_INFO!$F47))), 0))","v":0},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K47>0, IF(COUNTRY_INFO!$K47=4, 0, IF(COUNTRY_INFO!$K47=1, 0, IF(COUNTRY_INFO!$K47=2, COUNTRY_INFO!$G47*0.2, COUNTRY_INFO!$G47))), 0))","v":0},0,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S47)","v":0},"Yes",{"$f":"IF($D47=0,0,IF(AND($G47>0,$H47<>\"Yes\"),D47,IF(AND($G47>0,$H47=\"Yes\"),COUNTRY_INFO!$F47,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A48=0,\" \",COUNTRY_INFO!A48))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B48=0,\" \",COUNTRY_INFO!B48))","v":"Matabeleland North"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C48=0,\" \",COUNTRY_INFO!C48))","v":"Umguza"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K48>0, IF(COUNTRY_INFO!$K48=4, 0, IF(COUNTRY_INFO!$K48=1, COUNTRY_INFO!$F48*0.33, IF(COUNTRY_INFO!$K48=2, COUNTRY_INFO!$F48*0.5, COUNTRY_INFO!$F48))), 0))","v":0},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K48>0, IF(COUNTRY_INFO!$K48=4, 0, IF(COUNTRY_INFO!$K48=1, 0, IF(COUNTRY_INFO!$K48=2, COUNTRY_INFO!$G48*0.2, COUNTRY_INFO!$G48))), 0))","v":0},0,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S48)","v":0},"Yes",{"$f":"IF($D48=0,0,IF(AND($G48>0,$H48<>\"Yes\"),D48,IF(AND($G48>0,$H48=\"Yes\"),COUNTRY_INFO!$F48,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A49=0,\" \",COUNTRY_INFO!A49))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B49=0,\" \",COUNTRY_INFO!B49))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C49=0,\" \",COUNTRY_INFO!C49))","v":"Beit Bridge"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K49>0, IF(COUNTRY_INFO!$K49=4, 0, IF(COUNTRY_INFO!$K49=1, COUNTRY_INFO!$F49*0.33, IF(COUNTRY_INFO!$K49=2, COUNTRY_INFO!$F49*0.5, COUNTRY_INFO!$F49))), 0))","v":13660.35},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K49>0, IF(COUNTRY_INFO!$K49=4, 0, IF(COUNTRY_INFO!$K49=1, 0, IF(COUNTRY_INFO!$K49=2, COUNTRY_INFO!$G49*0.2, COUNTRY_INFO!$G49))), 0))","v":0},13660.35,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S49)","v":0},"Yes",{"$f":"IF($D49=0,0,IF(AND($G49>0,$H49<>\"Yes\"),D49,IF(AND($G49>0,$H49=\"Yes\"),COUNTRY_INFO!$F49,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A50=0,\" \",COUNTRY_INFO!A50))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B50=0,\" \",COUNTRY_INFO!B50))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C50=0,\" \",COUNTRY_INFO!C50))","v":"Bulilima"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K50>0, IF(COUNTRY_INFO!$K50=4, 0, IF(COUNTRY_INFO!$K50=1, COUNTRY_INFO!$F50*0.33, IF(COUNTRY_INFO!$K50=2, COUNTRY_INFO!$F50*0.5, COUNTRY_INFO!$F50))), 0))","v":10121.76},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K50>0, IF(COUNTRY_INFO!$K50=4, 0, IF(COUNTRY_INFO!$K50=1, 0, IF(COUNTRY_INFO!$K50=2, COUNTRY_INFO!$G50*0.2, COUNTRY_INFO!$G50))), 0))","v":0},10121.76,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S50)","v":0},"Yes",{"$f":"IF($D50=0,0,IF(AND($G50>0,$H50<>\"Yes\"),D50,IF(AND($G50>0,$H50=\"Yes\"),COUNTRY_INFO!$F50,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A51=0,\" \",COUNTRY_INFO!A51))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B51=0,\" \",COUNTRY_INFO!B51))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C51=0,\" \",COUNTRY_INFO!C51))","v":"Gwanda"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K51>0, IF(COUNTRY_INFO!$K51=4, 0, IF(COUNTRY_INFO!$K51=1, COUNTRY_INFO!$F51*0.33, IF(COUNTRY_INFO!$K51=2, COUNTRY_INFO!$F51*0.5, COUNTRY_INFO!$F51))), 0))","v":23032},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K51>0, IF(COUNTRY_INFO!$K51=4, 0, IF(COUNTRY_INFO!$K51=1, 0, IF(COUNTRY_INFO!$K51=2, COUNTRY_INFO!$G51*0.2, COUNTRY_INFO!$G51))), 0))","v":16642.400000000001},39674.400000000001,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S51)","v":0},"Yes",{"$f":"IF($D51=0,0,IF(AND($G51>0,$H51<>\"Yes\"),D51,IF(AND($G51>0,$H51=\"Yes\"),COUNTRY_INFO!$F51,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A52=0,\" \",COUNTRY_INFO!A52))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B52=0,\" \",COUNTRY_INFO!B52))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C52=0,\" \",COUNTRY_INFO!C52))","v":"Insiza"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K52>0, IF(COUNTRY_INFO!$K52=4, 0, IF(COUNTRY_INFO!$K52=1, COUNTRY_INFO!$F52*0.33, IF(COUNTRY_INFO!$K52=2, COUNTRY_INFO!$F52*0.5, COUNTRY_INFO!$F52))), 0))","v":16991},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K52>0, IF(COUNTRY_INFO!$K52=4, 0, IF(COUNTRY_INFO!$K52=1, 0, IF(COUNTRY_INFO!$K52=2, COUNTRY_INFO!$G52*0.2, COUNTRY_INFO!$G52))), 0))","v":12277.400000000001},29268.400000000001,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S52)","v":1},"Yes",{"$f":"IF($D52=0,0,IF(AND($G52>0,$H52<>\"Yes\"),D52,IF(AND($G52>0,$H52=\"Yes\"),COUNTRY_INFO!$F52,0)))","v":33982},null,12277.400000000001,46259.4,84955,36832.200000000004,84955,null,84955,85]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A53=0,\" \",COUNTRY_INFO!A53))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B53=0,\" \",COUNTRY_INFO!B53))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C53=0,\" \",COUNTRY_INFO!C53))","v":"Mangwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K53>0, IF(COUNTRY_INFO!$K53=4, 0, IF(COUNTRY_INFO!$K53=1, COUNTRY_INFO!$F53*0.33, IF(COUNTRY_INFO!$K53=2, COUNTRY_INFO!$F53*0.5, COUNTRY_INFO!$F53))), 0))","v":0},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K53>0, IF(COUNTRY_INFO!$K53=4, 0, IF(COUNTRY_INFO!$K53=1, 0, IF(COUNTRY_INFO!$K53=2, COUNTRY_INFO!$G53*0.2, COUNTRY_INFO!$G53))), 0))","v":0},0,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S53)","v":0},"Yes",{"$f":"IF($D53=0,0,IF(AND($G53>0,$H53<>\"Yes\"),D53,IF(AND($G53>0,$H53=\"Yes\"),COUNTRY_INFO!$F53,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A54=0,\" \",COUNTRY_INFO!A54))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B54=0,\" \",COUNTRY_INFO!B54))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C54=0,\" \",COUNTRY_INFO!C54))","v":"Matobo"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K54>0, IF(COUNTRY_INFO!$K54=4, 0, IF(COUNTRY_INFO!$K54=1, COUNTRY_INFO!$F54*0.33, IF(COUNTRY_INFO!$K54=2, COUNTRY_INFO!$F54*0.5, COUNTRY_INFO!$F54))), 0))","v":0},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K54>0, IF(COUNTRY_INFO!$K54=4, 0, IF(COUNTRY_INFO!$K54=1, 0, IF(COUNTRY_INFO!$K54=2, COUNTRY_INFO!$G54*0.2, COUNTRY_INFO!$G54))), 0))","v":0},0,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S54)","v":0},"Yes",{"$f":"IF($D54=0,0,IF(AND($G54>0,$H54<>\"Yes\"),D54,IF(AND($G54>0,$H54=\"Yes\"),COUNTRY_INFO!$F54,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A55=0,\" \",COUNTRY_INFO!A55))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B55=0,\" \",COUNTRY_INFO!B55))","v":"Matabeleland South"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C55=0,\" \",COUNTRY_INFO!C55))","v":"Umzingwane"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K55>0, IF(COUNTRY_INFO!$K55=4, 0, IF(COUNTRY_INFO!$K55=1, COUNTRY_INFO!$F55*0.33, IF(COUNTRY_INFO!$K55=2, COUNTRY_INFO!$F55*0.5, COUNTRY_INFO!$F55))), 0))","v":7040.22},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K55>0, IF(COUNTRY_INFO!$K55=4, 0, IF(COUNTRY_INFO!$K55=1, 0, IF(COUNTRY_INFO!$K55=2, COUNTRY_INFO!$G55*0.2, COUNTRY_INFO!$G55))), 0))","v":0},7040.22,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S55)","v":0},"Yes",{"$f":"IF($D55=0,0,IF(AND($G55>0,$H55<>\"Yes\"),D55,IF(AND($G55>0,$H55=\"Yes\"),COUNTRY_INFO!$F55,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A56=0,\" \",COUNTRY_INFO!A56))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B56=0,\" \",COUNTRY_INFO!B56))","v":"Midlands"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C56=0,\" \",COUNTRY_INFO!C56))","v":"Chirumhanzi"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K56>0, IF(COUNTRY_INFO!$K56=4, 0, IF(COUNTRY_INFO!$K56=1, COUNTRY_INFO!$F56*0.33, IF(COUNTRY_INFO!$K56=2, COUNTRY_INFO!$F56*0.5, COUNTRY_INFO!$F56))), 0))","v":13607},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K56>0, IF(COUNTRY_INFO!$K56=4, 0, IF(COUNTRY_INFO!$K56=1, 0, IF(COUNTRY_INFO!$K56=2, COUNTRY_INFO!$G56*0.2, COUNTRY_INFO!$G56))), 0))","v":9832.2000000000007},23439.200000000001,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S56)","v":1},"Yes",{"$f":"IF($D56=0,0,IF(AND($G56>0,$H56<>\"Yes\"),D56,IF(AND($G56>0,$H56=\"Yes\"),COUNTRY_INFO!$F56,0)))","v":27214},null,9832.2000000000007,37046.199999999997,68035,29496.600000000002,68035,null,68035,69]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A57=0,\" \",COUNTRY_INFO!A57))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B57=0,\" \",COUNTRY_INFO!B57))","v":"Midlands"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C57=0,\" \",COUNTRY_INFO!C57))","v":"Gokwe North"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K57>0, IF(COUNTRY_INFO!$K57=4, 0, IF(COUNTRY_INFO!$K57=1, COUNTRY_INFO!$F57*0.33, IF(COUNTRY_INFO!$K57=2, COUNTRY_INFO!$F57*0.5, COUNTRY_INFO!$F57))), 0))","v":40702.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K57>0, IF(COUNTRY_INFO!$K57=4, 0, IF(COUNTRY_INFO!$K57=1, 0, IF(COUNTRY_INFO!$K57=2, COUNTRY_INFO!$G57*0.2, COUNTRY_INFO!$G57))), 0))","v":29410.800000000003},70113.3,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S57)","v":1},"Yes",{"$f":"IF($D57=0,0,IF(AND($G57>0,$H57<>\"Yes\"),D57,IF(AND($G57>0,$H57=\"Yes\"),COUNTRY_INFO!$F57,0)))","v":81405},null,29410.800000000003,110815.8,203512.5,88232.400000000009,203512.5,null,203512.5,204]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A58=0,\" \",COUNTRY_INFO!A58))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B58=0,\" \",COUNTRY_INFO!B58))","v":"Midlands"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C58=0,\" \",COUNTRY_INFO!C58))","v":"Gokwe South"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K58>0, IF(COUNTRY_INFO!$K58=4, 0, IF(COUNTRY_INFO!$K58=1, COUNTRY_INFO!$F58*0.33, IF(COUNTRY_INFO!$K58=2, COUNTRY_INFO!$F58*0.5, COUNTRY_INFO!$F58))), 0))","v":36887.4},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K58>0, IF(COUNTRY_INFO!$K58=4, 0, IF(COUNTRY_INFO!$K58=1, 0, IF(COUNTRY_INFO!$K58=2, COUNTRY_INFO!$G58*0.2, COUNTRY_INFO!$G58))), 0))","v":0},36887.4,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S58)","v":0},"Yes",{"$f":"IF($D58=0,0,IF(AND($G58>0,$H58<>\"Yes\"),D58,IF(AND($G58>0,$H58=\"Yes\"),COUNTRY_INFO!$F58,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A59=0,\" \",COUNTRY_INFO!A59))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B59=0,\" \",COUNTRY_INFO!B59))","v":"Midlands"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C59=0,\" \",COUNTRY_INFO!C59))","v":"Gweru"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K59>0, IF(COUNTRY_INFO!$K59=4, 0, IF(COUNTRY_INFO!$K59=1, COUNTRY_INFO!$F59*0.33, IF(COUNTRY_INFO!$K59=2, COUNTRY_INFO!$F59*0.5, COUNTRY_INFO!$F59))), 0))","v":42280.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K59>0, IF(COUNTRY_INFO!$K59=4, 0, IF(COUNTRY_INFO!$K59=1, 0, IF(COUNTRY_INFO!$K59=2, COUNTRY_INFO!$G59*0.2, COUNTRY_INFO!$G59))), 0))","v":30551},72831.5,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S59)","v":1},"Yes",{"$f":"IF($D59=0,0,IF(AND($G59>0,$H59<>\"Yes\"),D59,IF(AND($G59>0,$H59=\"Yes\"),COUNTRY_INFO!$F59,0)))","v":84561},null,30551,115112,211402.5,91653,211402.5,null,211402.5,212]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A60=0,\" \",COUNTRY_INFO!A60))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B60=0,\" \",COUNTRY_INFO!B60))","v":"Midlands"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C60=0,\" \",COUNTRY_INFO!C60))","v":"Kwekwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K60>0, IF(COUNTRY_INFO!$K60=4, 0, IF(COUNTRY_INFO!$K60=1, COUNTRY_INFO!$F60*0.33, IF(COUNTRY_INFO!$K60=2, COUNTRY_INFO!$F60*0.5, COUNTRY_INFO!$F60))), 0))","v":52760.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K60>0, IF(COUNTRY_INFO!$K60=4, 0, IF(COUNTRY_INFO!$K60=1, 0, IF(COUNTRY_INFO!$K60=2, COUNTRY_INFO!$G60*0.2, COUNTRY_INFO!$G60))), 0))","v":38123.800000000003},90884.3,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S60)","v":0},"Yes",{"$f":"IF($D60=0,0,IF(AND($G60>0,$H60<>\"Yes\"),D60,IF(AND($G60>0,$H60=\"Yes\"),COUNTRY_INFO!$F60,0)))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A61=0,\" \",COUNTRY_INFO!A61))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B61=0,\" \",COUNTRY_INFO!B61))","v":"Midlands"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C61=0,\" \",COUNTRY_INFO!C61))","v":"Mberengwa"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K61>0, IF(COUNTRY_INFO!$K61=4, 0, IF(COUNTRY_INFO!$K61=1, COUNTRY_INFO!$F61*0.33, IF(COUNTRY_INFO!$K61=2, COUNTRY_INFO!$F61*0.5, COUNTRY_INFO!$F61))), 0))","v":31457},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K61>0, IF(COUNTRY_INFO!$K61=4, 0, IF(COUNTRY_INFO!$K61=1, 0, IF(COUNTRY_INFO!$K61=2, COUNTRY_INFO!$G61*0.2, COUNTRY_INFO!$G61))), 0))","v":22730.2},54187.199999999997,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S61)","v":1},"Yes",{"$f":"IF($D61=0,0,IF(AND($G61>0,$H61<>\"Yes\"),D61,IF(AND($G61>0,$H61=\"Yes\"),COUNTRY_INFO!$F61,0)))","v":62914},null,22730.2,85644.2,157285,68190.600000000006,157285,null,157285,158]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A62=0,\" \",COUNTRY_INFO!A62))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B62=0,\" \",COUNTRY_INFO!B62))","v":"Midlands"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C62=0,\" \",COUNTRY_INFO!C62))","v":"Shurugwi"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K62>0, IF(COUNTRY_INFO!$K62=4, 0, IF(COUNTRY_INFO!$K62=1, COUNTRY_INFO!$F62*0.33, IF(COUNTRY_INFO!$K62=2, COUNTRY_INFO!$F62*0.5, COUNTRY_INFO!$F62))), 0))","v":33691},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K62>0, IF(COUNTRY_INFO!$K62=4, 0, IF(COUNTRY_INFO!$K62=1, 0, IF(COUNTRY_INFO!$K62=2, COUNTRY_INFO!$G62*0.2, COUNTRY_INFO!$G62))), 0))","v":60861},94552,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S62)","v":1},"Yes",{"$f":"IF($D62=0,0,IF(AND($G62>0,$H62<>\"Yes\"),D62,IF(AND($G62>0,$H62=\"Yes\"),COUNTRY_INFO!$F62,0)))","v":33691},null,60861,94552,84227.5,182583,84227.5,null,84227.5,85]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A63=0,\" \",COUNTRY_INFO!A63))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B63=0,\" \",COUNTRY_INFO!B63))","v":"Midlands"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C63=0,\" \",COUNTRY_INFO!C63))","v":"Zvishavane"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K63>0, IF(COUNTRY_INFO!$K63=4, 0, IF(COUNTRY_INFO!$K63=1, COUNTRY_INFO!$F63*0.33, IF(COUNTRY_INFO!$K63=2, COUNTRY_INFO!$F63*0.5, COUNTRY_INFO!$F63))), 0))","v":19939},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K63>0, IF(COUNTRY_INFO!$K63=4, 0, IF(COUNTRY_INFO!$K63=1, 0, IF(COUNTRY_INFO!$K63=2, COUNTRY_INFO!$G63*0.2, COUNTRY_INFO!$G63))), 0))","v":14407.6},34346.6,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S63)","v":1},"Yes",{"$f":"IF($D63=0,0,IF(AND($G63>0,$H63<>\"Yes\"),D63,IF(AND($G63>0,$H63=\"Yes\"),COUNTRY_INFO!$F63,0)))","v":39878},null,14407.6,54285.599999999999,99695,43222.8,99695,null,99695,100]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A64=0,\" \",COUNTRY_INFO!A64))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B64=0,\" \",COUNTRY_INFO!B64))","v":"Masvingo"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C64=0,\" \",COUNTRY_INFO!C64))","v":"Bikita"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K64>0, IF(COUNTRY_INFO!$K64=4, 0, IF(COUNTRY_INFO!$K64=1, COUNTRY_INFO!$F64*0.33, IF(COUNTRY_INFO!$K64=2, COUNTRY_INFO!$F64*0.5, COUNTRY_INFO!$F64))), 0))","v":27494},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K64>0, IF(COUNTRY_INFO!$K64=4, 0, IF(COUNTRY_INFO!$K64=1, 0, IF(COUNTRY_INFO!$K64=2, COUNTRY_INFO!$G64*0.2, COUNTRY_INFO!$G64))), 0))","v":19866.800000000003},47360.800000000003,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S64)","v":1},"Yes",{"$f":"IF($D64=0,0,IF(AND($G64>0,$H64<>\"Yes\"),D64,IF(AND($G64>0,$H64=\"Yes\"),COUNTRY_INFO!$F64,0)))","v":54988},null,19866.800000000003,74854.8,137470,59600.400000000009,137470,null,137470,138]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A65=0,\" \",COUNTRY_INFO!A65))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B65=0,\" \",COUNTRY_INFO!B65))","v":"Masvingo"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C65=0,\" \",COUNTRY_INFO!C65))","v":"Chiredzi"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K65>0, IF(COUNTRY_INFO!$K65=4, 0, IF(COUNTRY_INFO!$K65=1, COUNTRY_INFO!$F65*0.33, IF(COUNTRY_INFO!$K65=2, COUNTRY_INFO!$F65*0.5, COUNTRY_INFO!$F65))), 0))","v":103709},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K65>0, IF(COUNTRY_INFO!$K65=4, 0, IF(COUNTRY_INFO!$K65=1, 0, IF(COUNTRY_INFO!$K65=2, COUNTRY_INFO!$G65*0.2, COUNTRY_INFO!$G65))), 0))","v":187346},291055,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S65)","v":1},"Yes",{"$f":"IF($D65=0,0,IF(AND($G65>0,$H65<>\"Yes\"),D65,IF(AND($G65>0,$H65=\"Yes\"),COUNTRY_INFO!$F65,0)))","v":103709},null,187346,291055,259272.5,562038,259272.5,null,259272.5,260]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A66=0,\" \",COUNTRY_INFO!A66))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B66=0,\" \",COUNTRY_INFO!B66))","v":"Masvingo"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C66=0,\" \",COUNTRY_INFO!C66))","v":"Chivi"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K66>0, IF(COUNTRY_INFO!$K66=4, 0, IF(COUNTRY_INFO!$K66=1, COUNTRY_INFO!$F66*0.33, IF(COUNTRY_INFO!$K66=2, COUNTRY_INFO!$F66*0.5, COUNTRY_INFO!$F66))), 0))","v":28119.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K66>0, IF(COUNTRY_INFO!$K66=4, 0, IF(COUNTRY_INFO!$K66=1, 0, IF(COUNTRY_INFO!$K66=2, COUNTRY_INFO!$G66*0.2, COUNTRY_INFO!$G66))), 0))","v":20318.600000000002},48438.100000000006,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S66)","v":1},"Yes",{"$f":"IF($D66=0,0,IF(AND($G66>0,$H66<>\"Yes\"),D66,IF(AND($G66>0,$H66=\"Yes\"),COUNTRY_INFO!$F66,0)))","v":56239},null,20318.600000000002,76557.600000000006,140597.5,60955.8,140597.5,null,140597.5,141]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A67=0,\" \",COUNTRY_INFO!A67))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B67=0,\" \",COUNTRY_INFO!B67))","v":"Masvingo"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C67=0,\" \",COUNTRY_INFO!C67))","v":"Gutu"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K67>0, IF(COUNTRY_INFO!$K67=4, 0, IF(COUNTRY_INFO!$K67=1, COUNTRY_INFO!$F67*0.33, IF(COUNTRY_INFO!$K67=2, COUNTRY_INFO!$F67*0.5, COUNTRY_INFO!$F67))), 0))","v":34391},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K67>0, IF(COUNTRY_INFO!$K67=4, 0, IF(COUNTRY_INFO!$K67=1, 0, IF(COUNTRY_INFO!$K67=2, COUNTRY_INFO!$G67*0.2, COUNTRY_INFO!$G67))), 0))","v":24850.400000000001},59241.4,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S67)","v":1},"Yes",{"$f":"IF($D67=0,0,IF(AND($G67>0,$H67<>\"Yes\"),D67,IF(AND($G67>0,$H67=\"Yes\"),COUNTRY_INFO!$F67,0)))","v":68782},null,24850.400000000001,93632.4,171955,74551.200000000012,171955,null,171955,172]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A68=0,\" \",COUNTRY_INFO!A68))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B68=0,\" \",COUNTRY_INFO!B68))","v":"Masvingo"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C68=0,\" \",COUNTRY_INFO!C68))","v":"Masvingo"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K68>0, IF(COUNTRY_INFO!$K68=4, 0, IF(COUNTRY_INFO!$K68=1, COUNTRY_INFO!$F68*0.33, IF(COUNTRY_INFO!$K68=2, COUNTRY_INFO!$F68*0.5, COUNTRY_INFO!$F68))), 0))","v":50651},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K68>0, IF(COUNTRY_INFO!$K68=4, 0, IF(COUNTRY_INFO!$K68=1, 0, IF(COUNTRY_INFO!$K68=2, COUNTRY_INFO!$G68*0.2, COUNTRY_INFO!$G68))), 0))","v":36599.599999999999},87250.6,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S68)","v":1},"Yes",{"$f":"IF($D68=0,0,IF(AND($G68>0,$H68<>\"Yes\"),D68,IF(AND($G68>0,$H68=\"Yes\"),COUNTRY_INFO!$F68,0)))","v":101302},null,36599.599999999999,137901.6,253255,109798.79999999999,253255,null,253255,254]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A69=0,\" \",COUNTRY_INFO!A69))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B69=0,\" \",COUNTRY_INFO!B69))","v":"Masvingo"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C69=0,\" \",COUNTRY_INFO!C69))","v":"Mwenezi"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K69>0, IF(COUNTRY_INFO!$K69=4, 0, IF(COUNTRY_INFO!$K69=1, COUNTRY_INFO!$F69*0.33, IF(COUNTRY_INFO!$K69=2, COUNTRY_INFO!$F69*0.5, COUNTRY_INFO!$F69))), 0))","v":28279.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K69>0, IF(COUNTRY_INFO!$K69=4, 0, IF(COUNTRY_INFO!$K69=1, 0, IF(COUNTRY_INFO!$K69=2, COUNTRY_INFO!$G69*0.2, COUNTRY_INFO!$G69))), 0))","v":20434.2},48713.7,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S69)","v":1},"Yes",{"$f":"IF($D69=0,0,IF(AND($G69>0,$H69<>\"Yes\"),D69,IF(AND($G69>0,$H69=\"Yes\"),COUNTRY_INFO!$F69,0)))","v":56559},null,20434.2,76993.2,141397.5,61302.600000000006,141397.5,null,141397.5,142]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A70=0,\" \",COUNTRY_INFO!A70))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B70=0,\" \",COUNTRY_INFO!B70))","v":"Masvingo"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C70=0,\" \",COUNTRY_INFO!C70))","v":"Zaka"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K70>0, IF(COUNTRY_INFO!$K70=4, 0, IF(COUNTRY_INFO!$K70=1, COUNTRY_INFO!$F70*0.33, IF(COUNTRY_INFO!$K70=2, COUNTRY_INFO!$F70*0.5, COUNTRY_INFO!$F70))), 0))","v":30702.5},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K70>0, IF(COUNTRY_INFO!$K70=4, 0, IF(COUNTRY_INFO!$K70=1, 0, IF(COUNTRY_INFO!$K70=2, COUNTRY_INFO!$G70*0.2, COUNTRY_INFO!$G70))), 0))","v":22185},52887.5,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S70)","v":1},"Yes",{"$f":"IF($D70=0,0,IF(AND($G70>0,$H70<>\"Yes\"),D70,IF(AND($G70>0,$H70=\"Yes\"),COUNTRY_INFO!$F70,0)))","v":61405},null,22185,83590,153512.5,66555,153512.5,null,153512.5,154]
[{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!A71=0,\" \",COUNTRY_INFO!A71))","v":"Zimbabwe"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!B71=0,\" \",COUNTRY_INFO!B71))","v":"Bulawayo"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\",\" \", IF(COUNTRY_INFO!C71=0,\" \",COUNTRY_INFO!C71))","v":"Bulawayo"},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K71>0, IF(COUNTRY_INFO!$K71=4, 0, IF(COUNTRY_INFO!$K71=1, COUNTRY_INFO!$F71*0.33, IF(COUNTRY_INFO!$K71=2, COUNTRY_INFO!$F71*0.5, COUNTRY_INFO!$F71))), 0))","v":73022.070000000007},{"$f":"IF(INTRO!$E$43=\"Non-endemic\", 0, IF(COUNTRY_INFO!$K71>0, IF(COUNTRY_INFO!$K71=4, 0, IF(COUNTRY_INFO!$K71=1, 0, IF(COUNTRY_INFO!$K71=2, COUNTRY_INFO!$G71*0.2, COUNTRY_INFO!$G71))), 0))","v":0},73022.070000000007,{"$f":"IF(INTRO!$E$43=\"Non-endemic\", \"Not required\", COUNTRY_INFO!S71)","v":0},"Yes",{"$f":"IF($D71=0,0,IF(AND($G71>0,$H71<>\"Yes\"),D71,IF(AND($G71>0,$H71=\"Yes\"),COUNTRY_INFO!$F71,0)))","v":0},null,0,0,0,0,0,null,0,0]

{"sheet":"IVM","index":5,"n_rows":71,"n_cols":17,"rows_kept":71,"cut":false,"hidden":true,"merged":[[6,14,7,14],[5,3,7,3],[6,15,7,15],[6,16,7,16],[6,10,7,10],[6,11,7,11],[6,12,7,12],[6,13,7,13],[3,0,3,2],[3,4,3,5],[6,4,7,4],[6,5,7,5],[5,10,5,16],[6,0,7,0],[6,1,7,1],[6,2,7,2],[6,7,6,9],[5,0,5,2],[5,4,5,5],[5,6,5,9]]}
["Ivermectin (IVM)"]
["Administrative structure, eligible population by age group, treatment plan and information about tablets"]
[]
["TOTAL",null,null,{"$f":"SUM(D$9:D$1000)","v":0},null,null,{"$f":"SUM(G$9:G$1000)","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["Country administrative structure",null,null,"Population requiring treatment with IVM","Treatment plan",null,"Target population",null,null,null,"Ivermectin (IVM)"]
["Country","Province/State","District",null,"LF","Oncho","LF","Oncho",null,null,"LF only","Oncho only","LF+Oncho","Total required","Remaining in stock","Tablets to be procured","Bottles (3mg)\n500 tablets"]
[null,null,null,null,null,null,null,"in the district","in villages","total"]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A9=0,\" \",COUNTRY_INFO!A9))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B9=0,\" \",COUNTRY_INFO!B9))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C9=0,\" \",COUNTRY_INFO!C9))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H9=1,COUNTRY_INFO!F9+COUNTRY_INFO!G9,0),IF(COUNTRY_INFO!$H9=1,COUNTRY_INFO!F9+COUNTRY_INFO!G9,IF(COUNTRY_INFO!$I9=1,IF(COUNTRY_INFO!M9>=(COUNTRY_INFO!F9+COUNTRY_INFO!G9),COUNTRY_INFO!F9+COUNTRY_INFO!G9,COUNTRY_INFO!$M9),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P9))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q9,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H9=1, IF($E9=1,$D9, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I9=1,$F9<>0),IF(COUNTRY_INFO!M9>=(COUNTRY_INFO!F9+COUNTRY_INFO!G9),COUNTRY_INFO!F9+COUNTRY_INFO!G9,COUNTRY_INFO!$M9), 0))","v":0},null,{"$f":"IF(I9=0,H9,IF(I9>H9,H9,I9))","v":0},{"$f":"IF(G9<J9,0,IF($E9=1, (G9-J9)*2.8, 0))","v":0},{"$f":"IF($E9<$F9, J9*(F9-E9)*2.8, 0)","v":0},{"$f":"IF(AND($E9=1, $F9<>0), J9*2.8, 0)","v":0},{"$f":"SUM(K9:M9)","v":0},null,{"$f":"IF($N9>$O9,$N9-$O9,0)","v":0},{"$f":"ROUNDUP($N9/500,0)","v":0}]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A10=0,\" \",COUNTRY_INFO!A10))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B10=0,\" \",COUNTRY_INFO!B10))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C10=0,\" \",COUNTRY_INFO!C10))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H10=1,COUNTRY_INFO!F10+COUNTRY_INFO!G10,0),IF(COUNTRY_INFO!$H10=1,COUNTRY_INFO!F10+COUNTRY_INFO!G10,IF(COUNTRY_INFO!$I10=1,IF(COUNTRY_INFO!M10>=(COUNTRY_INFO!F10+COUNTRY_INFO!G10),COUNTRY_INFO!F10+COUNTRY_INFO!G10,COUNTRY_INFO!$M10),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P10))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q10,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H10=1, IF($E10=1,$D10, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I10=1,$F10<>0),IF(COUNTRY_INFO!M10>=(COUNTRY_INFO!F10+COUNTRY_INFO!G10),COUNTRY_INFO!F10+COUNTRY_INFO!G10,COUNTRY_INFO!$M10), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A11=0,\" \",COUNTRY_INFO!A11))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B11=0,\" \",COUNTRY_INFO!B11))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C11=0,\" \",COUNTRY_INFO!C11))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H11=1,COUNTRY_INFO!F11+COUNTRY_INFO!G11,0),IF(COUNTRY_INFO!$H11=1,COUNTRY_INFO!F11+COUNTRY_INFO!G11,IF(COUNTRY_INFO!$I11=1,IF(COUNTRY_INFO!M11>=(COUNTRY_INFO!F11+COUNTRY_INFO!G11),COUNTRY_INFO!F11+COUNTRY_INFO!G11,COUNTRY_INFO!$M11),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P11))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q11,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H11=1, IF($E11=1,$D11, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I11=1,$F11<>0),IF(COUNTRY_INFO!M11>=(COUNTRY_INFO!F11+COUNTRY_INFO!G11),COUNTRY_INFO!F11+COUNTRY_INFO!G11,COUNTRY_INFO!$M11), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A12=0,\" \",COUNTRY_INFO!A12))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B12=0,\" \",COUNTRY_INFO!B12))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C12=0,\" \",COUNTRY_INFO!C12))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H12=1,COUNTRY_INFO!F12+COUNTRY_INFO!G12,0),IF(COUNTRY_INFO!$H12=1,COUNTRY_INFO!F12+COUNTRY_INFO!G12,IF(COUNTRY_INFO!$I12=1,IF(COUNTRY_INFO!M12>=(COUNTRY_INFO!F12+COUNTRY_INFO!G12),COUNTRY_INFO!F12+COUNTRY_INFO!G12,COUNTRY_INFO!$M12),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P12))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q12,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H12=1, IF($E12=1,$D12, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I12=1,$F12<>0),IF(COUNTRY_INFO!M12>=(COUNTRY_INFO!F12+COUNTRY_INFO!G12),COUNTRY_INFO!F12+COUNTRY_INFO!G12,COUNTRY_INFO!$M12), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A13=0,\" \",COUNTRY_INFO!A13))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B13=0,\" \",COUNTRY_INFO!B13))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C13=0,\" \",COUNTRY_INFO!C13))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H13=1,COUNTRY_INFO!F13+COUNTRY_INFO!G13,0),IF(COUNTRY_INFO!$H13=1,COUNTRY_INFO!F13+COUNTRY_INFO!G13,IF(COUNTRY_INFO!$I13=1,IF(COUNTRY_INFO!M13>=(COUNTRY_INFO!F13+COUNTRY_INFO!G13),COUNTRY_INFO!F13+COUNTRY_INFO!G13,COUNTRY_INFO!$M13),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P13))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q13,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H13=1, IF($E13=1,$D13, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I13=1,$F13<>0),IF(COUNTRY_INFO!M13>=(COUNTRY_INFO!F13+COUNTRY_INFO!G13),COUNTRY_INFO!F13+COUNTRY_INFO!G13,COUNTRY_INFO!$M13), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A14=0,\" \",COUNTRY_INFO!A14))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B14=0,\" \",COUNTRY_INFO!B14))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C14=0,\" \",COUNTRY_INFO!C14))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H14=1,COUNTRY_INFO!F14+COUNTRY_INFO!G14,0),IF(COUNTRY_INFO!$H14=1,COUNTRY_INFO!F14+COUNTRY_INFO!G14,IF(COUNTRY_INFO!$I14=1,IF(COUNTRY_INFO!M14>=(COUNTRY_INFO!F14+COUNTRY_INFO!G14),COUNTRY_INFO!F14+COUNTRY_INFO!G14,COUNTRY_INFO!$M14),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P14))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q14,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H14=1, IF($E14=1,$D14, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I14=1,$F14<>0),IF(COUNTRY_INFO!M14>=(COUNTRY_INFO!F14+COUNTRY_INFO!G14),COUNTRY_INFO!F14+COUNTRY_INFO!G14,COUNTRY_INFO!$M14), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A15=0,\" \",COUNTRY_INFO!A15))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B15=0,\" \",COUNTRY_INFO!B15))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C15=0,\" \",COUNTRY_INFO!C15))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H15=1,COUNTRY_INFO!F15+COUNTRY_INFO!G15,0),IF(COUNTRY_INFO!$H15=1,COUNTRY_INFO!F15+COUNTRY_INFO!G15,IF(COUNTRY_INFO!$I15=1,IF(COUNTRY_INFO!M15>=(COUNTRY_INFO!F15+COUNTRY_INFO!G15),COUNTRY_INFO!F15+COUNTRY_INFO!G15,COUNTRY_INFO!$M15),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P15))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q15,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H15=1, IF($E15=1,$D15, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I15=1,$F15<>0),IF(COUNTRY_INFO!M15>=(COUNTRY_INFO!F15+COUNTRY_INFO!G15),COUNTRY_INFO!F15+COUNTRY_INFO!G15,COUNTRY_INFO!$M15), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A16=0,\" \",COUNTRY_INFO!A16))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B16=0,\" \",COUNTRY_INFO!B16))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C16=0,\" \",COUNTRY_INFO!C16))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H16=1,COUNTRY_INFO!F16+COUNTRY_INFO!G16,0),IF(COUNTRY_INFO!$H16=1,COUNTRY_INFO!F16+COUNTRY_INFO!G16,IF(COUNTRY_INFO!$I16=1,IF(COUNTRY_INFO!M16>=(COUNTRY_INFO!F16+COUNTRY_INFO!G16),COUNTRY_INFO!F16+COUNTRY_INFO!G16,COUNTRY_INFO!$M16),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P16))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q16,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H16=1, IF($E16=1,$D16, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I16=1,$F16<>0),IF(COUNTRY_INFO!M16>=(COUNTRY_INFO!F16+COUNTRY_INFO!G16),COUNTRY_INFO!F16+COUNTRY_INFO!G16,COUNTRY_INFO!$M16), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A17=0,\" \",COUNTRY_INFO!A17))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B17=0,\" \",COUNTRY_INFO!B17))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C17=0,\" \",COUNTRY_INFO!C17))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H17=1,COUNTRY_INFO!F17+COUNTRY_INFO!G17,0),IF(COUNTRY_INFO!$H17=1,COUNTRY_INFO!F17+COUNTRY_INFO!G17,IF(COUNTRY_INFO!$I17=1,IF(COUNTRY_INFO!M17>=(COUNTRY_INFO!F17+COUNTRY_INFO!G17),COUNTRY_INFO!F17+COUNTRY_INFO!G17,COUNTRY_INFO!$M17),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P17))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q17,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H17=1, IF($E17=1,$D17, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I17=1,$F17<>0),IF(COUNTRY_INFO!M17>=(COUNTRY_INFO!F17+COUNTRY_INFO!G17),COUNTRY_INFO!F17+COUNTRY_INFO!G17,COUNTRY_INFO!$M17), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A18=0,\" \",COUNTRY_INFO!A18))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B18=0,\" \",COUNTRY_INFO!B18))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C18=0,\" \",COUNTRY_INFO!C18))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H18=1,COUNTRY_INFO!F18+COUNTRY_INFO!G18,0),IF(COUNTRY_INFO!$H18=1,COUNTRY_INFO!F18+COUNTRY_INFO!G18,IF(COUNTRY_INFO!$I18=1,IF(COUNTRY_INFO!M18>=(COUNTRY_INFO!F18+COUNTRY_INFO!G18),COUNTRY_INFO!F18+COUNTRY_INFO!G18,COUNTRY_INFO!$M18),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P18))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q18,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H18=1, IF($E18=1,$D18, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I18=1,$F18<>0),IF(COUNTRY_INFO!M18>=(COUNTRY_INFO!F18+COUNTRY_INFO!G18),COUNTRY_INFO!F18+COUNTRY_INFO!G18,COUNTRY_INFO!$M18), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A19=0,\" \",COUNTRY_INFO!A19))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B19=0,\" \",COUNTRY_INFO!B19))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C19=0,\" \",COUNTRY_INFO!C19))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H19=1,COUNTRY_INFO!F19+COUNTRY_INFO!G19,0),IF(COUNTRY_INFO!$H19=1,COUNTRY_INFO!F19+COUNTRY_INFO!G19,IF(COUNTRY_INFO!$I19=1,IF(COUNTRY_INFO!M19>=(COUNTRY_INFO!F19+COUNTRY_INFO!G19),COUNTRY_INFO!F19+COUNTRY_INFO!G19,COUNTRY_INFO!$M19),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P19))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q19,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H19=1, IF($E19=1,$D19, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I19=1,$F19<>0),IF(COUNTRY_INFO!M19>=(COUNTRY_INFO!F19+COUNTRY_INFO!G19),COUNTRY_INFO!F19+COUNTRY_INFO!G19,COUNTRY_INFO!$M19), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A20=0,\" \",COUNTRY_INFO!A20))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B20=0,\" \",COUNTRY_INFO!B20))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C20=0,\" \",COUNTRY_INFO!C20))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H20=1,COUNTRY_INFO!F20+COUNTRY_INFO!G20,0),IF(COUNTRY_INFO!$H20=1,COUNTRY_INFO!F20+COUNTRY_INFO!G20,IF(COUNTRY_INFO!$I20=1,IF(COUNTRY_INFO!M20>=(COUNTRY_INFO!F20+COUNTRY_INFO!G20),COUNTRY_INFO!F20+COUNTRY_INFO!G20,COUNTRY_INFO!$M20),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P20))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q20,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H20=1, IF($E20=1,$D20, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I20=1,$F20<>0),IF(COUNTRY_INFO!M20>=(COUNTRY_INFO!F20+COUNTRY_INFO!G20),COUNTRY_INFO!F20+COUNTRY_INFO!G20,COUNTRY_INFO!$M20), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A21=0,\" \",COUNTRY_INFO!A21))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B21=0,\" \",COUNTRY_INFO!B21))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C21=0,\" \",COUNTRY_INFO!C21))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H21=1,COUNTRY_INFO!F21+COUNTRY_INFO!G21,0),IF(COUNTRY_INFO!$H21=1,COUNTRY_INFO!F21+COUNTRY_INFO!G21,IF(COUNTRY_INFO!$I21=1,IF(COUNTRY_INFO!M21>=(COUNTRY_INFO!F21+COUNTRY_INFO!G21),COUNTRY_INFO!F21+COUNTRY_INFO!G21,COUNTRY_INFO!$M21),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P21))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q21,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H21=1, IF($E21=1,$D21, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I21=1,$F21<>0),IF(COUNTRY_INFO!M21>=(COUNTRY_INFO!F21+COUNTRY_INFO!G21),COUNTRY_INFO!F21+COUNTRY_INFO!G21,COUNTRY_INFO!$M21), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A22=0,\" \",COUNTRY_INFO!A22))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B22=0,\" \",COUNTRY_INFO!B22))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C22=0,\" \",COUNTRY_INFO!C22))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H22=1,COUNTRY_INFO!F22+COUNTRY_INFO!G22,0),IF(COUNTRY_INFO!$H22=1,COUNTRY_INFO!F22+COUNTRY_INFO!G22,IF(COUNTRY_INFO!$I22=1,IF(COUNTRY_INFO!M22>=(COUNTRY_INFO!F22+COUNTRY_INFO!G22),COUNTRY_INFO!F22+COUNTRY_INFO!G22,COUNTRY_INFO!$M22),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P22))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q22,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H22=1, IF($E22=1,$D22, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I22=1,$F22<>0),IF(COUNTRY_INFO!M22>=(COUNTRY_INFO!F22+COUNTRY_INFO!G22),COUNTRY_INFO!F22+COUNTRY_INFO!G22,COUNTRY_INFO!$M22), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A23=0,\" \",COUNTRY_INFO!A23))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B23=0,\" \",COUNTRY_INFO!B23))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C23=0,\" \",COUNTRY_INFO!C23))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H23=1,COUNTRY_INFO!F23+COUNTRY_INFO!G23,0),IF(COUNTRY_INFO!$H23=1,COUNTRY_INFO!F23+COUNTRY_INFO!G23,IF(COUNTRY_INFO!$I23=1,IF(COUNTRY_INFO!M23>=(COUNTRY_INFO!F23+COUNTRY_INFO!G23),COUNTRY_INFO!F23+COUNTRY_INFO!G23,COUNTRY_INFO!$M23),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P23))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q23,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H23=1, IF($E23=1,$D23, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I23=1,$F23<>0),IF(COUNTRY_INFO!M23>=(COUNTRY_INFO!F23+COUNTRY_INFO!G23),COUNTRY_INFO!F23+COUNTRY_INFO!G23,COUNTRY_INFO!$M23), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A24=0,\" \",COUNTRY_INFO!A24))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B24=0,\" \",COUNTRY_INFO!B24))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C24=0,\" \",COUNTRY_INFO!C24))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H24=1,COUNTRY_INFO!F24+COUNTRY_INFO!G24,0),IF(COUNTRY_INFO!$H24=1,COUNTRY_INFO!F24+COUNTRY_INFO!G24,IF(COUNTRY_INFO!$I24=1,IF(COUNTRY_INFO!M24>=(COUNTRY_INFO!F24+COUNTRY_INFO!G24),COUNTRY_INFO!F24+COUNTRY_INFO!G24,COUNTRY_INFO!$M24),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P24))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q24,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H24=1, IF($E24=1,$D24, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I24=1,$F24<>0),IF(COUNTRY_INFO!M24>=(COUNTRY_INFO!F24+COUNTRY_INFO!G24),COUNTRY_INFO!F24+COUNTRY_INFO!G24,COUNTRY_INFO!$M24), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A25=0,\" \",COUNTRY_INFO!A25))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B25=0,\" \",COUNTRY_INFO!B25))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C25=0,\" \",COUNTRY_INFO!C25))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H25=1,COUNTRY_INFO!F25+COUNTRY_INFO!G25,0),IF(COUNTRY_INFO!$H25=1,COUNTRY_INFO!F25+COUNTRY_INFO!G25,IF(COUNTRY_INFO!$I25=1,IF(COUNTRY_INFO!M25>=(COUNTRY_INFO!F25+COUNTRY_INFO!G25),COUNTRY_INFO!F25+COUNTRY_INFO!G25,COUNTRY_INFO!$M25),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P25))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q25,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H25=1, IF($E25=1,$D25, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I25=1,$F25<>0),IF(COUNTRY_INFO!M25>=(COUNTRY_INFO!F25+COUNTRY_INFO!G25),COUNTRY_INFO!F25+COUNTRY_INFO!G25,COUNTRY_INFO!$M25), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A26=0,\" \",COUNTRY_INFO!A26))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B26=0,\" \",COUNTRY_INFO!B26))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C26=0,\" \",COUNTRY_INFO!C26))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H26=1,COUNTRY_INFO!F26+COUNTRY_INFO!G26,0),IF(COUNTRY_INFO!$H26=1,COUNTRY_INFO!F26+COUNTRY_INFO!G26,IF(COUNTRY_INFO!$I26=1,IF(COUNTRY_INFO!M26>=(COUNTRY_INFO!F26+COUNTRY_INFO!G26),COUNTRY_INFO!F26+COUNTRY_INFO!G26,COUNTRY_INFO!$M26),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P26))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q26,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H26=1, IF($E26=1,$D26, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I26=1,$F26<>0),IF(COUNTRY_INFO!M26>=(COUNTRY_INFO!F26+COUNTRY_INFO!G26),COUNTRY_INFO!F26+COUNTRY_INFO!G26,COUNTRY_INFO!$M26), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A27=0,\" \",COUNTRY_INFO!A27))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B27=0,\" \",COUNTRY_INFO!B27))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C27=0,\" \",COUNTRY_INFO!C27))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H27=1,COUNTRY_INFO!F27+COUNTRY_INFO!G27,0),IF(COUNTRY_INFO!$H27=1,COUNTRY_INFO!F27+COUNTRY_INFO!G27,IF(COUNTRY_INFO!$I27=1,IF(COUNTRY_INFO!M27>=(COUNTRY_INFO!F27+COUNTRY_INFO!G27),COUNTRY_INFO!F27+COUNTRY_INFO!G27,COUNTRY_INFO!$M27),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P27))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q27,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H27=1, IF($E27=1,$D27, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I27=1,$F27<>0),IF(COUNTRY_INFO!M27>=(COUNTRY_INFO!F27+COUNTRY_INFO!G27),COUNTRY_INFO!F27+COUNTRY_INFO!G27,COUNTRY_INFO!$M27), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A28=0,\" \",COUNTRY_INFO!A28))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B28=0,\" \",COUNTRY_INFO!B28))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C28=0,\" \",COUNTRY_INFO!C28))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H28=1,COUNTRY_INFO!F28+COUNTRY_INFO!G28,0),IF(COUNTRY_INFO!$H28=1,COUNTRY_INFO!F28+COUNTRY_INFO!G28,IF(COUNTRY_INFO!$I28=1,IF(COUNTRY_INFO!M28>=(COUNTRY_INFO!F28+COUNTRY_INFO!G28),COUNTRY_INFO!F28+COUNTRY_INFO!G28,COUNTRY_INFO!$M28),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P28))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q28,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H28=1, IF($E28=1,$D28, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I28=1,$F28<>0),IF(COUNTRY_INFO!M28>=(COUNTRY_INFO!F28+COUNTRY_INFO!G28),COUNTRY_INFO!F28+COUNTRY_INFO!G28,COUNTRY_INFO!$M28), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A29=0,\" \",COUNTRY_INFO!A29))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B29=0,\" \",COUNTRY_INFO!B29))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C29=0,\" \",COUNTRY_INFO!C29))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H29=1,COUNTRY_INFO!F29+COUNTRY_INFO!G29,0),IF(COUNTRY_INFO!$H29=1,COUNTRY_INFO!F29+COUNTRY_INFO!G29,IF(COUNTRY_INFO!$I29=1,IF(COUNTRY_INFO!M29>=(COUNTRY_INFO!F29+COUNTRY_INFO!G29),COUNTRY_INFO!F29+COUNTRY_INFO!G29,COUNTRY_INFO!$M29),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P29))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q29,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H29=1, IF($E29=1,$D29, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I29=1,$F29<>0),IF(COUNTRY_INFO!M29>=(COUNTRY_INFO!F29+COUNTRY_INFO!G29),COUNTRY_INFO!F29+COUNTRY_INFO!G29,COUNTRY_INFO!$M29), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A30=0,\" \",COUNTRY_INFO!A30))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B30=0,\" \",COUNTRY_INFO!B30))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C30=0,\" \",COUNTRY_INFO!C30))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H30=1,COUNTRY_INFO!F30+COUNTRY_INFO!G30,0),IF(COUNTRY_INFO!$H30=1,COUNTRY_INFO!F30+COUNTRY_INFO!G30,IF(COUNTRY_INFO!$I30=1,IF(COUNTRY_INFO!M30>=(COUNTRY_INFO!F30+COUNTRY_INFO!G30),COUNTRY_INFO!F30+COUNTRY_INFO!G30,COUNTRY_INFO!$M30),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P30))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q30,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H30=1, IF($E30=1,$D30, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I30=1,$F30<>0),IF(COUNTRY_INFO!M30>=(COUNTRY_INFO!F30+COUNTRY_INFO!G30),COUNTRY_INFO!F30+COUNTRY_INFO!G30,COUNTRY_INFO!$M30), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A31=0,\" \",COUNTRY_INFO!A31))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B31=0,\" \",COUNTRY_INFO!B31))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C31=0,\" \",COUNTRY_INFO!C31))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H31=1,COUNTRY_INFO!F31+COUNTRY_INFO!G31,0),IF(COUNTRY_INFO!$H31=1,COUNTRY_INFO!F31+COUNTRY_INFO!G31,IF(COUNTRY_INFO!$I31=1,IF(COUNTRY_INFO!M31>=(COUNTRY_INFO!F31+COUNTRY_INFO!G31),COUNTRY_INFO!F31+COUNTRY_INFO!G31,COUNTRY_INFO!$M31),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P31))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q31,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H31=1, IF($E31=1,$D31, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I31=1,$F31<>0),IF(COUNTRY_INFO!M31>=(COUNTRY_INFO!F31+COUNTRY_INFO!G31),COUNTRY_INFO!F31+COUNTRY_INFO!G31,COUNTRY_INFO!$M31), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A32=0,\" \",COUNTRY_INFO!A32))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B32=0,\" \",COUNTRY_INFO!B32))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C32=0,\" \",COUNTRY_INFO!C32))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H32=1,COUNTRY_INFO!F32+COUNTRY_INFO!G32,0),IF(COUNTRY_INFO!$H32=1,COUNTRY_INFO!F32+COUNTRY_INFO!G32,IF(COUNTRY_INFO!$I32=1,IF(COUNTRY_INFO!M32>=(COUNTRY_INFO!F32+COUNTRY_INFO!G32),COUNTRY_INFO!F32+COUNTRY_INFO!G32,COUNTRY_INFO!$M32),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P32))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q32,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H32=1, IF($E32=1,$D32, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I32=1,$F32<>0),IF(COUNTRY_INFO!M32>=(COUNTRY_INFO!F32+COUNTRY_INFO!G32),COUNTRY_INFO!F32+COUNTRY_INFO!G32,COUNTRY_INFO!$M32), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A33=0,\" \",COUNTRY_INFO!A33))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B33=0,\" \",COUNTRY_INFO!B33))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C33=0,\" \",COUNTRY_INFO!C33))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H33=1,COUNTRY_INFO!F33+COUNTRY_INFO!G33,0),IF(COUNTRY_INFO!$H33=1,COUNTRY_INFO!F33+COUNTRY_INFO!G33,IF(COUNTRY_INFO!$I33=1,IF(COUNTRY_INFO!M33>=(COUNTRY_INFO!F33+COUNTRY_INFO!G33),COUNTRY_INFO!F33+COUNTRY_INFO!G33,COUNTRY_INFO!$M33),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P33))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q33,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H33=1, IF($E33=1,$D33, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I33=1,$F33<>0),IF(COUNTRY_INFO!M33>=(COUNTRY_INFO!F33+COUNTRY_INFO!G33),COUNTRY_INFO!F33+COUNTRY_INFO!G33,COUNTRY_INFO!$M33), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A34=0,\" \",COUNTRY_INFO!A34))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B34=0,\" \",COUNTRY_INFO!B34))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C34=0,\" \",COUNTRY_INFO!C34))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H34=1,COUNTRY_INFO!F34+COUNTRY_INFO!G34,0),IF(COUNTRY_INFO!$H34=1,COUNTRY_INFO!F34+COUNTRY_INFO!G34,IF(COUNTRY_INFO!$I34=1,IF(COUNTRY_INFO!M34>=(COUNTRY_INFO!F34+COUNTRY_INFO!G34),COUNTRY_INFO!F34+COUNTRY_INFO!G34,COUNTRY_INFO!$M34),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P34))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q34,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H34=1, IF($E34=1,$D34, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I34=1,$F34<>0),IF(COUNTRY_INFO!M34>=(COUNTRY_INFO!F34+COUNTRY_INFO!G34),COUNTRY_INFO!F34+COUNTRY_INFO!G34,COUNTRY_INFO!$M34), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A35=0,\" \",COUNTRY_INFO!A35))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B35=0,\" \",COUNTRY_INFO!B35))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C35=0,\" \",COUNTRY_INFO!C35))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H35=1,COUNTRY_INFO!F35+COUNTRY_INFO!G35,0),IF(COUNTRY_INFO!$H35=1,COUNTRY_INFO!F35+COUNTRY_INFO!G35,IF(COUNTRY_INFO!$I35=1,IF(COUNTRY_INFO!M35>=(COUNTRY_INFO!F35+COUNTRY_INFO!G35),COUNTRY_INFO!F35+COUNTRY_INFO!G35,COUNTRY_INFO!$M35),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P35))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q35,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H35=1, IF($E35=1,$D35, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I35=1,$F35<>0),IF(COUNTRY_INFO!M35>=(COUNTRY_INFO!F35+COUNTRY_INFO!G35),COUNTRY_INFO!F35+COUNTRY_INFO!G35,COUNTRY_INFO!$M35), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A36=0,\" \",COUNTRY_INFO!A36))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B36=0,\" \",COUNTRY_INFO!B36))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C36=0,\" \",COUNTRY_INFO!C36))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H36=1,COUNTRY_INFO!F36+COUNTRY_INFO!G36,0),IF(COUNTRY_INFO!$H36=1,COUNTRY_INFO!F36+COUNTRY_INFO!G36,IF(COUNTRY_INFO!$I36=1,IF(COUNTRY_INFO!M36>=(COUNTRY_INFO!F36+COUNTRY_INFO!G36),COUNTRY_INFO!F36+COUNTRY_INFO!G36,COUNTRY_INFO!$M36),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P36))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q36,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H36=1, IF($E36=1,$D36, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I36=1,$F36<>0),IF(COUNTRY_INFO!M36>=(COUNTRY_INFO!F36+COUNTRY_INFO!G36),COUNTRY_INFO!F36+COUNTRY_INFO!G36,COUNTRY_INFO!$M36), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A37=0,\" \",COUNTRY_INFO!A37))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B37=0,\" \",COUNTRY_INFO!B37))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C37=0,\" \",COUNTRY_INFO!C37))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H37=1,COUNTRY_INFO!F37+COUNTRY_INFO!G37,0),IF(COUNTRY_INFO!$H37=1,COUNTRY_INFO!F37+COUNTRY_INFO!G37,IF(COUNTRY_INFO!$I37=1,IF(COUNTRY_INFO!M37>=(COUNTRY_INFO!F37+COUNTRY_INFO!G37),COUNTRY_INFO!F37+COUNTRY_INFO!G37,COUNTRY_INFO!$M37),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P37))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q37,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H37=1, IF($E37=1,$D37, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I37=1,$F37<>0),IF(COUNTRY_INFO!M37>=(COUNTRY_INFO!F37+COUNTRY_INFO!G37),COUNTRY_INFO!F37+COUNTRY_INFO!G37,COUNTRY_INFO!$M37), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A38=0,\" \",COUNTRY_INFO!A38))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B38=0,\" \",COUNTRY_INFO!B38))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C38=0,\" \",COUNTRY_INFO!C38))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H38=1,COUNTRY_INFO!F38+COUNTRY_INFO!G38,0),IF(COUNTRY_INFO!$H38=1,COUNTRY_INFO!F38+COUNTRY_INFO!G38,IF(COUNTRY_INFO!$I38=1,IF(COUNTRY_INFO!M38>=(COUNTRY_INFO!F38+COUNTRY_INFO!G38),COUNTRY_INFO!F38+COUNTRY_INFO!G38,COUNTRY_INFO!$M38),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P38))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q38,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H38=1, IF($E38=1,$D38, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I38=1,$F38<>0),IF(COUNTRY_INFO!M38>=(COUNTRY_INFO!F38+COUNTRY_INFO!G38),COUNTRY_INFO!F38+COUNTRY_INFO!G38,COUNTRY_INFO!$M38), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A39=0,\" \",COUNTRY_INFO!A39))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B39=0,\" \",COUNTRY_INFO!B39))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C39=0,\" \",COUNTRY_INFO!C39))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H39=1,COUNTRY_INFO!F39+COUNTRY_INFO!G39,0),IF(COUNTRY_INFO!$H39=1,COUNTRY_INFO!F39+COUNTRY_INFO!G39,IF(COUNTRY_INFO!$I39=1,IF(COUNTRY_INFO!M39>=(COUNTRY_INFO!F39+COUNTRY_INFO!G39),COUNTRY_INFO!F39+COUNTRY_INFO!G39,COUNTRY_INFO!$M39),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P39))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q39,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H39=1, IF($E39=1,$D39, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I39=1,$F39<>0),IF(COUNTRY_INFO!M39>=(COUNTRY_INFO!F39+COUNTRY_INFO!G39),COUNTRY_INFO!F39+COUNTRY_INFO!G39,COUNTRY_INFO!$M39), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A40=0,\" \",COUNTRY_INFO!A40))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B40=0,\" \",COUNTRY_INFO!B40))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C40=0,\" \",COUNTRY_INFO!C40))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H40=1,COUNTRY_INFO!F40+COUNTRY_INFO!G40,0),IF(COUNTRY_INFO!$H40=1,COUNTRY_INFO!F40+COUNTRY_INFO!G40,IF(COUNTRY_INFO!$I40=1,IF(COUNTRY_INFO!M40>=(COUNTRY_INFO!F40+COUNTRY_INFO!G40),COUNTRY_INFO!F40+COUNTRY_INFO!G40,COUNTRY_INFO!$M40),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P40))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q40,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H40=1, IF($E40=1,$D40, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I40=1,$F40<>0),IF(COUNTRY_INFO!M40>=(COUNTRY_INFO!F40+COUNTRY_INFO!G40),COUNTRY_INFO!F40+COUNTRY_INFO!G40,COUNTRY_INFO!$M40), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A41=0,\" \",COUNTRY_INFO!A41))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B41=0,\" \",COUNTRY_INFO!B41))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C41=0,\" \",COUNTRY_INFO!C41))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H41=1,COUNTRY_INFO!F41+COUNTRY_INFO!G41,0),IF(COUNTRY_INFO!$H41=1,COUNTRY_INFO!F41+COUNTRY_INFO!G41,IF(COUNTRY_INFO!$I41=1,IF(COUNTRY_INFO!M41>=(COUNTRY_INFO!F41+COUNTRY_INFO!G41),COUNTRY_INFO!F41+COUNTRY_INFO!G41,COUNTRY_INFO!$M41),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P41))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q41,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H41=1, IF($E41=1,$D41, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I41=1,$F41<>0),IF(COUNTRY_INFO!M41>=(COUNTRY_INFO!F41+COUNTRY_INFO!G41),COUNTRY_INFO!F41+COUNTRY_INFO!G41,COUNTRY_INFO!$M41), 0))","v":0},null,{"$f":"IF(I41=0,H41,IF(I41>H41,H41,I41))","v":0},{"$f":"IF(G41<J41,0,IF($E41=1, (G41-J41)*2.8, 0))","v":0},{"$f":"IF($E41<$F41, J41*(F41-E41)*2.8, 0)","v":0},{"$f":"IF(AND($E41=1, $F41<>0), J41*2.8, 0)","v":0},{"$f":"SUM(K41:M41)","v":0},null,{"$f":"IF($N41>$O41,$N41-$O41,0)","v":0},{"$f":"ROUNDUP($N41/500,0)","v":0}]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A42=0,\" \",COUNTRY_INFO!A42))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B42=0,\" \",COUNTRY_INFO!B42))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C42=0,\" \",COUNTRY_INFO!C42))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H42=1,COUNTRY_INFO!F42+COUNTRY_INFO!G42,0),IF(COUNTRY_INFO!$H42=1,COUNTRY_INFO!F42+COUNTRY_INFO!G42,IF(COUNTRY_INFO!$I42=1,IF(COUNTRY_INFO!M42>=(COUNTRY_INFO!F42+COUNTRY_INFO!G42),COUNTRY_INFO!F42+COUNTRY_INFO!G42,COUNTRY_INFO!$M42),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P42))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q42,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H42=1, IF($E42=1,$D42, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I42=1,$F42<>0),IF(COUNTRY_INFO!M42>=(COUNTRY_INFO!F42+COUNTRY_INFO!G42),COUNTRY_INFO!F42+COUNTRY_INFO!G42,COUNTRY_INFO!$M42), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A43=0,\" \",COUNTRY_INFO!A43))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B43=0,\" \",COUNTRY_INFO!B43))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C43=0,\" \",COUNTRY_INFO!C43))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H43=1,COUNTRY_INFO!F43+COUNTRY_INFO!G43,0),IF(COUNTRY_INFO!$H43=1,COUNTRY_INFO!F43+COUNTRY_INFO!G43,IF(COUNTRY_INFO!$I43=1,IF(COUNTRY_INFO!M43>=(COUNTRY_INFO!F43+COUNTRY_INFO!G43),COUNTRY_INFO!F43+COUNTRY_INFO!G43,COUNTRY_INFO!$M43),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P43))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q43,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H43=1, IF($E43=1,$D43, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I43=1,$F43<>0),IF(COUNTRY_INFO!M43>=(COUNTRY_INFO!F43+COUNTRY_INFO!G43),COUNTRY_INFO!F43+COUNTRY_INFO!G43,COUNTRY_INFO!$M43), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A44=0,\" \",COUNTRY_INFO!A44))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B44=0,\" \",COUNTRY_INFO!B44))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C44=0,\" \",COUNTRY_INFO!C44))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H44=1,COUNTRY_INFO!F44+COUNTRY_INFO!G44,0),IF(COUNTRY_INFO!$H44=1,COUNTRY_INFO!F44+COUNTRY_INFO!G44,IF(COUNTRY_INFO!$I44=1,IF(COUNTRY_INFO!M44>=(COUNTRY_INFO!F44+COUNTRY_INFO!G44),COUNTRY_INFO!F44+COUNTRY_INFO!G44,COUNTRY_INFO!$M44),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P44))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q44,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H44=1, IF($E44=1,$D44, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I44=1,$F44<>0),IF(COUNTRY_INFO!M44>=(COUNTRY_INFO!F44+COUNTRY_INFO!G44),COUNTRY_INFO!F44+COUNTRY_INFO!G44,COUNTRY_INFO!$M44), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A45=0,\" \",COUNTRY_INFO!A45))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B45=0,\" \",COUNTRY_INFO!B45))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C45=0,\" \",COUNTRY_INFO!C45))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H45=1,COUNTRY_INFO!F45+COUNTRY_INFO!G45,0),IF(COUNTRY_INFO!$H45=1,COUNTRY_INFO!F45+COUNTRY_INFO!G45,IF(COUNTRY_INFO!$I45=1,IF(COUNTRY_INFO!M45>=(COUNTRY_INFO!F45+COUNTRY_INFO!G45),COUNTRY_INFO!F45+COUNTRY_INFO!G45,COUNTRY_INFO!$M45),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P45))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q45,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H45=1, IF($E45=1,$D45, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I45=1,$F45<>0),IF(COUNTRY_INFO!M45>=(COUNTRY_INFO!F45+COUNTRY_INFO!G45),COUNTRY_INFO!F45+COUNTRY_INFO!G45,COUNTRY_INFO!$M45), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A46=0,\" \",COUNTRY_INFO!A46))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B46=0,\" \",COUNTRY_INFO!B46))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C46=0,\" \",COUNTRY_INFO!C46))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H46=1,COUNTRY_INFO!F46+COUNTRY_INFO!G46,0),IF(COUNTRY_INFO!$H46=1,COUNTRY_INFO!F46+COUNTRY_INFO!G46,IF(COUNTRY_INFO!$I46=1,IF(COUNTRY_INFO!M46>=(COUNTRY_INFO!F46+COUNTRY_INFO!G46),COUNTRY_INFO!F46+COUNTRY_INFO!G46,COUNTRY_INFO!$M46),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P46))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q46,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H46=1, IF($E46=1,$D46, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I46=1,$F46<>0),IF(COUNTRY_INFO!M46>=(COUNTRY_INFO!F46+COUNTRY_INFO!G46),COUNTRY_INFO!F46+COUNTRY_INFO!G46,COUNTRY_INFO!$M46), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A47=0,\" \",COUNTRY_INFO!A47))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B47=0,\" \",COUNTRY_INFO!B47))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C47=0,\" \",COUNTRY_INFO!C47))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H47=1,COUNTRY_INFO!F47+COUNTRY_INFO!G47,0),IF(COUNTRY_INFO!$H47=1,COUNTRY_INFO!F47+COUNTRY_INFO!G47,IF(COUNTRY_INFO!$I47=1,IF(COUNTRY_INFO!M47>=(COUNTRY_INFO!F47+COUNTRY_INFO!G47),COUNTRY_INFO!F47+COUNTRY_INFO!G47,COUNTRY_INFO!$M47),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P47))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q47,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H47=1, IF($E47=1,$D47, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I47=1,$F47<>0),IF(COUNTRY_INFO!M47>=(COUNTRY_INFO!F47+COUNTRY_INFO!G47),COUNTRY_INFO!F47+COUNTRY_INFO!G47,COUNTRY_INFO!$M47), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A48=0,\" \",COUNTRY_INFO!A48))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B48=0,\" \",COUNTRY_INFO!B48))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C48=0,\" \",COUNTRY_INFO!C48))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H48=1,COUNTRY_INFO!F48+COUNTRY_INFO!G48,0),IF(COUNTRY_INFO!$H48=1,COUNTRY_INFO!F48+COUNTRY_INFO!G48,IF(COUNTRY_INFO!$I48=1,IF(COUNTRY_INFO!M48>=(COUNTRY_INFO!F48+COUNTRY_INFO!G48),COUNTRY_INFO!F48+COUNTRY_INFO!G48,COUNTRY_INFO!$M48),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P48))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q48,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H48=1, IF($E48=1,$D48, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I48=1,$F48<>0),IF(COUNTRY_INFO!M48>=(COUNTRY_INFO!F48+COUNTRY_INFO!G48),COUNTRY_INFO!F48+COUNTRY_INFO!G48,COUNTRY_INFO!$M48), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A49=0,\" \",COUNTRY_INFO!A49))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B49=0,\" \",COUNTRY_INFO!B49))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C49=0,\" \",COUNTRY_INFO!C49))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H49=1,COUNTRY_INFO!F49+COUNTRY_INFO!G49,0),IF(COUNTRY_INFO!$H49=1,COUNTRY_INFO!F49+COUNTRY_INFO!G49,IF(COUNTRY_INFO!$I49=1,IF(COUNTRY_INFO!M49>=(COUNTRY_INFO!F49+COUNTRY_INFO!G49),COUNTRY_INFO!F49+COUNTRY_INFO!G49,COUNTRY_INFO!$M49),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P49))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q49,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H49=1, IF($E49=1,$D49, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I49=1,$F49<>0),IF(COUNTRY_INFO!M49>=(COUNTRY_INFO!F49+COUNTRY_INFO!G49),COUNTRY_INFO!F49+COUNTRY_INFO!G49,COUNTRY_INFO!$M49), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A50=0,\" \",COUNTRY_INFO!A50))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B50=0,\" \",COUNTRY_INFO!B50))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C50=0,\" \",COUNTRY_INFO!C50))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H50=1,COUNTRY_INFO!F50+COUNTRY_INFO!G50,0),IF(COUNTRY_INFO!$H50=1,COUNTRY_INFO!F50+COUNTRY_INFO!G50,IF(COUNTRY_INFO!$I50=1,IF(COUNTRY_INFO!M50>=(COUNTRY_INFO!F50+COUNTRY_INFO!G50),COUNTRY_INFO!F50+COUNTRY_INFO!G50,COUNTRY_INFO!$M50),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P50))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q50,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H50=1, IF($E50=1,$D50, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I50=1,$F50<>0),IF(COUNTRY_INFO!M50>=(COUNTRY_INFO!F50+COUNTRY_INFO!G50),COUNTRY_INFO!F50+COUNTRY_INFO!G50,COUNTRY_INFO!$M50), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A51=0,\" \",COUNTRY_INFO!A51))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B51=0,\" \",COUNTRY_INFO!B51))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C51=0,\" \",COUNTRY_INFO!C51))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H51=1,COUNTRY_INFO!F51+COUNTRY_INFO!G51,0),IF(COUNTRY_INFO!$H51=1,COUNTRY_INFO!F51+COUNTRY_INFO!G51,IF(COUNTRY_INFO!$I51=1,IF(COUNTRY_INFO!M51>=(COUNTRY_INFO!F51+COUNTRY_INFO!G51),COUNTRY_INFO!F51+COUNTRY_INFO!G51,COUNTRY_INFO!$M51),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P51))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q51,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H51=1, IF($E51=1,$D51, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I51=1,$F51<>0),IF(COUNTRY_INFO!M51>=(COUNTRY_INFO!F51+COUNTRY_INFO!G51),COUNTRY_INFO!F51+COUNTRY_INFO!G51,COUNTRY_INFO!$M51), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A52=0,\" \",COUNTRY_INFO!A52))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B52=0,\" \",COUNTRY_INFO!B52))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C52=0,\" \",COUNTRY_INFO!C52))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H52=1,COUNTRY_INFO!F52+COUNTRY_INFO!G52,0),IF(COUNTRY_INFO!$H52=1,COUNTRY_INFO!F52+COUNTRY_INFO!G52,IF(COUNTRY_INFO!$I52=1,IF(COUNTRY_INFO!M52>=(COUNTRY_INFO!F52+COUNTRY_INFO!G52),COUNTRY_INFO!F52+COUNTRY_INFO!G52,COUNTRY_INFO!$M52),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P52))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q52,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H52=1, IF($E52=1,$D52, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I52=1,$F52<>0),IF(COUNTRY_INFO!M52>=(COUNTRY_INFO!F52+COUNTRY_INFO!G52),COUNTRY_INFO!F52+COUNTRY_INFO!G52,COUNTRY_INFO!$M52), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A53=0,\" \",COUNTRY_INFO!A53))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B53=0,\" \",COUNTRY_INFO!B53))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C53=0,\" \",COUNTRY_INFO!C53))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H53=1,COUNTRY_INFO!F53+COUNTRY_INFO!G53,0),IF(COUNTRY_INFO!$H53=1,COUNTRY_INFO!F53+COUNTRY_INFO!G53,IF(COUNTRY_INFO!$I53=1,IF(COUNTRY_INFO!M53>=(COUNTRY_INFO!F53+COUNTRY_INFO!G53),COUNTRY_INFO!F53+COUNTRY_INFO!G53,COUNTRY_INFO!$M53),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P53))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q53,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H53=1, IF($E53=1,$D53, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I53=1,$F53<>0),IF(COUNTRY_INFO!M53>=(COUNTRY_INFO!F53+COUNTRY_INFO!G53),COUNTRY_INFO!F53+COUNTRY_INFO!G53,COUNTRY_INFO!$M53), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A54=0,\" \",COUNTRY_INFO!A54))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B54=0,\" \",COUNTRY_INFO!B54))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C54=0,\" \",COUNTRY_INFO!C54))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H54=1,COUNTRY_INFO!F54+COUNTRY_INFO!G54,0),IF(COUNTRY_INFO!$H54=1,COUNTRY_INFO!F54+COUNTRY_INFO!G54,IF(COUNTRY_INFO!$I54=1,IF(COUNTRY_INFO!M54>=(COUNTRY_INFO!F54+COUNTRY_INFO!G54),COUNTRY_INFO!F54+COUNTRY_INFO!G54,COUNTRY_INFO!$M54),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P54))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q54,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H54=1, IF($E54=1,$D54, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I54=1,$F54<>0),IF(COUNTRY_INFO!M54>=(COUNTRY_INFO!F54+COUNTRY_INFO!G54),COUNTRY_INFO!F54+COUNTRY_INFO!G54,COUNTRY_INFO!$M54), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A55=0,\" \",COUNTRY_INFO!A55))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B55=0,\" \",COUNTRY_INFO!B55))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C55=0,\" \",COUNTRY_INFO!C55))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H55=1,COUNTRY_INFO!F55+COUNTRY_INFO!G55,0),IF(COUNTRY_INFO!$H55=1,COUNTRY_INFO!F55+COUNTRY_INFO!G55,IF(COUNTRY_INFO!$I55=1,IF(COUNTRY_INFO!M55>=(COUNTRY_INFO!F55+COUNTRY_INFO!G55),COUNTRY_INFO!F55+COUNTRY_INFO!G55,COUNTRY_INFO!$M55),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P55))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q55,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H55=1, IF($E55=1,$D55, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I55=1,$F55<>0),IF(COUNTRY_INFO!M55>=(COUNTRY_INFO!F55+COUNTRY_INFO!G55),COUNTRY_INFO!F55+COUNTRY_INFO!G55,COUNTRY_INFO!$M55), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A56=0,\" \",COUNTRY_INFO!A56))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B56=0,\" \",COUNTRY_INFO!B56))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C56=0,\" \",COUNTRY_INFO!C56))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H56=1,COUNTRY_INFO!F56+COUNTRY_INFO!G56,0),IF(COUNTRY_INFO!$H56=1,COUNTRY_INFO!F56+COUNTRY_INFO!G56,IF(COUNTRY_INFO!$I56=1,IF(COUNTRY_INFO!M56>=(COUNTRY_INFO!F56+COUNTRY_INFO!G56),COUNTRY_INFO!F56+COUNTRY_INFO!G56,COUNTRY_INFO!$M56),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P56))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q56,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H56=1, IF($E56=1,$D56, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I56=1,$F56<>0),IF(COUNTRY_INFO!M56>=(COUNTRY_INFO!F56+COUNTRY_INFO!G56),COUNTRY_INFO!F56+COUNTRY_INFO!G56,COUNTRY_INFO!$M56), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A57=0,\" \",COUNTRY_INFO!A57))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B57=0,\" \",COUNTRY_INFO!B57))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C57=0,\" \",COUNTRY_INFO!C57))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H57=1,COUNTRY_INFO!F57+COUNTRY_INFO!G57,0),IF(COUNTRY_INFO!$H57=1,COUNTRY_INFO!F57+COUNTRY_INFO!G57,IF(COUNTRY_INFO!$I57=1,IF(COUNTRY_INFO!M57>=(COUNTRY_INFO!F57+COUNTRY_INFO!G57),COUNTRY_INFO!F57+COUNTRY_INFO!G57,COUNTRY_INFO!$M57),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P57))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q57,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H57=1, IF($E57=1,$D57, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I57=1,$F57<>0),IF(COUNTRY_INFO!M57>=(COUNTRY_INFO!F57+COUNTRY_INFO!G57),COUNTRY_INFO!F57+COUNTRY_INFO!G57,COUNTRY_INFO!$M57), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A58=0,\" \",COUNTRY_INFO!A58))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B58=0,\" \",COUNTRY_INFO!B58))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C58=0,\" \",COUNTRY_INFO!C58))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H58=1,COUNTRY_INFO!F58+COUNTRY_INFO!G58,0),IF(COUNTRY_INFO!$H58=1,COUNTRY_INFO!F58+COUNTRY_INFO!G58,IF(COUNTRY_INFO!$I58=1,IF(COUNTRY_INFO!M58>=(COUNTRY_INFO!F58+COUNTRY_INFO!G58),COUNTRY_INFO!F58+COUNTRY_INFO!G58,COUNTRY_INFO!$M58),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P58))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q58,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H58=1, IF($E58=1,$D58, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I58=1,$F58<>0),IF(COUNTRY_INFO!M58>=(COUNTRY_INFO!F58+COUNTRY_INFO!G58),COUNTRY_INFO!F58+COUNTRY_INFO!G58,COUNTRY_INFO!$M58), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A59=0,\" \",COUNTRY_INFO!A59))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B59=0,\" \",COUNTRY_INFO!B59))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C59=0,\" \",COUNTRY_INFO!C59))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H59=1,COUNTRY_INFO!F59+COUNTRY_INFO!G59,0),IF(COUNTRY_INFO!$H59=1,COUNTRY_INFO!F59+COUNTRY_INFO!G59,IF(COUNTRY_INFO!$I59=1,IF(COUNTRY_INFO!M59>=(COUNTRY_INFO!F59+COUNTRY_INFO!G59),COUNTRY_INFO!F59+COUNTRY_INFO!G59,COUNTRY_INFO!$M59),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P59))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q59,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H59=1, IF($E59=1,$D59, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I59=1,$F59<>0),IF(COUNTRY_INFO!M59>=(COUNTRY_INFO!F59+COUNTRY_INFO!G59),COUNTRY_INFO!F59+COUNTRY_INFO!G59,COUNTRY_INFO!$M59), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A60=0,\" \",COUNTRY_INFO!A60))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B60=0,\" \",COUNTRY_INFO!B60))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C60=0,\" \",COUNTRY_INFO!C60))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H60=1,COUNTRY_INFO!F60+COUNTRY_INFO!G60,0),IF(COUNTRY_INFO!$H60=1,COUNTRY_INFO!F60+COUNTRY_INFO!G60,IF(COUNTRY_INFO!$I60=1,IF(COUNTRY_INFO!M60>=(COUNTRY_INFO!F60+COUNTRY_INFO!G60),COUNTRY_INFO!F60+COUNTRY_INFO!G60,COUNTRY_INFO!$M60),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P60))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q60,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H60=1, IF($E60=1,$D60, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I60=1,$F60<>0),IF(COUNTRY_INFO!M60>=(COUNTRY_INFO!F60+COUNTRY_INFO!G60),COUNTRY_INFO!F60+COUNTRY_INFO!G60,COUNTRY_INFO!$M60), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A61=0,\" \",COUNTRY_INFO!A61))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B61=0,\" \",COUNTRY_INFO!B61))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C61=0,\" \",COUNTRY_INFO!C61))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H61=1,COUNTRY_INFO!F61+COUNTRY_INFO!G61,0),IF(COUNTRY_INFO!$H61=1,COUNTRY_INFO!F61+COUNTRY_INFO!G61,IF(COUNTRY_INFO!$I61=1,IF(COUNTRY_INFO!M61>=(COUNTRY_INFO!F61+COUNTRY_INFO!G61),COUNTRY_INFO!F61+COUNTRY_INFO!G61,COUNTRY_INFO!$M61),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P61))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q61,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H61=1, IF($E61=1,$D61, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I61=1,$F61<>0),IF(COUNTRY_INFO!M61>=(COUNTRY_INFO!F61+COUNTRY_INFO!G61),COUNTRY_INFO!F61+COUNTRY_INFO!G61,COUNTRY_INFO!$M61), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A62=0,\" \",COUNTRY_INFO!A62))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B62=0,\" \",COUNTRY_INFO!B62))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C62=0,\" \",COUNTRY_INFO!C62))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H62=1,COUNTRY_INFO!F62+COUNTRY_INFO!G62,0),IF(COUNTRY_INFO!$H62=1,COUNTRY_INFO!F62+COUNTRY_INFO!G62,IF(COUNTRY_INFO!$I62=1,IF(COUNTRY_INFO!M62>=(COUNTRY_INFO!F62+COUNTRY_INFO!G62),COUNTRY_INFO!F62+COUNTRY_INFO!G62,COUNTRY_INFO!$M62),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P62))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q62,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H62=1, IF($E62=1,$D62, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I62=1,$F62<>0),IF(COUNTRY_INFO!M62>=(COUNTRY_INFO!F62+COUNTRY_INFO!G62),COUNTRY_INFO!F62+COUNTRY_INFO!G62,COUNTRY_INFO!$M62), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A63=0,\" \",COUNTRY_INFO!A63))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B63=0,\" \",COUNTRY_INFO!B63))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C63=0,\" \",COUNTRY_INFO!C63))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H63=1,COUNTRY_INFO!F63+COUNTRY_INFO!G63,0),IF(COUNTRY_INFO!$H63=1,COUNTRY_INFO!F63+COUNTRY_INFO!G63,IF(COUNTRY_INFO!$I63=1,IF(COUNTRY_INFO!M63>=(COUNTRY_INFO!F63+COUNTRY_INFO!G63),COUNTRY_INFO!F63+COUNTRY_INFO!G63,COUNTRY_INFO!$M63),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P63))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q63,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H63=1, IF($E63=1,$D63, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I63=1,$F63<>0),IF(COUNTRY_INFO!M63>=(COUNTRY_INFO!F63+COUNTRY_INFO!G63),COUNTRY_INFO!F63+COUNTRY_INFO!G63,COUNTRY_INFO!$M63), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A64=0,\" \",COUNTRY_INFO!A64))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B64=0,\" \",COUNTRY_INFO!B64))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C64=0,\" \",COUNTRY_INFO!C64))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H64=1,COUNTRY_INFO!F64+COUNTRY_INFO!G64,0),IF(COUNTRY_INFO!$H64=1,COUNTRY_INFO!F64+COUNTRY_INFO!G64,IF(COUNTRY_INFO!$I64=1,IF(COUNTRY_INFO!M64>=(COUNTRY_INFO!F64+COUNTRY_INFO!G64),COUNTRY_INFO!F64+COUNTRY_INFO!G64,COUNTRY_INFO!$M64),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P64))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q64,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H64=1, IF($E64=1,$D64, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I64=1,$F64<>0),IF(COUNTRY_INFO!M64>=(COUNTRY_INFO!F64+COUNTRY_INFO!G64),COUNTRY_INFO!F64+COUNTRY_INFO!G64,COUNTRY_INFO!$M64), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A65=0,\" \",COUNTRY_INFO!A65))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B65=0,\" \",COUNTRY_INFO!B65))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C65=0,\" \",COUNTRY_INFO!C65))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H65=1,COUNTRY_INFO!F65+COUNTRY_INFO!G65,0),IF(COUNTRY_INFO!$H65=1,COUNTRY_INFO!F65+COUNTRY_INFO!G65,IF(COUNTRY_INFO!$I65=1,IF(COUNTRY_INFO!M65>=(COUNTRY_INFO!F65+COUNTRY_INFO!G65),COUNTRY_INFO!F65+COUNTRY_INFO!G65,COUNTRY_INFO!$M65),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P65))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q65,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H65=1, IF($E65=1,$D65, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I65=1,$F65<>0),IF(COUNTRY_INFO!M65>=(COUNTRY_INFO!F65+COUNTRY_INFO!G65),COUNTRY_INFO!F65+COUNTRY_INFO!G65,COUNTRY_INFO!$M65), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A66=0,\" \",COUNTRY_INFO!A66))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B66=0,\" \",COUNTRY_INFO!B66))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C66=0,\" \",COUNTRY_INFO!C66))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H66=1,COUNTRY_INFO!F66+COUNTRY_INFO!G66,0),IF(COUNTRY_INFO!$H66=1,COUNTRY_INFO!F66+COUNTRY_INFO!G66,IF(COUNTRY_INFO!$I66=1,IF(COUNTRY_INFO!M66>=(COUNTRY_INFO!F66+COUNTRY_INFO!G66),COUNTRY_INFO!F66+COUNTRY_INFO!G66,COUNTRY_INFO!$M66),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P66))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q66,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H66=1, IF($E66=1,$D66, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I66=1,$F66<>0),IF(COUNTRY_INFO!M66>=(COUNTRY_INFO!F66+COUNTRY_INFO!G66),COUNTRY_INFO!F66+COUNTRY_INFO!G66,COUNTRY_INFO!$M66), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A67=0,\" \",COUNTRY_INFO!A67))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B67=0,\" \",COUNTRY_INFO!B67))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C67=0,\" \",COUNTRY_INFO!C67))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H67=1,COUNTRY_INFO!F67+COUNTRY_INFO!G67,0),IF(COUNTRY_INFO!$H67=1,COUNTRY_INFO!F67+COUNTRY_INFO!G67,IF(COUNTRY_INFO!$I67=1,IF(COUNTRY_INFO!M67>=(COUNTRY_INFO!F67+COUNTRY_INFO!G67),COUNTRY_INFO!F67+COUNTRY_INFO!G67,COUNTRY_INFO!$M67),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P67))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q67,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H67=1, IF($E67=1,$D67, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I67=1,$F67<>0),IF(COUNTRY_INFO!M67>=(COUNTRY_INFO!F67+COUNTRY_INFO!G67),COUNTRY_INFO!F67+COUNTRY_INFO!G67,COUNTRY_INFO!$M67), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A68=0,\" \",COUNTRY_INFO!A68))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B68=0,\" \",COUNTRY_INFO!B68))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C68=0,\" \",COUNTRY_INFO!C68))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H68=1,COUNTRY_INFO!F68+COUNTRY_INFO!G68,0),IF(COUNTRY_INFO!$H68=1,COUNTRY_INFO!F68+COUNTRY_INFO!G68,IF(COUNTRY_INFO!$I68=1,IF(COUNTRY_INFO!M68>=(COUNTRY_INFO!F68+COUNTRY_INFO!G68),COUNTRY_INFO!F68+COUNTRY_INFO!G68,COUNTRY_INFO!$M68),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P68))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q68,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H68=1, IF($E68=1,$D68, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I68=1,$F68<>0),IF(COUNTRY_INFO!M68>=(COUNTRY_INFO!F68+COUNTRY_INFO!G68),COUNTRY_INFO!F68+COUNTRY_INFO!G68,COUNTRY_INFO!$M68), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A69=0,\" \",COUNTRY_INFO!A69))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B69=0,\" \",COUNTRY_INFO!B69))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C69=0,\" \",COUNTRY_INFO!C69))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H69=1,COUNTRY_INFO!F69+COUNTRY_INFO!G69,0),IF(COUNTRY_INFO!$H69=1,COUNTRY_INFO!F69+COUNTRY_INFO!G69,IF(COUNTRY_INFO!$I69=1,IF(COUNTRY_INFO!M69>=(COUNTRY_INFO!F69+COUNTRY_INFO!G69),COUNTRY_INFO!F69+COUNTRY_INFO!G69,COUNTRY_INFO!$M69),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P69))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q69,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H69=1, IF($E69=1,$D69, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I69=1,$F69<>0),IF(COUNTRY_INFO!M69>=(COUNTRY_INFO!F69+COUNTRY_INFO!G69),COUNTRY_INFO!F69+COUNTRY_INFO!G69,COUNTRY_INFO!$M69), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A70=0,\" \",COUNTRY_INFO!A70))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B70=0,\" \",COUNTRY_INFO!B70))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C70=0,\" \",COUNTRY_INFO!C70))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H70=1,COUNTRY_INFO!F70+COUNTRY_INFO!G70,0),IF(COUNTRY_INFO!$H70=1,COUNTRY_INFO!F70+COUNTRY_INFO!G70,IF(COUNTRY_INFO!$I70=1,IF(COUNTRY_INFO!M70>=(COUNTRY_INFO!F70+COUNTRY_INFO!G70),COUNTRY_INFO!F70+COUNTRY_INFO!G70,COUNTRY_INFO!$M70),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P70))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q70,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H70=1, IF($E70=1,$D70, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I70=1,$F70<>0),IF(COUNTRY_INFO!M70>=(COUNTRY_INFO!F70+COUNTRY_INFO!G70),COUNTRY_INFO!F70+COUNTRY_INFO!G70,COUNTRY_INFO!$M70), 0))","v":0},null,0,0,0,0,0,null,0,0]
[{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!A71=0,\" \",COUNTRY_INFO!A71))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!B71=0,\" \",COUNTRY_INFO!B71))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",\" \",IF(COUNTRY_INFO!C71=0,\" \",COUNTRY_INFO!C71))","v":" "},{"$f":"IF(INTRO!$E$39=\"Non-endemic\",0,IF(INTRO!$E$39=\"Endemic but PC is not required\",IF(COUNTRY_INFO!$H71=1,COUNTRY_INFO!F71+COUNTRY_INFO!G71,0),IF(COUNTRY_INFO!$H71=1,COUNTRY_INFO!F71+COUNTRY_INFO!G71,IF(COUNTRY_INFO!$I71=1,IF(COUNTRY_INFO!M71>=(COUNTRY_INFO!F71+COUNTRY_INFO!G71),COUNTRY_INFO!F71+COUNTRY_INFO!G71,COUNTRY_INFO!$M71),0))))","v":0},{"$f":"IF(AND(INTRO!$E$39=\"Non-endemic\",INTRO!$E$37=\"Non-endemic\"),\"Not required\",IF(INTRO!$E$39=\"Non-endemic\",\"Treat with DEC\",COUNTRY_INFO!P71))","v":"Treat with DEC"},{"$f":"IF(INTRO!$E$39<>\"Non-endemic\",COUNTRY_INFO!Q71,\"Not required\")","v":"Not required"},{"$f":"IF(COUNTRY_INFO!H71=1, IF($E71=1,$D71, 0),0)","v":0},{"$f":"IF(INTRO!$E$39<>\"Endemic\",0, IF(AND(COUNTRY_INFO!$I71=1,$F71<>0),IF(COUNTRY_INFO!M71>=(COUNTRY_INFO!F71+COUNTRY_INFO!G71),COUNTRY_INFO!F71+COUNTRY_INFO!G71,COUNTRY_INFO!$M71), 0))","v":0},null,0,0,0,0,0,null,0,0]

{"sheet":"IVM+","index":6,"n_rows":71,"n_cols":9,"rows_kept":71,"cut":false,"hidden":false,"merged":[[6,5,7,5],[6,6,7,6],[6,7,7,7],[6,8,7,8],[5,4,7,4],[5,5,5,8],[6,0,7,0],[6,1,7,1],[6,2,7,2],[6,3,7,3],[3,0,3,2],[5,0,5,2]]}
["Ivermectin (IVM) for IDA therapy"]
["Administrative structure, eligible population by age group, treatment plan and information about tablets"]
[]
["TOTAL",null,null,null,{"$f":"SUM(E$9:E$1000)","v":6986039},19560909.199999999,0,19560909.199999999,39140]
[]
["Country administrative structure",null,null,"Treatment plan","Population targeted for treatment with IVM \n(IDA therapy)","Ivermectin (IVM)"]
["Country","Province/State","District","LF",null,"Total required","Remaining in stock","Tablets to be procured","Bottles (3mg)\n500 tablets"]
[]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A9=0,\" \",COUNTRY_INFO!A9),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B9=0,\" \",COUNTRY_INFO!B9),\" \")","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C9=0,\" \",COUNTRY_INFO!C9),\" \")","v":"Buhera"},{"$f":"IF(COUNTRY_INFO!T9<>\"\",COUNTRY_INFO!P9,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T9<>\"\",COUNTRY_INFO!$H9=1),COUNTRY_INFO!F9+COUNTRY_INFO!G9,0)","v":0},{"$f":"E9*2.8","v":0},null,{"$f":"IF($F9>$G9,$F9-$G9,0)","v":0},{"$f":"ROUNDUP($F9/500,0)","v":0}]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A10=0,\" \",COUNTRY_INFO!A10),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B10=0,\" \",COUNTRY_INFO!B10),\" \")","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C10=0,\" \",COUNTRY_INFO!C10),\" \")","v":"Chimanimani"},{"$f":"IF(COUNTRY_INFO!T10<>\"\",COUNTRY_INFO!P10,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T10<>\"\",COUNTRY_INFO!$H10=1),COUNTRY_INFO!F10+COUNTRY_INFO!G10,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A11=0,\" \",COUNTRY_INFO!A11),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B11=0,\" \",COUNTRY_INFO!B11),\" \")","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C11=0,\" \",COUNTRY_INFO!C11),\" \")","v":"Chipinge"},{"$f":"IF(COUNTRY_INFO!T11<>\"\",COUNTRY_INFO!P11,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T11<>\"\",COUNTRY_INFO!$H11=1),COUNTRY_INFO!F11+COUNTRY_INFO!G11,0)","v":308095},862666,null,862666,1726]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A12=0,\" \",COUNTRY_INFO!A12),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B12=0,\" \",COUNTRY_INFO!B12),\" \")","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C12=0,\" \",COUNTRY_INFO!C12),\" \")","v":"Makoni"},{"$f":"IF(COUNTRY_INFO!T12<>\"\",COUNTRY_INFO!P12,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T12<>\"\",COUNTRY_INFO!$H12=1),COUNTRY_INFO!F12+COUNTRY_INFO!G12,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A13=0,\" \",COUNTRY_INFO!A13),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B13=0,\" \",COUNTRY_INFO!B13),\" \")","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C13=0,\" \",COUNTRY_INFO!C13),\" \")","v":"Mutare"},{"$f":"IF(COUNTRY_INFO!T13<>\"\",COUNTRY_INFO!P13,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T13<>\"\",COUNTRY_INFO!$H13=1),COUNTRY_INFO!F13+COUNTRY_INFO!G13,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A14=0,\" \",COUNTRY_INFO!A14),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B14=0,\" \",COUNTRY_INFO!B14),\" \")","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C14=0,\" \",COUNTRY_INFO!C14),\" \")","v":"Mutasa"},{"$f":"IF(COUNTRY_INFO!T14<>\"\",COUNTRY_INFO!P14,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T14<>\"\",COUNTRY_INFO!$H14=1),COUNTRY_INFO!F14+COUNTRY_INFO!G14,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A15=0,\" \",COUNTRY_INFO!A15),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B15=0,\" \",COUNTRY_INFO!B15),\" \")","v":"Manicaland"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C15=0,\" \",COUNTRY_INFO!C15),\" \")","v":"Nyanga"},{"$f":"IF(COUNTRY_INFO!T15<>\"\",COUNTRY_INFO!P15,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T15<>\"\",COUNTRY_INFO!$H15=1),COUNTRY_INFO!F15+COUNTRY_INFO!G15,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A16=0,\" \",COUNTRY_INFO!A16),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B16=0,\" \",COUNTRY_INFO!B16),\" \")","v":"Harare"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C16=0,\" \",COUNTRY_INFO!C16),\" \")","v":"Chitungwiza"},{"$f":"IF(COUNTRY_INFO!T16<>\"\",COUNTRY_INFO!P16,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T16<>\"\",COUNTRY_INFO!$H16=1),COUNTRY_INFO!F16+COUNTRY_INFO!G16,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A17=0,\" \",COUNTRY_INFO!A17),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B17=0,\" \",COUNTRY_INFO!B17),\" \")","v":"Harare"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C17=0,\" \",COUNTRY_INFO!C17),\" \")","v":"Harare"},{"$f":"IF(COUNTRY_INFO!T17<>\"\",COUNTRY_INFO!P17,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T17<>\"\",COUNTRY_INFO!$H17=1),COUNTRY_INFO!F17+COUNTRY_INFO!G17,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A18=0,\" \",COUNTRY_INFO!A18),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B18=0,\" \",COUNTRY_INFO!B18),\" \")","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C18=0,\" \",COUNTRY_INFO!C18),\" \")","v":"Bindura"},{"$f":"IF(COUNTRY_INFO!T18<>\"\",COUNTRY_INFO!P18,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T18<>\"\",COUNTRY_INFO!$H18=1),COUNTRY_INFO!F18+COUNTRY_INFO!G18,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A19=0,\" \",COUNTRY_INFO!A19),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B19=0,\" \",COUNTRY_INFO!B19),\" \")","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C19=0,\" \",COUNTRY_INFO!C19),\" \")","v":"Centenary"},{"$f":"IF(COUNTRY_INFO!T19<>\"\",COUNTRY_INFO!P19,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T19<>\"\",COUNTRY_INFO!$H19=1),COUNTRY_INFO!F19+COUNTRY_INFO!G19,0)","v":116715},326802,null,326802,654]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A20=0,\" \",COUNTRY_INFO!A20),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B20=0,\" \",COUNTRY_INFO!B20),\" \")","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C20=0,\" \",COUNTRY_INFO!C20),\" \")","v":"Guruve"},{"$f":"IF(COUNTRY_INFO!T20<>\"\",COUNTRY_INFO!P20,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T20<>\"\",COUNTRY_INFO!$H20=1),COUNTRY_INFO!F20+COUNTRY_INFO!G20,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A21=0,\" \",COUNTRY_INFO!A21),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B21=0,\" \",COUNTRY_INFO!B21),\" \")","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C21=0,\" \",COUNTRY_INFO!C21),\" \")","v":"Mazowe"},{"$f":"IF(COUNTRY_INFO!T21<>\"\",COUNTRY_INFO!P21,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T21<>\"\",COUNTRY_INFO!$H21=1),COUNTRY_INFO!F21+COUNTRY_INFO!G21,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A22=0,\" \",COUNTRY_INFO!A22),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B22=0,\" \",COUNTRY_INFO!B22),\" \")","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C22=0,\" \",COUNTRY_INFO!C22),\" \")","v":"Mt Darwin"},{"$f":"IF(COUNTRY_INFO!T22<>\"\",COUNTRY_INFO!P22,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T22<>\"\",COUNTRY_INFO!$H22=1),COUNTRY_INFO!F22+COUNTRY_INFO!G22,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A23=0,\" \",COUNTRY_INFO!A23),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B23=0,\" \",COUNTRY_INFO!B23),\" \")","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C23=0,\" \",COUNTRY_INFO!C23),\" \")","v":"Rushinga"},{"$f":"IF(COUNTRY_INFO!T23<>\"\",COUNTRY_INFO!P23,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T23<>\"\",COUNTRY_INFO!$H23=1),COUNTRY_INFO!F23+COUNTRY_INFO!G23,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A24=0,\" \",COUNTRY_INFO!A24),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B24=0,\" \",COUNTRY_INFO!B24),\" \")","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C24=0,\" \",COUNTRY_INFO!C24),\" \")","v":"Shamva"},{"$f":"IF(COUNTRY_INFO!T24<>\"\",COUNTRY_INFO!P24,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T24<>\"\",COUNTRY_INFO!$H24=1),COUNTRY_INFO!F24+COUNTRY_INFO!G24,0)","v":117532},329089.59999999998,null,329089.59999999998,659]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A25=0,\" \",COUNTRY_INFO!A25),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B25=0,\" \",COUNTRY_INFO!B25),\" \")","v":"Mashnaland Central"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C25=0,\" \",COUNTRY_INFO!C25),\" \")","v":"Mbire"},{"$f":"IF(COUNTRY_INFO!T25<>\"\",COUNTRY_INFO!P25,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T25<>\"\",COUNTRY_INFO!$H25=1),COUNTRY_INFO!F25+COUNTRY_INFO!G25,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A26=0,\" \",COUNTRY_INFO!A26),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B26=0,\" \",COUNTRY_INFO!B26),\" \")","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C26=0,\" \",COUNTRY_INFO!C26),\" \")","v":"Chikomba"},{"$f":"IF(COUNTRY_INFO!T26<>\"\",COUNTRY_INFO!P26,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T26<>\"\",COUNTRY_INFO!$H26=1),COUNTRY_INFO!F26+COUNTRY_INFO!G26,0)","v":114999},321997.19999999995,null,321997.19999999995,644]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A27=0,\" \",COUNTRY_INFO!A27),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B27=0,\" \",COUNTRY_INFO!B27),\" \")","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C27=0,\" \",COUNTRY_INFO!C27),\" \")","v":"Goromonzi"},{"$f":"IF(COUNTRY_INFO!T27<>\"\",COUNTRY_INFO!P27,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T27<>\"\",COUNTRY_INFO!$H27=1),COUNTRY_INFO!F27+COUNTRY_INFO!G27,0)","v":213854},598791.19999999995,null,598791.19999999995,1198]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A28=0,\" \",COUNTRY_INFO!A28),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B28=0,\" \",COUNTRY_INFO!B28),\" \")","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C28=0,\" \",COUNTRY_INFO!C28),\" \")","v":"UMP"},{"$f":"IF(COUNTRY_INFO!T28<>\"\",COUNTRY_INFO!P28,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T28<>\"\",COUNTRY_INFO!$H28=1),COUNTRY_INFO!F28+COUNTRY_INFO!G28,0)","v":107038},299706.39999999997,null,299706.39999999997,600]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A29=0,\" \",COUNTRY_INFO!A29),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B29=0,\" \",COUNTRY_INFO!B29),\" \")","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C29=0,\" \",COUNTRY_INFO!C29),\" \")","v":"Hwedza"},{"$f":"IF(COUNTRY_INFO!T29<>\"\",COUNTRY_INFO!P29,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T29<>\"\",COUNTRY_INFO!$H29=1),COUNTRY_INFO!F29+COUNTRY_INFO!G29,0)","v":67457},188879.59999999998,null,188879.59999999998,378]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A30=0,\" \",COUNTRY_INFO!A30),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B30=0,\" \",COUNTRY_INFO!B30),\" \")","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C30=0,\" \",COUNTRY_INFO!C30),\" \")","v":"Marondera"},{"$f":"IF(COUNTRY_INFO!T30<>\"\",COUNTRY_INFO!P30,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T30<>\"\",COUNTRY_INFO!$H30=1),COUNTRY_INFO!F30+COUNTRY_INFO!G30,0)","v":170127},476355.6,null,476355.6,953]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A31=0,\" \",COUNTRY_INFO!A31),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B31=0,\" \",COUNTRY_INFO!B31),\" \")","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C31=0,\" \",COUNTRY_INFO!C31),\" \")","v":"Mudzi"},{"$f":"IF(COUNTRY_INFO!T31<>\"\",COUNTRY_INFO!P31,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T31<>\"\",COUNTRY_INFO!$H31=1),COUNTRY_INFO!F31+COUNTRY_INFO!G31,0)","v":126659},354645.19999999995,null,354645.19999999995,710]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A32=0,\" \",COUNTRY_INFO!A32),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B32=0,\" \",COUNTRY_INFO!B32),\" \")","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C32=0,\" \",COUNTRY_INFO!C32),\" \")","v":"Murewa"},{"$f":"IF(COUNTRY_INFO!T32<>\"\",COUNTRY_INFO!P32,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T32<>\"\",COUNTRY_INFO!$H32=1),COUNTRY_INFO!F32+COUNTRY_INFO!G32,0)","v":189730},531244,null,531244,1063]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A33=0,\" \",COUNTRY_INFO!A33),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B33=0,\" \",COUNTRY_INFO!B33),\" \")","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C33=0,\" \",COUNTRY_INFO!C33),\" \")","v":"Mutoko"},{"$f":"IF(COUNTRY_INFO!T33<>\"\",COUNTRY_INFO!P33,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T33<>\"\",COUNTRY_INFO!$H33=1),COUNTRY_INFO!F33+COUNTRY_INFO!G33,0)","v":138897},388911.6,null,388911.6,778]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A34=0,\" \",COUNTRY_INFO!A34),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B34=0,\" \",COUNTRY_INFO!B34),\" \")","v":"Mashonaland East"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C34=0,\" \",COUNTRY_INFO!C34),\" \")","v":"Seke"},{"$f":"IF(COUNTRY_INFO!T34<>\"\",COUNTRY_INFO!P34,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T34<>\"\",COUNTRY_INFO!$H34=1),COUNTRY_INFO!F34+COUNTRY_INFO!G34,0)","v":308819},864693.2,null,864693.2,1730]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A35=0,\" \",COUNTRY_INFO!A35),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B35=0,\" \",COUNTRY_INFO!B35),\" \")","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C35=0,\" \",COUNTRY_INFO!C35),\" \")","v":"Chegutu"},{"$f":"IF(COUNTRY_INFO!T35<>\"\",COUNTRY_INFO!P35,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T35<>\"\",COUNTRY_INFO!$H35=1),COUNTRY_INFO!F35+COUNTRY_INFO!G35,0)","v":258385},723478,null,723478,1447]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A36=0,\" \",COUNTRY_INFO!A36),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B36=0,\" \",COUNTRY_INFO!B36),\" \")","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C36=0,\" \",COUNTRY_INFO!C36),\" \")","v":"Hurungwe"},{"$f":"IF(COUNTRY_INFO!T36<>\"\",COUNTRY_INFO!P36,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T36<>\"\",COUNTRY_INFO!$H36=1),COUNTRY_INFO!F36+COUNTRY_INFO!G36,0)","v":340098},952274.39999999991,null,952274.39999999991,1905]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A37=0,\" \",COUNTRY_INFO!A37),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B37=0,\" \",COUNTRY_INFO!B37),\" \")","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C37=0,\" \",COUNTRY_INFO!C37),\" \")","v":"Sanyati"},{"$f":"IF(COUNTRY_INFO!T37<>\"\",COUNTRY_INFO!P37,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T37<>\"\",COUNTRY_INFO!$H37=1),COUNTRY_INFO!F37+COUNTRY_INFO!G37,0)","v":195205},546574,null,546574,1094]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A38=0,\" \",COUNTRY_INFO!A38),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B38=0,\" \",COUNTRY_INFO!B38),\" \")","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C38=0,\" \",COUNTRY_INFO!C38),\" \")","v":"Kariba"},{"$f":"IF(COUNTRY_INFO!T38<>\"\",COUNTRY_INFO!P38,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T38<>\"\",COUNTRY_INFO!$H38=1),COUNTRY_INFO!F38+COUNTRY_INFO!G38,0)","v":64464},180499.19999999998,null,180499.19999999998,361]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A39=0,\" \",COUNTRY_INFO!A39),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B39=0,\" \",COUNTRY_INFO!B39),\" \")","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C39=0,\" \",COUNTRY_INFO!C39),\" \")","v":"Makonde"},{"$f":"IF(COUNTRY_INFO!T39<>\"\",COUNTRY_INFO!P39,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T39<>\"\",COUNTRY_INFO!$H39=1),COUNTRY_INFO!F39+COUNTRY_INFO!G39,0)","v":220015},616042,null,616042,1233]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A40=0,\" \",COUNTRY_INFO!A40),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B40=0,\" \",COUNTRY_INFO!B40),\" \")","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C40=0,\" \",COUNTRY_INFO!C40),\" \")","v":"Mhondoro-Ngezi"},{"$f":"IF(COUNTRY_INFO!T40<>\"\",COUNTRY_INFO!P40,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T40<>\"\",COUNTRY_INFO!$H40=1),COUNTRY_INFO!F40+COUNTRY_INFO!G40,0)","v":99178},277698.39999999997,null,277698.39999999997,556]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A41=0,\" \",COUNTRY_INFO!A41),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B41=0,\" \",COUNTRY_INFO!B41),\" \")","v":"Mashonaland West"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C41=0,\" \",COUNTRY_INFO!C41),\" \")","v":"Zvimba"},{"$f":"IF(COUNTRY_INFO!T41<>\"\",COUNTRY_INFO!P41,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T41<>\"\",COUNTRY_INFO!$H41=1),COUNTRY_INFO!F41+COUNTRY_INFO!G41,0)","v":250006},{"$f":"E41*2.8","v":700016.79999999993},null,{"$f":"IF($F41>$G41,$F41-$G41,0)","v":700016.79999999993},{"$f":"ROUNDUP($F41/500,0)","v":1401}]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A42=0,\" \",COUNTRY_INFO!A42),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B42=0,\" \",COUNTRY_INFO!B42),\" \")","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C42=0,\" \",COUNTRY_INFO!C42),\" \")","v":"Binga"},{"$f":"IF(COUNTRY_INFO!T42<>\"\",COUNTRY_INFO!P42,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T42<>\"\",COUNTRY_INFO!$H42=1),COUNTRY_INFO!F42+COUNTRY_INFO!G42,0)","v":132209},370185.19999999995,null,370185.19999999995,741]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A43=0,\" \",COUNTRY_INFO!A43),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B43=0,\" \",COUNTRY_INFO!B43),\" \")","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C43=0,\" \",COUNTRY_INFO!C43),\" \")","v":"Bubi"},{"$f":"IF(COUNTRY_INFO!T43<>\"\",COUNTRY_INFO!P43,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T43<>\"\",COUNTRY_INFO!$H43=1),COUNTRY_INFO!F43+COUNTRY_INFO!G43,0)","v":58820},164696,null,164696,330]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A44=0,\" \",COUNTRY_INFO!A44),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B44=0,\" \",COUNTRY_INFO!B44),\" \")","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C44=0,\" \",COUNTRY_INFO!C44),\" \")","v":"Hwange"},{"$f":"IF(COUNTRY_INFO!T44<>\"\",COUNTRY_INFO!P44,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T44<>\"\",COUNTRY_INFO!$H44=1),COUNTRY_INFO!F44+COUNTRY_INFO!G44,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A45=0,\" \",COUNTRY_INFO!A45),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B45=0,\" \",COUNTRY_INFO!B45),\" \")","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C45=0,\" \",COUNTRY_INFO!C45),\" \")","v":"Lupane"},{"$f":"IF(COUNTRY_INFO!T45<>\"\",COUNTRY_INFO!P45,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T45<>\"\",COUNTRY_INFO!$H45=1),COUNTRY_INFO!F45+COUNTRY_INFO!G45,0)","v":95205},266574,null,266574,534]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A46=0,\" \",COUNTRY_INFO!A46),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B46=0,\" \",COUNTRY_INFO!B46),\" \")","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C46=0,\" \",COUNTRY_INFO!C46),\" \")","v":"Nkayi"},{"$f":"IF(COUNTRY_INFO!T46<>\"\",COUNTRY_INFO!P46,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T46<>\"\",COUNTRY_INFO!$H46=1),COUNTRY_INFO!F46+COUNTRY_INFO!G46,0)","v":103735},290458,null,290458,581]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A47=0,\" \",COUNTRY_INFO!A47),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B47=0,\" \",COUNTRY_INFO!B47),\" \")","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C47=0,\" \",COUNTRY_INFO!C47),\" \")","v":"Tsholotsho"},{"$f":"IF(COUNTRY_INFO!T47<>\"\",COUNTRY_INFO!P47,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T47<>\"\",COUNTRY_INFO!$H47=1),COUNTRY_INFO!F47+COUNTRY_INFO!G47,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A48=0,\" \",COUNTRY_INFO!A48),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B48=0,\" \",COUNTRY_INFO!B48),\" \")","v":"Matabeleland North"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C48=0,\" \",COUNTRY_INFO!C48),\" \")","v":"Umguza"},{"$f":"IF(COUNTRY_INFO!T48<>\"\",COUNTRY_INFO!P48,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T48<>\"\",COUNTRY_INFO!$H48=1),COUNTRY_INFO!F48+COUNTRY_INFO!G48,0)","v":85249},238697.19999999998,null,238697.19999999998,478]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A49=0,\" \",COUNTRY_INFO!A49),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B49=0,\" \",COUNTRY_INFO!B49),\" \")","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C49=0,\" \",COUNTRY_INFO!C49),\" \")","v":"Beit Bridge"},{"$f":"IF(COUNTRY_INFO!T49<>\"\",COUNTRY_INFO!P49,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T49<>\"\",COUNTRY_INFO!$H49=1),COUNTRY_INFO!F49+COUNTRY_INFO!G49,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A50=0,\" \",COUNTRY_INFO!A50),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B50=0,\" \",COUNTRY_INFO!B50),\" \")","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C50=0,\" \",COUNTRY_INFO!C50),\" \")","v":"Bulilima"},{"$f":"IF(COUNTRY_INFO!T50<>\"\",COUNTRY_INFO!P50,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T50<>\"\",COUNTRY_INFO!$H50=1),COUNTRY_INFO!F50+COUNTRY_INFO!G50,0)","v":86080},241023.99999999997,null,241023.99999999997,483]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A51=0,\" \",COUNTRY_INFO!A51),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B51=0,\" \",COUNTRY_INFO!B51),\" \")","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C51=0,\" \",COUNTRY_INFO!C51),\" \")","v":"Gwanda"},{"$f":"IF(COUNTRY_INFO!T51<>\"\",COUNTRY_INFO!P51,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T51<>\"\",COUNTRY_INFO!$H51=1),COUNTRY_INFO!F51+COUNTRY_INFO!G51,0)","v":129276},361972.8,null,361972.8,724]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A52=0,\" \",COUNTRY_INFO!A52),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B52=0,\" \",COUNTRY_INFO!B52),\" \")","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C52=0,\" \",COUNTRY_INFO!C52),\" \")","v":"Insiza"},{"$f":"IF(COUNTRY_INFO!T52<>\"\",COUNTRY_INFO!P52,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T52<>\"\",COUNTRY_INFO!$H52=1),COUNTRY_INFO!F52+COUNTRY_INFO!G52,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A53=0,\" \",COUNTRY_INFO!A53),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B53=0,\" \",COUNTRY_INFO!B53),\" \")","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C53=0,\" \",COUNTRY_INFO!C53),\" \")","v":"Mangwe"},{"$f":"IF(COUNTRY_INFO!T53<>\"\",COUNTRY_INFO!P53,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T53<>\"\",COUNTRY_INFO!$H53=1),COUNTRY_INFO!F53+COUNTRY_INFO!G53,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A54=0,\" \",COUNTRY_INFO!A54),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B54=0,\" \",COUNTRY_INFO!B54),\" \")","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C54=0,\" \",COUNTRY_INFO!C54),\" \")","v":"Matobo"},{"$f":"IF(COUNTRY_INFO!T54<>\"\",COUNTRY_INFO!P54,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T54<>\"\",COUNTRY_INFO!$H54=1),COUNTRY_INFO!F54+COUNTRY_INFO!G54,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A55=0,\" \",COUNTRY_INFO!A55),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B55=0,\" \",COUNTRY_INFO!B55),\" \")","v":"Matabeleland South"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C55=0,\" \",COUNTRY_INFO!C55),\" \")","v":"Umzingwane"},{"$f":"IF(COUNTRY_INFO!T55<>\"\",COUNTRY_INFO!P55,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T55<>\"\",COUNTRY_INFO!$H55=1),COUNTRY_INFO!F55+COUNTRY_INFO!G55,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A56=0,\" \",COUNTRY_INFO!A56),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B56=0,\" \",COUNTRY_INFO!B56),\" \")","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C56=0,\" \",COUNTRY_INFO!C56),\" \")","v":"Chirumhanzi"},{"$f":"IF(COUNTRY_INFO!T56<>\"\",COUNTRY_INFO!P56,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T56<>\"\",COUNTRY_INFO!$H56=1),COUNTRY_INFO!F56+COUNTRY_INFO!G56,0)","v":76375},213850,null,213850,428]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A57=0,\" \",COUNTRY_INFO!A57),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B57=0,\" \",COUNTRY_INFO!B57),\" \")","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C57=0,\" \",COUNTRY_INFO!C57),\" \")","v":"Gokwe North"},{"$f":"IF(COUNTRY_INFO!T57<>\"\",COUNTRY_INFO!P57,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T57<>\"\",COUNTRY_INFO!$H57=1),COUNTRY_INFO!F57+COUNTRY_INFO!G57,0)","v":228459},639685.19999999995,null,639685.19999999995,1280]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A58=0,\" \",COUNTRY_INFO!A58),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B58=0,\" \",COUNTRY_INFO!B58),\" \")","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C58=0,\" \",COUNTRY_INFO!C58),\" \")","v":"Gokwe South"},{"$f":"IF(COUNTRY_INFO!T58<>\"\",COUNTRY_INFO!P58,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T58<>\"\",COUNTRY_INFO!$H58=1),COUNTRY_INFO!F58+COUNTRY_INFO!G58,0)","v":313705},878374,null,878374,1757]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A59=0,\" \",COUNTRY_INFO!A59),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B59=0,\" \",COUNTRY_INFO!B59),\" \")","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C59=0,\" \",COUNTRY_INFO!C59),\" \")","v":"Gweru"},{"$f":"IF(COUNTRY_INFO!T59<>\"\",COUNTRY_INFO!P59,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T59<>\"\",COUNTRY_INFO!$H59=1),COUNTRY_INFO!F59+COUNTRY_INFO!G59,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A60=0,\" \",COUNTRY_INFO!A60),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B60=0,\" \",COUNTRY_INFO!B60),\" \")","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C60=0,\" \",COUNTRY_INFO!C60),\" \")","v":"Kwekwe"},{"$f":"IF(COUNTRY_INFO!T60<>\"\",COUNTRY_INFO!P60,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T60<>\"\",COUNTRY_INFO!$H60=1),COUNTRY_INFO!F60+COUNTRY_INFO!G60,0)","v":296140},829192,null,829192,1659]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A61=0,\" \",COUNTRY_INFO!A61),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B61=0,\" \",COUNTRY_INFO!B61),\" \")","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C61=0,\" \",COUNTRY_INFO!C61),\" \")","v":"Mberengwa"},{"$f":"IF(COUNTRY_INFO!T61<>\"\",COUNTRY_INFO!P61,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T61<>\"\",COUNTRY_INFO!$H61=1),COUNTRY_INFO!F61+COUNTRY_INFO!G61,0)","v":176565},494381.99999999994,null,494381.99999999994,989]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A62=0,\" \",COUNTRY_INFO!A62),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B62=0,\" \",COUNTRY_INFO!B62),\" \")","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C62=0,\" \",COUNTRY_INFO!C62),\" \")","v":"Shurugwi"},{"$f":"IF(COUNTRY_INFO!T62<>\"\",COUNTRY_INFO!P62,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T62<>\"\",COUNTRY_INFO!$H62=1),COUNTRY_INFO!F62+COUNTRY_INFO!G62,0)","v":94552},264745.59999999998,null,264745.59999999998,530]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A63=0,\" \",COUNTRY_INFO!A63),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B63=0,\" \",COUNTRY_INFO!B63),\" \")","v":"Midlands"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C63=0,\" \",COUNTRY_INFO!C63),\" \")","v":"Zvishavane"},{"$f":"IF(COUNTRY_INFO!T63<>\"\",COUNTRY_INFO!P63,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T63<>\"\",COUNTRY_INFO!$H63=1),COUNTRY_INFO!F63+COUNTRY_INFO!G63,0)","v":111916},313364.8,null,313364.8,627]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A64=0,\" \",COUNTRY_INFO!A64),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B64=0,\" \",COUNTRY_INFO!B64),\" \")","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C64=0,\" \",COUNTRY_INFO!C64),\" \")","v":"Bikita"},{"$f":"IF(COUNTRY_INFO!T64<>\"\",COUNTRY_INFO!P64,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T64<>\"\",COUNTRY_INFO!$H64=1),COUNTRY_INFO!F64+COUNTRY_INFO!G64,0)","v":154322},432101.6,null,432101.6,865]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A65=0,\" \",COUNTRY_INFO!A65),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B65=0,\" \",COUNTRY_INFO!B65),\" \")","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C65=0,\" \",COUNTRY_INFO!C65),\" \")","v":"Chiredzi"},{"$f":"IF(COUNTRY_INFO!T65<>\"\",COUNTRY_INFO!P65,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T65<>\"\",COUNTRY_INFO!$H65=1),COUNTRY_INFO!F65+COUNTRY_INFO!G65,0)","v":291055},814954,null,814954,1630]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A66=0,\" \",COUNTRY_INFO!A66),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B66=0,\" \",COUNTRY_INFO!B66),\" \")","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C66=0,\" \",COUNTRY_INFO!C66),\" \")","v":"Chivi"},{"$f":"IF(COUNTRY_INFO!T66<>\"\",COUNTRY_INFO!P66,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T66<>\"\",COUNTRY_INFO!$H66=1),COUNTRY_INFO!F66+COUNTRY_INFO!G66,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A67=0,\" \",COUNTRY_INFO!A67),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B67=0,\" \",COUNTRY_INFO!B67),\" \")","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C67=0,\" \",COUNTRY_INFO!C67),\" \")","v":"Gutu"},{"$f":"IF(COUNTRY_INFO!T67<>\"\",COUNTRY_INFO!P67,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T67<>\"\",COUNTRY_INFO!$H67=1),COUNTRY_INFO!F67+COUNTRY_INFO!G67,0)","v":193034},540495.19999999995,null,540495.19999999995,1081]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A68=0,\" \",COUNTRY_INFO!A68),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B68=0,\" \",COUNTRY_INFO!B68),\" \")","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C68=0,\" \",COUNTRY_INFO!C68),\" \")","v":"Masvingo"},{"$f":"IF(COUNTRY_INFO!T68<>\"\",COUNTRY_INFO!P68,0)","v":0},{"$f":"IF(AND(COUNTRY_INFO!T68<>\"\",COUNTRY_INFO!$H68=1),COUNTRY_INFO!F68+COUNTRY_INFO!G68,0)","v":0},0,null,0,0]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A69=0,\" \",COUNTRY_INFO!A69),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B69=0,\" \",COUNTRY_INFO!B69),\" \")","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C69=0,\" \",COUNTRY_INFO!C69),\" \")","v":"Mwenezi"},{"$f":"IF(COUNTRY_INFO!T69<>\"\",COUNTRY_INFO!P69,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T69<>\"\",COUNTRY_INFO!$H69=1),COUNTRY_INFO!F69+COUNTRY_INFO!G69,0)","v":158730},444444,null,444444,889]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A70=0,\" \",COUNTRY_INFO!A70),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B70=0,\" \",COUNTRY_INFO!B70),\" \")","v":"Masvingo"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C70=0,\" \",COUNTRY_INFO!C70),\" \")","v":"Zaka"},{"$f":"IF(COUNTRY_INFO!T70<>\"\",COUNTRY_INFO!P70,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T70<>\"\",COUNTRY_INFO!$H70=1),COUNTRY_INFO!F70+COUNTRY_INFO!G70,0)","v":172330},482523.99999999994,null,482523.99999999994,966]
[{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!A71=0,\" \",COUNTRY_INFO!A71),\" \")","v":"Zimbabwe"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!B71=0,\" \",COUNTRY_INFO!B71),\" \")","v":"Bulawayo"},{"$f":"IF(AND(INTRO!$E$37=\"Endemic\",INTRO!$E$39=\"Non-endemic\"),IF(COUNTRY_INFO!C71=0,\" \",COUNTRY_INFO!C71),\" \")","v":"Bulawayo"},{"$f":"IF(COUNTRY_INFO!T71<>\"\",COUNTRY_INFO!P71,0)","v":1},{"$f":"IF(AND(COUNTRY_INFO!T71<>\"\",COUNTRY_INFO!$H71=1),COUNTRY_INFO!F71+COUNTRY_INFO!G71,0)","v":621009},1738825.2,null,1738825.2,3478]

{"sheet":"SUMMARY","index":7,"n_rows":93,"n_cols":8,"rows_kept":93,"cut":false,"hidden":false,"merged":[[97,1,97,7],[76,4,76,5],[75,2,75,3],[73,4,73,5],[74,4,74,5],[75,4,75,5],[73,2,73,3],[74,2,74,3],[92,1,92,7],[77,4,77,5],[87,1,87,7],[91,1,91,7],[86,1,86,7],[84,1,84,2],[84,3,84,7],[83,1,83,2],[77,2,77,3],[63,4,63,6],[64,4,64,6],[65,4,65,6],[66,4,66,6],[76,2,76,3],[0,1,0,7],[1,1,1,7],[2,1,2,5],[3,1,3,7],[4,1,4,7],[6,1,6,7],[5,2,5,5],[68,1,68,7],[57,1,57,7],[56,1,56,7],[25,1,25,7],[21,2,24,5],[30,2,30,3],[30,4,30,5],[30,6,30,7],[42,5,42,6],[43,5,43,6],[44,5,44,6],[58,1,58,7],[45,5,45,6],[40,5,40,6],[41,5,41,6],[9,1,10,1],[9,2,9,5],[9,6,9,7],[49,5,49,6],[82,2,82,7],[83,3,83,7],[50,5,50,6],[46,5,46,6],[47,5,47,6],[48,5,48,6],[62,4,62,6],[53,1,53,7],[59,1,59,7],[54,1,54,7],[55,1,55,7],[81,1,81,7],[61,1,61,7],[79,1,79,7],[80,1,80,7],[69,1,69,7]]}
[]
[null,"Joint request for selected PC medicines v.3.1"]
[]
[null,"This form constitutes an official government request to WHO for the supply of the PC medicines. It can be submitted any time before 15 August of the current year for distribution of medicines during the following year, but at least 6-8 months before the planned PC intervention(s) to allow time for reviewing and approval of the request, placing order, manufacturing PC medicines and shipment to the country."]
[]
[null,"Country",{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33,\" \")","v":"Zimbabwe"},null,null,null,"Year",{"$f":"IF(INTRO!$E$35<>0,INTRO!$E$35,\" \")","v":2020}]
[]
[null,"Information on PC medicines requested to WHO"]
[]
[null,"PC medicine","Number of tablets",null,null,null,"Total number of bottles"]
[null,null,"Required","In stock","In pipeline","Requested","Required","Requested"]
[null,"Diethylcarbamazine citrate",19673330,16587000,null,{"$f":"IF(C12>(D12+E12),C12-D12-E12, 0)","v":3086330},{"$f":"IF($C12=0,0, IF($B12=\"Albendazole for LF\", IF($C12=ALB_MBD!$I$4,ALB_MBD!$U$4,ROUNDUP($C12/200,0)), IF($B12=\"Albendazole for STH (SAC)\", IF($C12=ALB_MBD!$L$4,ALB_MBD!$X$4,ROUNDUP($C12/200,0)), IF($B12=\"Mebendazole (SAC)\", IF($C12=ALB_MBD!$P$4,ALB_MBD!$AA$4,ROUNDUP($C12/150,0)), IF($B12=\"Diethylcarbamazine citrate\", IF($C12=DEC!$J$4,DEC!$M$4,ROUNDUP($C12/1000,0)), IF($B12=\"Praziquantel (SAC)\", IF($C12=PZQ!$O$4,PZQ!$R$4,ROUNDUP($C12/1000,0)), IF($B12=\"Ivermectin\", IF($C12=IVM!$N$4,IVM!$Q$4,$C12/500+0.49),0)))))))","v":19694},{"$f":"IF($F12=0,0,IF(OR($B12=\"Albendazole for LF\",$B12=\"Albendazole for STH (SAC)\"),$G12-ROUNDUP(($E12+$D12)/200,0),IF($B12=\"Ivermectin\",$G12-ROUNDUP(($E12+$D12)/500,0),IF($B12=\"Mebendazole (SAC)\",$G12-ROUNDUP(($E12+$D12)/150,0),$G12-ROUNDUP(($E12+$D12)/1000,0)))))","v":3107}]
[null,"Albendazole for LF",7869332,3431500,null,4437832,{"$f":"IF($C13=0,0, IF($B13=\"Albendazole for LF\", IF($C13=ALB_MBD!$I$4,ALB_MBD!$U$4,ROUNDUP($C13/200,0)), IF($B13=\"Albendazole for STH (SAC)\", IF($C13=ALB_MBD!$L$4,ALB_MBD!$X$4,ROUNDUP($C13/200,0)), IF($B13=\"Mebendazole (SAC)\", IF($C13=ALB_MBD!$P$4,ALB_MBD!$AA$4,ROUNDUP($C13/150,0)), IF($B13=\"Diethylcarbamazine citrate\", IF($C13=DEC!$J$4,DEC!$M$4,ROUNDUP($C13/1000,0)), IF($B13=\"Praziquantel (SAC)\", IF($C13=PZQ!$O$4,PZQ!$R$4,ROUNDUP($C13/1000,0)), IF($B13=\"Ivermectin\", IF($C13=IVM!$N$4,IVM!$Q$4,$C13/500+0.49),0)))))))","v":39368},22210]
[null,"Albendazole for STH (SAC)",0,0,null,0,{"$f":"IF($C14=0,0, IF($B14=\"Albendazole for LF\", IF($C14=ALB_MBD!$I$4,ALB_MBD!$U$4,ROUNDUP($C14/200,0)), IF($B14=\"Albendazole for STH (SAC)\", IF($C14=ALB_MBD!$L$4,ALB_MBD!$X$4,ROUNDUP($C14/200,0)), IF($B14=\"Mebendazole (SAC)\", IF($C14=ALB_MBD!$P$4,ALB_MBD!$AA$4,ROUNDUP($C14/150,0)), IF($B14=\"Diethylcarbamazine citrate\", IF($C14=DEC!$J$4,DEC!$M$4,ROUNDUP($C14/1000,0)), IF($B14=\"Praziquantel (SAC)\", IF($C14=PZQ!$O$4,PZQ!$R$4,ROUNDUP($C14/1000,0)), IF($B14=\"Ivermectin\", IF($C14=IVM!$N$4,IVM!$Q$4,$C14/500+0.49),0)))))))","v":0},0]
[null,"Praziquantel (SAC)",6576892.5,0,null,6576892.5,{"$f":"IF($C15=0,0, IF($B15=\"Albendazole for LF\", IF($C15=ALB_MBD!$I$4,ALB_MBD!$U$4,ROUNDUP($C15/200,0)), IF($B15=\"Albendazole for STH (SAC)\", IF($C15=ALB_MBD!$L$4,ALB_MBD!$X$4,ROUNDUP($C15/200,0)), IF($B15=\"Mebendazole (SAC)\", IF($C15=ALB_MBD!$P$4,ALB_MBD!$AA$4,ROUNDUP($C15/150,0)), IF($B15=\"Diethylcarbamazine citrate\", IF($C15=DEC!$J$4,DEC!$M$4,ROUNDUP($C15/1000,0)), IF($B15=\"Praziquantel (SAC)\", IF($C15=PZQ!$O$4,PZQ!$R$4,ROUNDUP($C15/1000,0)), IF($B15=\"Ivermectin\", IF($C15=IVM!$N$4,IVM!$Q$4,$C15/500+0.49),0)))))))","v":6599},6599]
[null,"Ivermectin",19560909.199999999,0,null,19560909.199999999,{"$f":"IF($C16=0,0, IF($B16=\"Albendazole for LF\", IF($C16=ALB_MBD!$I$4,ALB_MBD!$U$4,ROUNDUP($C16/200,0)), IF($B16=\"Albendazole for STH (SAC)\", IF($C16=ALB_MBD!$L$4,ALB_MBD!$X$4,ROUNDUP($C16/200,0)), IF($B16=\"Mebendazole (SAC)\", IF($C16=ALB_MBD!$P$4,ALB_MBD!$AA$4,ROUNDUP($C16/150,0)), IF($B16=\"Diethylcarbamazine citrate\", IF($C16=DEC!$J$4,DEC!$M$4,ROUNDUP($C16/1000,0)), IF($B16=\"Praziquantel (SAC)\", IF($C16=PZQ!$O$4,PZQ!$R$4,ROUNDUP($C16/1000,0)), IF($B16=\"Ivermectin\", IF($C16=IVM!$N$4,IVM!$Q$4,$C16/500+0.49),0)))))))","v":39122.308399999994},39122.308399999994]
[null,null,0,0,null,0,{"$f":"IF($C17=0,0, IF($B17=\"Albendazole for LF\", IF($C17=ALB_MBD!$I$4,ALB_MBD!$U$4,ROUNDUP($C17/200,0)), IF($B17=\"Albendazole for STH (SAC)\", IF($C17=ALB_MBD!$L$4,ALB_MBD!$X$4,ROUNDUP($C17/200,0)), IF($B17=\"Mebendazole (SAC)\", IF($C17=ALB_MBD!$P$4,ALB_MBD!$AA$4,ROUNDUP($C17/150,0)), IF($B17=\"Diethylcarbamazine citrate\", IF($C17=DEC!$J$4,DEC!$M$4,ROUNDUP($C17/1000,0)), IF($B17=\"Praziquantel (SAC)\", IF($C17=PZQ!$O$4,PZQ!$R$4,ROUNDUP($C17/1000,0)), IF($B17=\"Ivermectin\", IF($C17=IVM!$N$4,IVM!$Q$4,$C17/500+0.49),0)))))))","v":0},0]
[]
[null,"Number of people to be treated with donated medicine ( see User Guide for details )"]
[]
[null,"Disease",null,null,null,null,"Round 1","Round 2"]
[null,"Lymphatic filariasis","These figures are estimated only for targeted \nage groups to be treated with donated \nmedicines in areas where treatment for specific disease is required",null,null,null,7869332," "]
[null,"Soil-transmitted helminthiases",null,null,null,null,3372570,0]
[null,"Schistosomiasis",null,null,null,null,2630757," "]
[null,null,null,null,null,null," "," "]
[]
[]
[]
[null,"Information on planned PC interventions"]
[]
[null,"PC medicine","Planned date of the \n1st round of PC",null,"Planned date of the \n2nd round of PC",null,"Date by which the medicine \nshould arrive to the national warehouse"]
[null,"Diethylcarbamazine citrate"]
[null,"Albendazole for LF"]
[null,"Albendazole for STH","October",null,null,null,"January",2020]
[null,"Praziquantel","October"]
[null,"Ivermectin"]
[]
[]
[null,"Information on PC medicines for treatment of population not targeted with current donation through WHO"]
[]
[null,"PC medicine","Age group","# of people","# of tablets","Specify source",null,"Status"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"Checklist"]
[null,"Submission"]
[null,"What should be submitted?"]
[null,"The supply of the requested medicines should be based on up-to-date epidemiological data, specific usage plans, and capacity for implementation. The following checklist ensures that all necessary forms and information are provided to WHO (in electronic format). "]
[null,"Joint request for selected PC medicines"]
[null,"Joint reporting form"]
[null,"PC epidemiological data reporting form"]
[]
[null,"Availability of funding for implementation in the year for which the medicines are requested"]
[]
[null,"Diseases \ntargeted for implementation","Total treatments","Funding secured for","Source",null,null,"Amount"]
[null,{"$f":"B22","v":"Lymphatic filariasis"},{"$f":"SUM(G22:H22)","v":7869332},null,"WHO/HIGHERLIFE FOUNDATION "]
[null,{"$f":"B23","v":"Soil-transmitted helminthiases"},{"$f":"SUM(G23:H23)","v":3372570},"YES","WHO/HIGHERLIFE FOUNDATION "]
[null,{"$f":"B24","v":"Schistosomiasis"},{"$f":"SUM(G24:H24)","v":2630757},"YES","WHO/HIGHERLIFE FOUNDATION "]
[null,{"$f":"B25","v":0},{"$f":"SUM(G25:H25)","v":0}]
[]
[null,"Who should fill in the form? "]
[null,"National NTD coordinator should compile all required information needed to complete the request form. In the absence of such a coordinator, specific programme managers should coordinate their respective part. The final single request must be approved by the Ministry of Health."]
[]
[null,"Information on person(s) who has filled in the form"]
[]
[null,"Title ","Name",null,"Phone",null,"Email","Date"]
[null,"NTD/PC Coordinator","DR I Phiri",null,263772810580,null,"drisaacphiri@yahoo.com","2020-07-16"]
[]
[]
[]
[]
[null,"The WHO recommends that all serious adverse events suspected to be associated with use of PC medicines should be reported in accordance with national Pharmacovigilance guidelines. In the absence of a national Pharmacovigilance system, contact the WHO Neglected Tropical Disease department for guidance."]
[null,"The WHO is committed to facilitate PC medicines donation with a free-of-charge supply of a) albendazole, mebendazole and praziquantel to the MoH’s national warehouse; and b) diethylcarbamazine citrate to the entry port/airport of recipient countries."]
[null,"The institution submitting the present request is responsible for a) arranging the offloading of the medicines from the truck and storing it in the national warehouse and subsequent shipment to the final distribution centres; b) for registering the donated medicine, if required, by the relevant national regulatory authorities; and c) for informing about any changes of their PC campaigns (e.g. postpone of the planned MDA date, replacement of NTD coordinator, etc.)."]
[null,null,"I have read and accept WHO Data Sharing Policy"]
[null,"Name and signature of NTD coordinator \nor Ministry of Health representative",null,"Dr I Phiri"]
[null,"Date:",null,"2020-07-16"]
[]
[null,"Please complete information on shipment and consignee in the worksheet SHIPMENT. Any additional details related to this Request should be provided in the \"Additional information\" box in the worksheet SHIPMENT."]
[null,"Please send the national request (signed and in electronic format) to the concerned WR with copy to:"]
[null,"WHO headquarters","PC_JointForms@who.int"]
[null,"WHO Regional Office","Regional Advisor for NTD"]
[null,"Mectizan donation program","Dr Yao Sodahlon, email: ysodahlon@taskforce.org"]
[]
[null,"Please note that your request will be reviewed by an independent panel before approval. The information in this form, joint reporting form and PC epidemiological data reporting form are essential for WHO to ensure efficient usage of medicines. As part of its ongoing monitoring and evaluation activities, and to meet its contractual obligations to donors and other partners, WHO and its appointed agents reserve the right to periodically inspect stocks of the medicines at country level."]

{"sheet":"SHIPMENT","index":8,"n_rows":46,"n_cols":8,"rows_kept":46,"cut":false,"hidden":false,"merged":[[32,2,32,4],[32,5,32,7],[29,2,29,4],[29,5,29,7],[30,2,30,4],[30,5,30,7],[31,2,31,4],[31,5,31,7],[26,2,26,4],[26,5,26,7],[27,2,27,4],[27,5,27,7],[28,2,28,4],[28,5,28,7],[23,2,23,4],[23,5,23,7],[21,5,21,7],[16,5,16,7],[17,2,17,4],[12,2,12,4],[12,5,12,7],[13,2,13,4],[13,5,13,7],[14,2,14,4],[14,5,14,7],[9,2,9,4],[9,5,9,7],[10,2,10,4],[10,5,10,7],[11,2,11,4],[11,5,11,7],[6,1,6,7],[7,2,7,4],[7,5,7,7],[8,2,8,4],[8,5,8,7],[15,5,15,7],[20,2,20,4],[18,2,18,4],[16,2,16,4],[47,1,56,7],[45,1,45,7],[37,1,37,6],[38,1,38,5],[40,1,40,7],[41,1,41,6],[39,1,39,6],[42,1,42,6],[43,1,43,7],[25,2,25,4],[25,5,25,7],[24,1,24,7],[34,1,34,7],[36,1,36,7],[0,1,0,7],[1,1,1,7],[2,1,2,5],[17,5,17,7],[18,5,18,7],[19,2,19,4],[19,5,19,7],[21,2,21,4],[3,2,3,5],[4,1,4,7],[22,2,22,4],[22,5,22,7],[15,2,15,4],[20,5,20,7]]}
[]
[null,"Joint request for selected PC medicines v.3.1"]
[]
[null,"Country",{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33,\" \")","v":"Zimbabwe"},null,null,null,"Year",{"$f":"IF(INTRO!$E$35<>0,INTRO!$E$35,\" \")","v":2020}]
[]
[null,"Information on shipment and consignee "]
[]
[null,null,"Consignee",null,null,"Delivery point / Final recipient\nif different from the consignee"]
[null,"Name","Gasasira, Dr Alex Ntale",null,null,"Dr ISAAC PHIRI"]
[null,"Department/Unit","The WHO Representative",null,null,"EPIDEMIOLOGY AND DISEASE CONTROL"]
[null,"Organization","WHO",null,null,"MINISTRY OF HEALTH, ZIMBABWE"]
[null,"Phone","+263772155629-32",null,null,"+263772810580"]
[null,"Fax"]
[null,"E-mail","afzwinfo@who.int",null,null,"drisaacphiri@yahoo.com"]
[null,"Mailing address","P.O. BOX CY 348, CAUSEWAY, HARARE",null,null,"P.O. BOX CY 1122, CAUSEWAY, HARARE, ZIMBABWE"]
[]
[null,null,"Consignee",null,null,"Delivery point / Final recipient\nif different from the consignee"]
[null,"Name"]
[null,"Department/Unit"]
[null,"Organization",null,null,null,"NatPharm "]
[null,"Phone"]
[null,"Fax"]
[null,"E-mail"]
[null,"Mailing address"]
[]
[null,null,"Consignee",null,null,"Delivery point / Final recipient\nif different from the consignee"]
[null,"Name"]
[null,"Department/Unit"]
[null,"Organization"]
[null,"Phone"]
[null,"Fax"]
[null,"E-mail"]
[null,"Mailing address"]
[]
[]
[null,"Information on import requirements"]
[]
[null,"Is the Import Permit required?"]
[null,"How long does it take to obtain the Import Permit?"]
[null,"Do you require any documents to be submitted together with the Import Permit application?"]
[null,"If YES, please specify here"]
[null,"Does the consignee have to get customs clearance before the shipment can proceed?"]
[null,"Is there any additional information may be helpful in ensuring timely clearance and delivery of medicines to your country? "]
[null,"If YES, please specify here"]
[]
[null,"Additional information"]

{"sheet":"DATA_POLICY","index":9,"n_rows":39,"n_cols":8,"rows_kept":39,"cut":false,"hidden":true,"merged":[[55,1,55,2],[0,1,0,5],[1,1,1,7],[3,3,3,5],[6,1,6,7],[8,1,12,7],[13,1,16,7],[17,1,21,7],[22,1,25,7],[26,2,36,7],[38,1,45,7]]}
[]
[null,"Joint request for selected PC medicines v.3.1"]
[]
[null,"Country",null,{"$f":"IF(INTRO!$E$33<>0,INTRO!$E$33,\" \")","v":"Zimbabwe"},null,null,"Year",{"$f":"IF(INTRO!$E$35<>0,INTRO!$E$35,\" \")","v":2020}]
[]
[]
[null,"WHO Data Sharing Policy statement"]
[]
[null,"Data are the basis for all sound public health actions and the benefits of data sharing are widely recognized, including scientific and public health benefits. Whenever possible, WHO wishes to promote the sharing of health data, including but not restricted to surveillance and epidemiological data.  "]
[]
[]
[]
[]
[null,{"$f":"\"In this connection, and without prejudice to information sharing and publication pursuant to legally binding instruments, by providing data to WHO, the Ministry of Health of \" & D4 & \":\"","v":"In this connection, and without prejudice to information sharing and publication pursuant to legally binding instruments, by providing data to WHO, the Ministry of Health of Zimbabwe:"}]
[]
[]
[]
[null,"Confirms that all data to be supplied to WHO hereunder have been collected in accordance with applicable national laws, including data protection laws aimed at protecting the confidentiality of identifiable persons;"]
[]
[]
[]
[]
[null,{"$f":"\"Agrees that WHO shall be entitled, subject always to measures to ensure the ethical and secure use of the data, and subject always to an appropriate acknowledgement of \"&D4&\":\"","v":"Agrees that WHO shall be entitled, subject always to measures to ensure the ethical and secure use of the data, and subject always to an appropriate acknowledgement of Zimbabwe:"}]
[]
[]
[]
[null,null,"to publish the data, stripped of any personal identifiers and make the Data available to any interested party on request (to the extent they have not, or not yet, been published by WHO) on terms that allow non-commercial, not-for-profit use of the Data for public health purposes (provided always that publication of the Data shall remain under the control of WHO); \nto use, compile, aggregate, evaluate and analyse the Data and publish and disseminate the results thereof in conjunction with WHO’s work and in accordance with the Organization’s policies and practices."]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,{"$f":"CONCATENATE(\"Except where data sharing and publication is required under legally binding instruments (IHR, WHO Nomenclature Regulations 1967, etc.), the Ministry of Health of \", D4,\" may in respect of certain data opt out of (any part of) the above,\" & \" by notifying WHO thereof in writing at the following address, provided that any such notification shall clearly identify the data in question and clearly indicate the scope of the opt-out (in reference to the  above), \" & \"and provided that specific reasons shall be given for the opt out.\")","v":"Except where data sharing and publication is required under legally binding instruments (IHR, WHO Nomenclature Regulations 1967, etc.), the Ministry of Health of Zimbabwe may in respect of certain data opt out of (any part of) the above, by notifying WHO thereof in writing at the following address, provided that any such notification shall clearly identify the data in question and clearly indicate the scope of the opt-out (in reference to the  above), and provided that specific reasons shall be given for the opt out."}]